{"text_format":"1","workbook":"xlsx","n_sheets":8,"sheets":["Instructions","CMFs","Input","Input Summary","Output","Intersection Tables","Calibration Factors","Construction - do not delete"],"not_rendered":{"charts":0,"images":0,"macros":1,"external_links":0,"defined_names":42,"comments":2,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Instructions","index":0,"n_rows":39,"n_cols":14,"rows_kept":39,"cut":false,"hidden":false,"merged":[[1,1,1,19],[2,1,2,19],[11,13,12,17],[14,13,15,17],[33,4,36,9],[6,11,7,19],[17,13,18,17],[17,4,18,9],[20,4,22,9],[24,4,26,9],[6,1,8,9],[10,1,10,9],[20,13,20,17],[28,4,28,9],[30,4,30,9]]}
[]
[null,"MassDOT Safety Alternatives Analysis Guide Spreadsheet Tool"]
[null,"Method 3 - Observed Crash Frequency"]
[]
[null,"Overview",null,null,null,null,null,null,null,null,null,"Color Coding Rules"]
[]
[null,"This Excel file has been developed to assist analyis in conducting Safety Alternative Analysis. The SPFs were developed as a part of the project entitled \"Calibration of Safety Performance Functions and Crash Modification Factors for Massachusetts’ Urban Intersections\". ",null,null,null,null,null,null,null,null,null,"The worksheets include three color options to help users identify locations where input data is required."]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,"Color Used",null,"Type of Information Required from User"]
[null,"Macros must be enable to use this spreadsheet"]
[null,null,null,null,null,null,null,null,null,null,null,"Sample",null,"Required input information as identified in the HSM. To be keyed in manually."]
[null,null,null,null,null,null,null,null,null,null,null,"Text"]
[null,"The contents of this Excel file include the following:"]
[null,null,null,null,null,null,null,null,null,null,null,"Sample",null,"Input data required from the user but restricted to options provided in the pull-down menu."]
[null,"Worksheet Name",null,null,"Contents",null,null,null,null,null,null,"Text"]
[]
[null,"Instructions",null,null,"The worksheet you are seeing now provides an overview of the Excel file, summary of the worksheets and the color coding rules.",null,null,null,null,null,null,"Sample",null,"Optional input information that can be used to supplement the analysis if this information is available.  "]
[null,null,null,null,null,null,null,null,null,null,null,"Text"]
[]
[null,"CMFs",null,null,"Provides the State-Preferred CMF List. In cases where a CMF for a treatment is not provided in this list, the analyst should work with MassDOT to identify an appropriate value for analysis."]
[]
[]
[]
[null,"Input",null,null,"Contains input required to perform the analysis. For detailed explanation on input fields, please refer to the MassDOT Safety Analysis Guide. At end of sheet, the Run Report macro must be run to obtain results in the Output worksheet."]
[]
[]
[]
[null,"Output",null,null,"Summarizes the results of the analysis."]
[]
[null,"Year #, Design Year",null,null,"Internal SPF worksheets.",null,null,null,null,null,null,"Acknowledgement"]
[]
[null,null,null,null,null,null,null,null,null,null,null,"University of Massachusetts Lowell (SPF development)."]
[null,null,null,null,"Please do NOT change any of the hidden worksheets. ",null,null,null,null,null,null,"VHB, Inc."]
[]
[]
[]
[]
["Last Updated: September 2024"]

{"sheet":"CMFs","index":1,"n_rows":169,"n_cols":12,"rows_kept":169,"cut":false,"hidden":false,"merged":[[108,0,117,0],[118,0,127,0],[128,0,129,0],[130,0,149,0],[150,0,168,0],[91,0,107,0],[1,0,20,0],[21,0,30,0],[31,0,50,0],[51,0,70,0],[71,0,90,0]]}
["Facility","Countermeasure","Crash Type","All Severity CMF","FI CMF","Area Type","Prior Condition","Site Description","Notes","Resource 1 ","Resource 2","Resource 3"]
["Pedestrian and Bicycle","Add Separated Bike Lane","Vehicle-Bicycle",0.26,0.26,"Urban","No Bicycle Infrastructure","Urban Street","Assumed KABC CMF applies to all because all Bike crashes are assumed to be KABC","http://www.cmfclearinghouse.org/detail.cfm?facid=4097"]
[null,"Add Separation between Road and Bike Lane","Vehicle-Bicycle",0.63,0.63,"Urban","Bike Lane with No Buffer","Urban Street",null,"Cross-Sectional Comparison of Cycle Track and Bike Lane CMF"]
[null,"Add Shared Use Path","Vehicle-Bicycle",0.75,0.75,"Urban","No Shared Use Path Present","Principal Arterial Other, Minor arterial, major and minor collectors",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=9250"]
[null,"Add Sidewalk - Urban","Vehicle-Pedestrian",0.12,0.12,"Urban/Suburban","No Sidewalk Present",null,null,"https://www.pedbikeinfo.org/cms/downloads/WalkingAlongRoadways_Study_Guidelines.pdf"]
[null,"Add Wide Paved Shoulder for Pedestrian Walkway","Vehicle-Pedestrian",0.28999999999999998,0.28999999999999998,"Rural","Narrow, Unwalkable Shoulder","Rural Highway with Pedestrian Traffic",null,"https://safety.fhwa.dot.gov/speedmgt/ref_mats/fhwasa1304/resources/CRF%20Desktop%20Reference.pdf"]
[null,"Advanced Pedestrian Crossing Signage","Vehicle-Pedestrian",0.75,0.75,"Urban and Suburban","No Advanced Warning Signage or Markings","Mid-Block and Intersection Crossings","Minimum of 340 to Maximum of 52892 Annual Average Daily Traffic (AADT)","http://www.cmfclearinghouse.org/detail.cfm?facid=9017"]
[null,"Bike box","Vehicle-Bicycle",0.65,0.65,"Urban","No Bike Box","Signalized Intersection",null,"Herrstedt, L., M.A. Nielsen, L. Agústson, K.M.L. Krogsgaard, E. Jørgensen, and N.O. Jørgensen. Safety of Cyclists in Urban Areas: Danish Experiences. Copenhagen, Denmark: Danish Road Directorate, 1994 via Signalized Intersections Informational Guide"]
[null,"Bike lane","All",{"$f":"AVERAGE(0.7859,1.3065,0.901,0.558,0.435,0.51,0.643,0.734,0.694,0.649)","v":0.72164000000000006},0.93,"Urban","No Bike Lane","Urban Street","FI CMF only applicable for Method 3. Weighted average from http://www.cmfclearinghouse.org/study_detail.cfm?stid=618. KABC CMF is a weighted average of all KABC CMFs in the study","http://www.cmfclearinghouse.org/study_detail.cfm?stid=618"]
[null,"Convert to High-Visibility Crosswalk","Vehicle-Pedestrian",0.52,0.52,"Urban","Standard Crosswalk Markings","Three or Four Leg Intersection","Signalized and unsignalized intersections. ","https://www.sciencedirect.com/science/article/abs/pii/S0001457512001613","http://www.cmfclearinghouse.org/detail.cfm?facid=4123"]
[null,"Exclusive Pedestrian Phase","Vehicle-Pedestrian",0.49,0.49,"Urban","Signalized Intersection without Exclusive Phase","Signalized Intersection","3-leg,4-leg,More than 4 legs intersection","http://www.cmfclearinghouse.org/detail.cfm?facid=4117"]
[null,"Implement Leading Pedestrian Interval","All",0.9,0.83,"Urban and Suburban","No Leading Pedestrian Interval","Urban Signalized Intersection","FI CMF only applicable for Method 3","http://www.cmfclearinghouse.org/detail.cfm?facid=9902","http://www.cmfclearinghouse.org/detail.cfm?facid=9901"]
[null,"Increase Pedestrian Crossing Time","Vehicle-Pedestrian",0.49,0.49,"Urban","Standard Crossing Time","Signalized Intersection with Pedestrian Crossing Phase","3-leg,4-leg,More than 4 legs","http://www.cmfclearinghouse.org/detail.cfm?facid=4115"]
[null,"Install Crosswalk Lighting","Vehicle-Pedestrian",0.41,0.41,"All","No Lighting Present","Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=440","http://www.cmfclearinghouse.org/detail.cfm?facid=441"]
[null,"Install Grade-Separated Pedestrian Crossing","Vehicle-Pedestrian",0.14000000000000001,0.14000000000000001,"Urban","At-Grade Pedestrian Crossing","Pedestrian Crossing",null,"https://lctr.eng.fiu.edu/Documents/CRFFinalReport.pdf"]
[null,"Install Median Island for Pedestrian Crossing at Controlled Crossing","Vehicle-Pedestrian",0.71099999999999997,0.73399999999999999,"Urban and Suburban","Two-Way Left-Turn Lane","Signalized Pedestrian Crossing","FI CMF only applicable for Method 3. Minimum of 10500 to Maximum of 57000 Annual Average Daily Traffic (AADT)","http://www.cmfclearinghouse.org/detail.cfm?facid=5075","http://www.cmfclearinghouse.org/detail.cfm?facid=5076"]
[null,"Install Median Island for Pedestrian Crossing at Uncontrolled Crossing","Vehicle-Pedestrian",0.68500000000000005,0.68500000000000005,"Urban and Suburban","No Raised Median Present","Uncontrolled Pedestrian Crossing",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=8799"]
[null,"Install Pedestrian Countdown Timer","All",0.91200000000000003,0.95199999999999996,null,"No Pedestrian Countdown Timer","4- legged signalized Intersection with Pedestrian Crossing","FI CMF only applicable for Method 3. ","http://www.cmfclearinghouse.org/detail.cfm?facid=8791","http://www.cmfclearinghouse.org/detail.cfm?facid=8790"]
[null,"Install Pedestrian Hybrid Beacon (or HAWK Crossing)","Vehicle-Pedestrian",0.54300000000000004,0.55000000000000004,"Urban and Suburban","No PHB/HAWK","Uncontrolled Pedestrian Crossing",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=10608","http://www.cmfclearinghouse.org/detail.cfm?facid=10607"]
[null,"Install Raised Pedestrian Crossing","All",0.7,0.64,null,"Flat Pedestrian Crossing","Pedestrian Crossing","FI CMF only applicable for Method 3."," Bahar, G., Parkhill, M., Hauer, E., Council, F., Persaud, B., Zegeer, C., Elvik, R., Smiley, A., and\nScott, B. “Prepare Parts I and II of a Highway Safety Manual: Knowledge Base for Part II”.\nUnpublished material from NCHRP Project 17-27, (May 2007). ","https://safety.fhwa.dot.gov/ped_bike/tools_solve/fhwasa18041/fhwasa18041.pdf"]
[null,"Install Rectangular Rapid Flashing Beacon (RRFB)","Vehicle-Pedestrian",0.52600000000000002,0.52600000000000002,"Urban and Suburban","No RRFB Present","Uncontrolled Pedestrian Crossing",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=9024"]
["Interchanges","Add Interchange Lighting","All",0.5,0.74,"All","No Lighting Present","Interchange","Proportionally adjusted from the target crash type (nighttime) to all crashes","http://www.cmfclearinghouse.org/detail.cfm?facid=1283","http://www.cmfclearinghouse.org/detail.cfm?facid=1284"]
[null,"Add Lane to Interchange Ramp","All",2.15,1.62,"Urban and Suburban","One Lane on Ramp","Interchange Entrance or Exit Ramp","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Equation 19-20 and Table 19-5"]
[null,"Convert Diamond Interchange to a Diverging Diamond Interchange","All",0.67,0.59,"Suburban","Traditional Diamond Interchange","Diamond Interchange","Speed limit 40-45 mph","http://www.cmfclearinghouse.org/detail.cfm?facid=8278","http://www.cmfclearinghouse.org/detail.cfm?facid=8258"]
[null,"Extend Acceleration Lane from X Miles to Y Miles","All","exp(-2.59*[Y-X])","exp(-4.55*[Y-X])",null,"Acceleration Lane Length of X Miles","Freeway Interchange Area","Principal Arterial Interstate","http://www.cmfclearinghouse.org/detail.cfm?facid=5216","http://www.cmfclearinghouse.org/detail.cfm?facid=5215"]
[null,"Extend Deceleration Lane to 700 Feet","All",0.41,0.41,null,"Expressway Deceleration Lane Less than 700 feet","Expressway Approaching Exit",null,"http://www.cmfclearinghouse.org/study_detail.cfm?stid=303"]
[null,"Increase Spacing Between Entrance Ramp and Exit Ramp from X Feet to Y Feet","All","exp(450/Y-450/X)","exp(171/Y-171/X)",null,"X Feet Between Entrance and Exit Ramps","Freeway Interchange Area",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=7445","http://www.cmfclearinghouse.org/detail.cfm?facid=7444"]
[null,"Provide Auxiliary Lane in Weaving Area","All",0.79,0.77,null,"No Auxiliary Lane Between Ramps","Freeway Interchange Area",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=7441","http://www.cmfclearinghouse.org/detail.cfm?facid=7440"]
[null,"Widen Ramp Lane Width from X Feet to Y Feet","All","(3149*exp[-0.0458*(Y-X)]+10168)/13317","exp[-0.0458*(Y-X)]","All","Lane Width of X Feet","Freeway Ramp","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Equation 19-34, Table 19-25","http://onlinepubs.trb.org/onlinepubs/nchrp/docs/nchrp17-45_fr.pdf"]
[null,"Widen Ramp Left Shoulder Width from X Feet to Y Feet","All","(3149*exp[-0.0539*(Y-X)]+10168*exp[-0.0259*(Y-X)])/13317","exp[-0.0539*(Y-X)]","All","Right Shoulder Width of X Feet","Freeway Ramp","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Equation 19-35, Table 19-26","http://onlinepubs.trb.org/onlinepubs/nchrp/docs/nchrp17-45_fr.pdf"]
[null,"Widen Ramp Right Shoulder Width from X Feet to Y Feet","All","(3149*exp[-0.0539*(Y-X)]+10168*exp[-0.0259*(Y-X)])/13317","exp[-0.0539*(Y-X)]","All","Right Shoulder Width of X Feet","Freeway Ramp","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Equation 19-35, Table 19-26","http://onlinepubs.trb.org/onlinepubs/nchrp/docs/nchrp17-45_fr.pdf"]
["Intersections","Add 3-Inch Yellow Retroreflective Sheeting to Signal Backplates","All",0.85,0.85,"Urban","No Retroreflective Sheeting on Signals","Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=1410"]
[null,"Add Flashing Lights at Railroad Grade Crossing","All",0.21,0.21,null,"Static Signs","At-Grade Railroad Crossing",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=485"]
[null,"Add Intersection Lighting","All",0.98,0.97521824999999995,"All","No Lighting","Intersection","Proportionally adjusted from the target crash type (nighttime) to all crashes. 3-leg,4-leg intersection","http://www.cmfclearinghouse.org/detail.cfm?facid=4462"]
[null,"Add Low-Volume Driveway at Approach Corner of  Signalized Intersection","All",0.82,0.79,null,"No Driveway within 50 Feet of Approach Corner","Four-Leg Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=9738","http://www.cmfclearinghouse.org/detail.cfm?facid=9734"]
[null,"Add Low-Volume Driveway at Receiving Corner of  Signalized Intersection","All",1.33,1.29,null,"No Driveway within 50 Feet of Receiving Corner","Four-Leg Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=9740","http://www.cmfclearinghouse.org/detail.cfm?facid=9736"]
[null,"Change Intersection Skew Angle from X to Y at a Rural Four-Leg Stop-Control Intersection of Two Lane Highways","All","e^(0.0054*[Y-X])","e^(0.0054*[Y-X])","Rural","Intersection Skew Angle of X Degrees","Four-Leg Minor Stop-Controlled Intersection of Rural Two-Lane Highways",null,"Highway Safety Manual Equation 10-23"]
[null,"Change Intersection Skew Angle from X to Y at a Rural Four-Leg Stop-Control Intersection with a Multilane Highway","All","((0.053*Y)/(1.43+0.053*Y)+1)/((0.053*X)/(1.43+0.053*X)+1)","((0.048*Y)/(0.72+0.048*Y)+1)/((0.048*X)/(0.72+0.048*X)+1)","Rural","Intersection Skew Angle of X Degrees","Four-Leg Minor Stop-Controlled Intersection with a Multilane Highway",null,"Highway Safety Manual Equation 11-21","Highway Safety Manual Equation 11-20"]
[null,"Change Intersection Skew Angle from X to Y at a Rural Three-Leg Stop-Control Intersection of Two Lane Highways","All","e^(0.004*[Y-X])","e^(0.004*[Y-X])","Rural","Intersection Skew Angle of X Degrees","Three-Leg Minor Stop-Controlled Intersection of Rural Two-Lane Highways",null,"Highway Safety Manual Equation 10-22"]
[null,"Change Intersection Skew Angle from X to Y at a Rural Three-Leg Stop-Control Intersection with a Multilane Highway","All","((0.016*Y)/(0.98+0.016*Y)+1)/((0.016*X)/(0.98+0.016*X)+1)","((0.017*Y)/(0.52+0.017*Y)+1)/((0.017*X)/(0.52+0.017*X)+1)","Rural","Intersection Skew Angle of X Degrees","Three-Leg Minor Stop-Controlled Intersection with a Multilane Highway",null,"Highway Safety Manual Equation 11-19","Highway Safety Manual Equation 11-18"]
[null,"Change Left Turn Phasing from Permissive to Protected/Permissive on One Approach","All",1.0309999999999999,0.96199999999999997,"Urban","Permissive Left-Turn Phasing","Four Leg Signalized Intersection Approach","I use permissive/protected, but it can also be protective/permissive (no difference between lead or lag). This applies to all left-turn phasing CMFs","http://www.cmfclearinghouse.org/detail.cfm?facid=4269","http://www.cmfclearinghouse.org/detail.cfm?facid=4268"]
[null,"Change Left Turn Phasing from Permissive to Flashing Yellow Arrow on One Approach","All",0.753,0.753,"Urban","Permissive Left-Turn Phasing","Four Leg Signalized Intersection Approach",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=4174"]
[null,"Change Left Turn Phasing from Permissive to Protected on One Approach","All",0.94,0.94,"Urban and Suburban","Permissive Left-Turn Phasing","Signalized Intersection Approach",null,"Highway Safety Manual Table 12-25"]
[null,"Change Left Turn Phasing from Permissive/Protected to Flashing Yellow Arrow on All Approaches","All",0.92200000000000004,0.86,"Urban","Protective/Permissive Left-Turn Phasing","Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=9668","http://www.cmfclearinghouse.org/detail.cfm?facid=4176"]
[null,"Change Left Turn Phasing from Permissive/Protected to Protected on Major Approach","All",0.63963999999999999,0.52282000000000006,"Urban","Protective/Permissive Left-Turn Phasing","Signalized Intersection","Proportionally adjusted from the target crash type (angle and left-turn) to all crashes","http://www.cmfclearinghouse.org/detail.cfm?facid=339"]
[null,"Change Left Turn Phasing from Permissive/Protected to Protected on Minor Approach","All",0.65,0.53727999999999998,"Urban","Protective/Permissive Left-Turn Phasing","Signalized Intersection","Proportionally adjusted from the target crash type (angle and left-turn) to all crashes","http://www.cmfclearinghouse.org/detail.cfm?facid=337"]
[null,"Change Left Turn Phasing from Protected to Flashing Yellow Arrow on All Approaches","All",1.3380000000000001,1.3380000000000001,"Urban","Protected Left-Turn Phasing","Four-Leg Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=4172"]
[null,"Change the Number of Approaches with Left Turn Lanes from X to Y at a Rural Four-Leg Signalized Intersection of Two Lane Highways","All","0.82^[Y-X]","0.82^[Y-X]","Rural","Left Turn Lanes on X Approaches","Four-Leg Signalized Intersection of Two-Lane Rural Roads",null,"Highway Safety Manual Table 10-13"]
[null,"Change the Number of Approaches with Left Turn Lanes from X to Y at an Urban or Suburban Four-Leg Signalized Intersection","All","0.90^[Y-X]","0.90^[Y-X]","Urban and Suburban","Left Turn Lanes on X Approaches","Four-Leg Signalized Intersection with an Arterial",null,"Highway Safety Manual Table 12-24"]
[null,"Change the Number of Approaches with Left Turn Lanes from X to Y at an Urban or Suburban Three-Leg Signalized Intersection","All","0.93^[Y-X]","0.93^[Y-X]","Urban and Suburban","Left Turn Lanes on X Approaches","Three-Leg Signalized Intersection with an Arterial",null,"Highway Safety Manual Table 12-24"]
[null,"Change the Number of Approaches with Right Turn Lanes from X to Y at a Rural Four-Leg Signalized Intersection of Two Lane Highways","All","0.96^[Y-X]","0.96^[Y-X]","Rural","Right Turn Lanes on X Approaches","Four-Leg Signalized Intersection of Two-Lane Rural Roads",null,"Highway Safety Manual Table 10-14"]
[null,"Change the Number of Approaches with Right Turn Lanes from X to Y at an Urban or Suburban Four-Leg Signalized Intersection","All","0.96^[Y-X]","0.96^[Y-X]","Urban and Suburban","Right Turn Lanes on X Approaches","Four-Leg Signalized Intersection with an Arterial",null,"Highway Safety Manual Table 12-24"]
[null,"Change the Number of Approaches with Right Turn Lanes from X to Y at an Urban or Suburban Three-Leg Signalized Intersection","All","0.96^[Y-X]","0.96^[Y-X]","Urban and Suburban","Right Turn Lanes on X Approaches","Three-Leg Signalized Intersection with an Arterial",null,"Highway Safety Manual Table 12-24"]
[null,"Change the Number of Approaches with Right Turn on Red Prohibitied from X to Y","All","0.98^[Y-X]","0.98^[Y-X]",null,"Right Turn on Red Permitted","Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=5194"]
[null,"Change the Number of Major Approaches with Left Turn Lanes from X to Y at a Rural Four-Leg Stop-Controlled Intersection of Two Lane Highways","All","0.72^[Y-X]","0.72^[Y-X]","Rural","Left Turn Lanes on X Major Approaches","Four-Leg Minor Stop-Controlled Intersection of Two-Lane Rural Roads",null,"Highway Safety Manual Table 10-13"]
[null,"Change the Number of Major Approaches with Left Turn Lanes from X to Y at a Rural Four-Leg Stop-Controlled Intersection with a Multilane Highway","All","0.72^[Y-X]","0.65^[Y-X]","Rural","Left Turn Lanes on X Major Approaches","Four-Leg Minor Stop-Controlled Intersection with Multilane Highway",null,"Highway Safety Manual Table 11-22"]
[null,"Change the Number of Major Approaches with Left Turn Lanes from X to Y at an Urban or Suburban Four-Leg Stop-Controlled Intersection with an Arterial","All","0.73^[Y-X]","0.73^[Y-X]","Urban and Suburban","Left Turn Lanes on X Major Approaches","Four-Leg Minor Stop-Controlled Intersection with an Arterial",null,"Highway Safety Manual Table 11-22"]
[null,"Change the Number of Major Approaches with Right Turn Lanes from X to Y at a Rural Four-Leg Stop-Controlled Intersection of Two Lane Highways","All","0.86^[Y-X]","0.86^[Y-X]","Rural","Right Turn Lanes on X Major Approaches","Four-Leg Minor Stop-Controlled Intersection of Two-Lane Rural Roads",null,"Highway Safety Manual Table 10-14"]
[null,"Change the Number of Major Approaches with Right Turn Lanes from X to Y at a Rural Four-Leg Stop-Controlled Intersection with a Multilane Highway","All","0.86^[Y-X]","0.77^[Y-X]","Rural","Right Turn Lanes on X Major Approaches","Four-Leg Minor Stop-Controlled Intersection with Multilane Highway",null,"Highway Safety Manual Table 11-23"]
[null,"Change the Number of Major Approaches with Right Turn Lanes from X to Y at an Urban or Suburban Four-Leg Stop-Controlled Intersection with an Arterial","All","0.86^[Y-X]","0.86^[Y-X]","Urban and Suburban","Right Turn Lanes on X Major Approaches","Four-Leg Minor Stop-Controlled Intersection with an Arterial",null,"Highway Safety Manual Table 11-22"]
[null,"Convert a Signalized T-Intersection to a Continuous Green-T Intersection","All",0.95799999999999996,0.84599999999999997,null,"Signalized 3-Leg Intersection","3-Leg Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=8656","http://www.cmfclearinghouse.org/detail.cfm?facid=8655"]
[null,"Convert All-Way Stop-Controlled Intersection to a Modern Roundabout","All",1.1140000000000001,0.55400000000000005,"All","All-Way Stop-Controlled Intersection","3-Leg or 4-Leg Intersection","Minimum of 4100 (total entering) to Maximum of 48100 (total entering) Annual Average Daily Traffic (AADT)","http://www.cmfclearinghouse.org/detail.cfm?facid=4933","http://www.cmfclearinghouse.org/detail.cfm?facid=4932"]
[null,"Convert At-Grade Intersection to a Diverging Diamond Interchange","All",0.42,0.42,null,"At-Grade Four-Leg Signalized Intersection","At-Grade Four Leg Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=9658"]
[null,"Convert At-Grade Intersection to Interchange","All",0.57999999999999996,0.43,null,"At-Grade Four-Leg Intersection","At-Grade Four-Leg Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=459","http://www.cmfclearinghouse.org/detail.cfm?facid=460"]
[null,"Convert Four-Leg Intersection to Two Three-Leg Intersections","All",1.03,0.75,"Urban","Four-Leg Intersection","Intersection","Proportionally adjusted from FI and PDO to All. No fatal or all CMF provided in study, presume 1 or apply ABC CMF?","http://www.cmfclearinghouse.org/detail.cfm?facid=201","http://www.cmfclearinghouse.org/detail.cfm?facid=203"]
[null,"Convert from Minor Stop-Control to All-Way Stop-Control","All",0.46,0.3,"Urban","Minor Stop-Controlled Intersection","Stop-controlled Intersection","All severity CMF is proportionally adjusted from the Angle and Rear End CMF","http://www.cmfclearinghouse.org/detail.cfm?facid=310","http://www.cmfclearinghouse.org/detail.cfm?facid=311","http://www.cmfclearinghouse.org/detail.cfm?facid=314"]
[null,"Convert from Pedestal-Mounted Traffic Signal to Mast Arm-Mounted Traffic Signal","All",0.71,0.71,null,"Signalized Intersection with Post-Mounted Traffic Signals","Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=1422"]
[null,"Convert from Pedestal-Mounted Traffic Signal to Span Wire-Mounted Traffic Signal","All",0.71,0.71,null,"Signalized Intersection with Post-Mounted Traffic Signals","Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=1422"]
[null,"Convert from Span Wire-Mounted Traffic Signal to Mast Arm-Mounted Traffic Signal","All",0.97,0.98,"All","Signalized Intersection with Span Wire-Mounted Traffic Signals","Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=9405","http://www.cmfclearinghouse.org/detail.cfm?facid=9404"]
[null,"Convert from two 3-leg intersections Offset by L Miles to a 4-leg intersection with Major Road AADT","All","((0.05-0.005*ln(AADT))/L+0.322)/(2*(0.05-0.005*ln(AADT))/L+0.322)","((0.05-0.005*ln(AADT))/L+0.322)/(2*(0.05-0.005*ln(AADT))/L+0.322)","Rural","Two Three-Leg Intersections Offset by X Miles","Rural Intersections",null,"Highway Safety Manual Equation 10-17"]
[null,"Convert from Two-Way Stop-Control to Signalized Intersection","Multi-Vehicle",0.56999999999999995,0.46,"Urban/Suburban","Minor Stop-Controlled Intersection","Three-Leg or Four-Leg Intersection",null,"MassDOT CMF Memo"]
[null,"Convert Minor Stop-Control Intersection to Modern Roundabout","Multi-Vehicle",0.48,0.16,"Urban/Suburban","Minor Stop-Controlled Intersection","Four-Leg Intersection",null,"MassDOT CMF Memo"]
[null,"Convert Signalized Intersection to Modern Roundabout","All",0.79200000000000004,0.34200000000000003,"Urban and Suburban","Signalized Intersection","Three-leg, Four-leg Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=4253","http://www.cmfclearinghouse.org/detail.cfm?facid=4252"]
[null,"Convert Two-Way Stop-Control Intersection to Right-In-Right-Out Operations","All",0.55000000000000004,0.55000000000000004,"Urban","Three-Leg Stop-Controlled Intersection with Left-Turns Allowed","Three-Leg Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=9821"]
[null,"Extend Left Turn Lane","All",0.72,0.76,"Urban","Turn Lane with Insufficient Length","Signalized Intersection","Proportionally adjusted from the target crash types (rear end and sideswipe) to all crashes","https://journals.sagepub.com/doi/pdf/10.1177/0361198120920270"]
[null,"Extend Right Turn Lane","All",0.72,0.76,"Urban","Turn Lane with Insufficient Length","Signalized Intersection","Proportionally adjusted from the target crash types (rear end and sideswipe) to all crashes","https://journals.sagepub.com/doi/pdf/10.1177/0361198120920270"]
[null,"Flatten Vertical Curve on Intersection Approach to Increase Stopping Sight Distance","All",0.7,0.62,"Rural","Intersection Downstream from a Crest Vertical Curve with Limited Sight Distance","Rural Segment with Downstream Intersection","Speed Limit 25-65 mph; applies to crest vertical curves. Taken as the inverse of the CMFs.","http://www.cmfclearinghouse.org/detail.cfm?facid=6871","http://www.cmfclearinghouse.org/detail.cfm?facid=6870"]
[null,"General Signalized Intersection Improvements at an HSIP Cluster","Multi-Vehicle",0.81,0.67,"Urban/Suburban","No Hidden Intersection, Driveway or Curve","Signalized Intersection","Improvements include any combination of repaving, new pavement markings, upgrading signal timing and equipment","MassDOT CMF Memo"]
[null,"High Friction Surface Treatment on Intersection Approach","All",0.79900000000000004,0.79900000000000004,"All","Intersection with Low Friction Numbers","Signalized or Stop-Controlled Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=2259"]
[null,"Increase All Red Clearance Interval","All",0.79800000000000004,0.86299999999999999,"Urban","All-Red Clearance Interval Shorter than 1 Second","Signalized Intersection","Three-leg, four-leg signalized ","http://www.cmfclearinghouse.org/detail.cfm?facid=4212","http://www.cmfclearinghouse.org/detail.cfm?facid=4211"]
[null,"Increase Intersection Triangle Sight Distance from X Feet of Available Sight Distance to Y Feet","All","0.64*exp(203.368*[1/Y-1/X])+0.36","0.71*exp(195.791*[1/Y-1/X])+0.29",null,null,null,"Proportionally adjusted from the target crash type (angle and left-turn) to all crashes","Eccles, Kimberly, Scott Himes, Kara Peach, Frank Gross, Richard J. Porter, Timothy J. Gates, and Christopher M. Monsere. Guidance for Evaluating the Safety Impacts of Intersection Sight Distance, National Cooperative Highway Research Program, Report 875, Washington, D.C., 2018. Available at https://www.nap.edu/download/25081"]
[null,"Increase Yellow Change Interval by One Second","All",1.1399999999999999,1.07,"Urban","Existing Yellow Change Interval","Signalized Intersection","Three-leg, four-leg signalized ","http://www.cmfclearinghouse.org/detail.cfm?facid=4208","http://www.cmfclearinghouse.org/detail.cfm?facid=4207"]
[null,"Innovative Intersection - Median U-Turn","All",0.63300000000000001,0.7732,"Urban and Suburban","Signalized Intersection","Four-Leg Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=10851","http://www.cmfclearinghouse.org/detail.cfm?facid=10852"]
[null,"Innovative Intersection - RCUT","All",0.8,0.8,"All","Both signalized and stop-controlled intersections","Four-Leg Intersection","Speed Limit >= 55 mph","http://www.cmfclearinghouse.org/detail.cfm?facid=10382"]
[null,"Innovative Intersection - Displaced Left Turn","All",0.88,0.88,null,"Signalized Intersection","Four-Leg Intersection",null,"https://www.researchgate.net/publication/327915966_Development_of_Crash_Modification_Factors_for_Continuous_Flow_Intersections"]
[null,"Innovative Intersection - Signalized RCUT","All",0.76319999999999999,5.6689999999999997E-2,"Urban and Suburban","Signalized Intersection","Four-Leg Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=10880","http://www.cmfclearinghouse.org/detail.cfm?facid=10879"]
[null,"Install Adaptive Traffic Signal Control","All",0.94799999999999995,0.95799999999999996,null,"Traditional Traffic Signal","Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=10561","http://www.cmfclearinghouse.org/detail.cfm?facid=10559"]
[null,"Install Advance Warning Dilemma Zone Protection System at Signalized Intersection","All",0.91800000000000004,0.89,null,"No Dilemma Zone Warning System","High-Speed Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=4857","http://www.cmfclearinghouse.org/detail.cfm?facid=4855"]
[null,"Install Flashing Lights and Sound Signals at Railroad Grade Crossing","All",0.5,0.5,null,"Static Signs","At-Grade Railroad Crossing",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=482"]
[null,"Install Gates and Signs at Railroad Grade Crossing","All",7.0000000000000007E-2,7.0000000000000007E-2,null,"Static Signs","At-Grade Railroad Crossing",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=493"]
[null,"Install Red Signal Ahead Sign","All",0.86,0.83130000000000004,"Urban","Signalized Intersection without \"Red Signal Ahead\" Warning Sign","Signalized Intersection","Proportionally adjusted from FI and PDO to All. Proportionally adjusted from the target crash type (angle) to all crashes","http://www.cmfclearinghouse.org/detail.cfm?facid=1684"]
[null,"Install Transverse Rumble Strips on Stop Controlled Approaches","All",0.87,0.71,"Rural","No Transverse Rumble Strips","Four-leg Stop-Controlled Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=9045","http://www.cmfclearinghouse.org/detail.cfm?facid=9046"]
[null,"Optimimize Total Change Period to Greater than ITE Recommended","All",0.92200000000000004,0.93700000000000006,"Urban","Total Change Interval Less Than ITE Recommended","Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=4219","http://www.cmfclearinghouse.org/detail.cfm?facid=4220"]
[null,"Provide a Left Turn Lane on a Major Approach at a Rural Three-Leg Stop-Controlled Intersection of Two Lane Highways","All",0.56000000000000005,0.56000000000000005,"Rural","No Left Turn Lane on Major Approach","Three-Leg Minor Stop-Controlled Intersection of Two-Lane Rural Roads",null,"Highway Safety Manual Table 10-13"]
[null,"Provide a Left Turn Lane on a Major Approach at a Rural Three-Leg Stop-Controlled Intersection with a Multilane Highway","All",0.56000000000000005,0.45,"Rural","No Left Turn Lane on Major Approach","Three-Leg Minor Stop-Controlled Intersection with Multilane Highway",null,"Highway Safety Manual Table 11-22"]
[null,"Provide a Left Turn Lane on a Major Approach at an Urban or Suburban Three-Leg Stop-Controlled Intersection with an Arterial","All",0.67,0.67,"Urban and Suburban","No Left Turn Lane on Major Approach","Three-Leg Minor Stop-Controlled Intersection with an Arterial",null,"Highway Safety Manual Table 11-22"]
[null,"Provide a Right Turn Lane on a Major Approach at a Rural Three-Leg Stop-Controlled Intersection of Two Lane Highways","All",0.86,0.86,"Rural","No Right Turn Lane on Major Approach","Three-Leg Minor Stop-Controlled Intersection of Two-Lane Rural Roads",null,"Highway Safety Manual Table 10-14"]
[null,"Provide a Right Turn Lane on a Major Approach at a Rural Three-Leg Stop-Controlled Intersection with a Multilane Highway","All",0.86,0.77,"Rural","No right Turn Lane on Major Approach","Three-Leg Minor Stop-Controlled Intersection with Multilane Highway",null,"Highway Safety Manual Table 11-23"]
[null,"Provide a Right Turn Lane on a Major Approach at an Urban or Suburban Three-Leg Stop-Controlled Intersection with an Arterial","All",0.86,0.86,"Urban and Suburban","No Right Turn Lane on Major Approach","Three-Leg Minor Stop-Controlled Intersection with an Arterial",null,"Highway Safety Manual Table 11-22"]
[null,"Provide Advance Street Name Signs","All",0.98399999999999999,0.99,"All","No Advanced Street Signs","Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=2450","http://www.cmfclearinghouse.org/detail.cfm?facid=2449"]
[null,"Remove Minor Street Leg from Four Leg Signalized Intersection","All",0.74,0.74,"Urban and Suburban","Four-Leg Signalized Intersection","Signalized Intersection","Cross-sectional comparison of 4SG and 3SG SPFs","MassDOT Intersection SPFs"]
[null,"Remove Minor Street Leg from Four Leg Stop-Controlled Intersection","All",0.98,0.98,"Urban and Suburban","Four-Leg Stop-Controlled Intersection","Stop-Controlled Intersection","Cross-sectional comparison of 4ST and 3ST SPFs","MassDOT Intersection SPFs"]
[null,"Replace 8-Inch Signal Heads with 12-Inch Signal Heads","All",0.97,0.97,null,"Signalized Intersection with 8-Inch Signal Heads","Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=2334"]
[null,"Replace Incandescent Signal Bulbs with LEDs - 3-Leg Intersection","All",1.04,1.17,"Urban","Incandescent Bulbs","3-Leg Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=4891","http://www.cmfclearinghouse.org/detail.cfm?facid=4890"]
[null,"Replace Incandescent Signal Bulbs with LEDs - 4-Leg Intersection","All",0.98199999999999998,1.0469999999999999,"Urban","Incandescent Bulbs","4-Leg Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=4899","http://www.cmfclearinghouse.org/detail.cfm?facid=4898"]
[null,"Shift Left Turn Lane to Create Positive Offset","All",0.66200000000000003,0.64400000000000002,null,"Left Turn Lanes with Negative Offset","Four-Leg Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=6096","http://www.cmfclearinghouse.org/detail.cfm?facid=6095"]
[null,"Signalizing driveway (Commercial, industrial, residential?)","Multi-Vehicle",0.56999999999999995,0.46,"Urban/Suburban","Minor Stop-Controlled Intersection","Three-Leg or Four-Leg Intersection",null,"MassDOT CMF Memo"]
[null,"Systemic Stop-Control Intersection Improvements","All",0.91700000000000004,0.89900000000000002,"All","Stop-Controlled Intersection without Supplemental Signage or Pavement Markings","Stop-Controlled Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=8867","http://www.cmfclearinghouse.org/detail.cfm?facid=8866"]
["Freeway Segments","Add Roadside Guardrail","All",1.0004362801377726,0.97505135277891897,null,"No Roadside Barrier Present","Freeway Segment","Proportionally adjusted from the target crash type (run off road) to all crashes; Speed Limit 50-70 mph","http://www.cmfclearinghouse.org/detail.cfm?facid=8395","http://www.cmfclearinghouse.org/detail.cfm?facid=8394"]
[null,"Add Segment Lighting","All",0.94,0.90342931937172777,"All","No Lighting Present","Freeway/Expressway Segment","Proportionally adjusted from FI and PDO to All. Proportionally adjusted from the target crash type (nighttime) to all crashes","http://www.cmfclearinghouse.org/detail.cfm?facid=581","http://www.cmfclearinghouse.org/detail.cfm?facid=582"]
[null,"Add Thru Lane on Segment (via Restriping)","All",0.93,0.76,"Urban","Fewer Lanes","Freeway Segment","Speed Limit >50 mph; Proportionally adjusted from FI and PDO to All","http://www.cmfclearinghouse.org/detail.cfm?facid=8334"]
[null,"Adding a New Off-Ramp","All","Contact MassDOT","Contact MassDOT","All","No Off Ramp Present","Freeway Segment","CMF spreadsheet to be provided \"Entrance Ramp Calculator to Calculate CMF\". Proportionally adjusted from FI and PDO to All. These CMFs provide a rough estimate of expected changes to safety performance with interchange modifications. We recommend using IHSDM or ISATe to perform a more detailed review.","HSM Chapters 18 and 19"]
[null,"Adding a New On-Ramp","All","Contact MassDOT","Contact MassDOT","All","No On Ramp Present","Freeway Segment","CMF spreadsheet to be provided \"Exit Ramp Calculator to Calculate CMF\". These CMFs provide a rough estimate of expected changes to safety performance with interchange modifications. We recommend using IHSDM or ISATe to perform a more detailed review. Proportionally adjusted from FI and PDO to All.","HSM Chapters 18 and 19"]
[null,"Addition of raised pavement reflectors","All",0.99,0.97853984874927291,"Rural","No raised pavement markers","Freeway/Expressway Segment","Proportionally adjusted from FI and PDO to All. Proportionally adjusted from the target crash type (nighttime) to all crashes","http://www.cmfclearinghouse.org/detail.cfm?facid=110"]
[null,"Change from other type of weave to Type B Weave","Multi-Vehicle","Contact MassDOT","Contact MassDOT","All","Non-Type B Weave Present","Freeway Segment","CMF spreadsheet to be provided  \"Convert to Type B Weave\". These CMFs provide a rough estimate of expected changes to safety performance with interchange modifications. We recommend using IHSDM or ISATe to perform a more detailed review. Proportionally adjusted from FI and PDO to All","HSM Equation 18-30 through 18-34, Table 18-20"]
[null,"Eliminate Weaving Condition","Multi-Vehicle","Contact MassDOT","Contact MassDOT","All","Weave Present","Freeway Segment","CMF spreadsheet to be provided \"Adding or Eliminating Weave\". These CMFs provide a rough estimate of expected changes to safety performance with interchange modifications. We recommend using IHSDM or ISATe to perform a more detailed review. Proportionally adjusted from FI and PDO to All","HSM Equation 18-30 through 18-34, Table 18-20"]
[null,"Install Median Cable Barrier","All",0.99,0.99116849580374433,"All","Traversable Median with No Barrier","Divided Freeway or Expressway","Proportionally adjusted from FI and PDO to All. Proportionally adjusted from the target crash type (cross-median) to all crashes","MassDOT CMF Memo"]
[null,"Install Median Concrete Barrier","All",0.99,0.98773402194964488,"Rural","Traversable Median with No Barrier","Divided Freeway or Expressway","Proportionally adjusted from FI and PDO to All. Proportionally adjusted from the target crash type (cross-median) to all crashes","http://www.cmfclearinghouse.org/detail.cfm?facid=2256"]
[null,"Install Median Guardrail","All",0.99,0.99043253712072299,null,"Traversable Median with No Barrier","Divided Freeway or Expressway","Proportionally adjusted from FI and PDO to All. Proportionally adjusted from the target crash type (cross-median) to all crashes","http://www.cmfclearinghouse.org/detail.cfm?facid=51"]
[null,"Install Rumble Strips on Inside Shoulder","Single-Vehicle",0.95,0.81100000000000005,"All","Paved Shoulder with No Rumble Strips","Freeway or Expressway Tangent","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Equations 18-36 & 18-37"]
[null,"Install Rumble Strips on Outside Shoulder","Single-Vehicle",0.95,0.81100000000000005,"All","Paved Shoulder with No Rumble Strips","Freeway or Expressway Tangent","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Equations 18-36 & 18-37"]
[null,"Install Variable Speed Limits","All",0.71,0.71,"Urban","Static Speed Limit","Divided Interstate","Speed Limit > 40 mph; Proportionally adjusted from FI and PDO to All","http://www.cmfclearinghouse.org/detail.cfm?facid=8730"]
[null,"Install/Upgrade Horizontal Curve Signage with Flourescent Sheeting, Warning Signs, and Flashing Beacons","All",0.60599999999999998,0.60599999999999998,null,"No Curve Delineation Treatment","Horizontal Curve on Expressway","Italian Study","http://www.cmfclearinghouse.org/detail.cfm?facid=1851"]
[null,"Introduce Weaving Condition","Multi-Vehicle","Contact MassDOT","Contact MassDOT","All","No Weave Present","Freeway Segment","CMF spreadsheet to be provided \"Adding or Eliminating Weave\". These CMFs provide a rough estimate of expected changes to safety performance with interchange modifications. We recommend using IHSDM or ISATe to perform a more detailed review. Proportionally adjusted from FI and PDO to All","HSM Equation 18-30 through 18-34, Table 18-20"]
[null,"Widen Average Clear Zone from X Feet to Y Feet","Single-Vehicle","(74548*exp(-0.00451*[X-Y])+195150)/269698","exp(-0.00451*[X-Y])","All","Average Clear Zone Width of X Feet","Freeway Segment","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Equation 18-38"]
[null,"Widen Median from X Feet to Y Feet - Multi-Vehicle Crashes","Multi-Vehicle","(74548*exp(-0.00302*[Y-X])+195150*exp(-0.00291*[Y-X]))/269698","exp(-0.00302*[Y-X])","All","Median Width of X Feet","Divided Freeway Segment with No Median Barrier","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Table 18-17"]
[null,"Widen Median from X Feet to Y Feet - Single-Vehicle Crashes","Single-Vehicle","(74548*exp(0.00102*[Y-X])+195150*exp(-0.00289*[Y-X]))/269698","exp(0.00102*[Y-X])","All","Median Width of X Feet","Divided Freeway Segment with No Median Barrier","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Table 18-17"]
[null,"Widen Paved Inside Shoulder from X Feet to Y Feet","All","(74548*exp(0.0172*[X-Y])+195150*exp(0.0153*[X-Y]))/269698","exp(0.0172*[X-Y])","All","Paved Inside Shoulder of X Feet","Freeway Segment","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Equation 18-26, Table 18-16"]
[null,"Widen Paved Outside Shoulder on Curve from X Feet to Y Feet","Single-Vehicle","(74548*exp(0.0897*[X-Y])+195150*exp(0.0840*[X-Y]))/269698","exp(0.0897*[X-Y])","All","Paved Outside Shoulder of X Feet","Freeway Horizontal Curve","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Eqaution 18-35, Table 18-21"]
[null,"Widen Paved Outside Shoulder on Tangent from X Feet to Y Feet","Single-Vehicle","(74548*exp(0.0647*[X-Y])+195150)/269698","exp(0.0647*[X-Y])","All","Paved Outside Shoulder of X Feet","Freeway Tangent","Proportionally adjusted from FI and PDO to All","Highway Safety Manual Eqaution 18-35, Table 18-21"]
["Non-Freeway Segments","Add Auxiliary Passing Lane","All",0.63,0.57999999999999996,"Rural","No Passing Lanes Present but Operations Indicate Need","Two-Lane Undivided Highway","Proportionally adjusted from FI and PDO to All","http://www.cmfclearinghouse.org/detail.cfm?facid=4083","http://www.cmfclearinghouse.org/detail.cfm?facid=4082"]
[null,"Add Breakaway Supports for Utility Poles in Clear Zone","All",1,0.99346722776597096,"Rural","Utility Poles without Breakaway Supports","Roadway with Utility Poles along Roadside","Proportionally adjusted from FI and PDO to All. Proportionally adjusted from the target crash type (fixed-object crashes) to all crashes. Based on an assumption of an 1 step improvement in roadside hazard rating","http://www.cmfclearinghouse.org/detail.cfm?facid=5187"]
[null,"Add Centerline Rumble Strips","All",0.97,0.9576543609519923,"Rural","No Centerline Rumble Strips","Two Lane Undivided Highway","Proportionally adjusted from FI and PDO to All. Proportionally adjusted from the target crash type (head-on and sideswipe-opposite) to all crashes","http://www.cmfclearinghouse.org/detail.cfm?facid=3360","http://www.cmfclearinghouse.org/detail.cfm?facid=3355"]
[null,"Add Fluorescent Sheeting to Chevron Signs","All",0.82,0.75,"Rural","No Sign or Sign Without Flourescent Sheeting","Two Lane Undivided Highway",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=2433","http://www.cmfclearinghouse.org/detail.cfm?facid=2431"]
[null,"Add SafetyEdge","All",0.97,0.95729124150258271,"Rural","Steep Pavement Edge Dropoff","Two Lane Undivided Highway","Proportionally adjusted from the target crash type (run off road) to all crashes. Proportionally adjusted from FI and PDO to All","http://www.cmfclearinghouse.org/detail.cfm?facid=9661"]
[null,"Add Segment Lighting","All",0.93,0.87649828996073242,"All","No Lighting Present","Urban Street","Proportionally adjusted from the target crash type (nighttime) to all crashes. Proportionally adjusted from FI and PDO to All","http://www.cmfclearinghouse.org/detail.cfm?facid=7774"]
[null,"Add Shoulder Rumble Strips","All",0.98,0.96542624312113834,"Rural","No Shoulder Rumble Strips Present","Two Lane Undivided Highway","Proportionally adjusted from the target crash type (run off road) to all crashes. Proportionally adjusted from FI and PDO to All","http://www.cmfclearinghouse.org/detail.cfm?facid=3447","http://www.cmfclearinghouse.org/detail.cfm?facid=3442"]
[null,"Add Thru Lane on Segment - Convert from Rural Two Lane Roadway to Four Lane Divided","All",0.71199999999999997,0.54900000000000004,"Rural","Two Lane Undivided Highway with Congestion-Related Safety Issues","Two Lane Undivided Highway Segment",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=7569","http://www.cmfclearinghouse.org/detail.cfm?facid=7571"]
[null,"Add Thru Lane on Segment - Convert from Urban Two Lane Roadway to Four Lane Divided","All",0.34100000000000003,0.36699999999999999,"Urban","Two Lane Undivided Highway with Congestion-Related Safety Issues","Two Lane Undivided Highway Segment",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=7568","http://www.cmfclearinghouse.org/detail.cfm?facid=7566"]
[null,"Add TWLTL - 2U to 3T","All",0.79700000000000004,0.73899999999999999,"All","No Two Way Left Turn Lane","Two Lane Undivided Highway",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=2341","http://www.cmfclearinghouse.org/detail.cfm?facid=2346"]
[null,"Add TWLTL - 4U to 5T","All",0.56399999999999995,0.56399999999999995,"Urban and Suburban","4-Lane Undivided Street","Urban or Suburban Arterial","This CMF applies in areas with a population between 5,000 and 25,000 people.","http://www.cmfclearinghouse.org/detail.cfm?facid=9418"]
[null,"Add Wet-Reflective Pavement Markings","All",0.82499999999999996,0.59499999999999997,null,"Standard Pavement Markings","Multilane Highway",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=8110","http://www.cmfclearinghouse.org/detail.cfm?facid=8109"]
[null,"Change Roadside Hazard Rating from X to Y by Flattening Roadside Slope","All","exp(0.0668*(Y-X))","exp(0.0668*(Y-X))","Rural","Roadside Slope Associated with Roadside Hazard Rating of X","Two Lane Rural Road",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=5187","https://www.fhwa.dot.gov/publications/research/safety/99207/appd.cfm"]
[null,"Change Roadside Hazard Rating from X to Y by Widening Clear Zone","All","exp(0.0668*(Y-X))","exp(0.0668*(Y-X))","Rural","Roadside Clear Zone Associated with Roadside Hazard Rating of X","Two Lane Rural Road",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=5187","https://www.fhwa.dot.gov/publications/research/safety/99207/appd.cfm"]
[null,"Convert Angle Parking to Parallel Parking","All",0.91,0.95631293014876639,"Urban","Angle Parking","Local Roadways","Proportionally adjusted from the target crash type (parking-related) to all crashes. Proportionally adjusted from FI and PDO to All","http://www.cmfclearinghouse.org/detail.cfm?facid=164"]
[null,"Convert Edgeline Markings from 4\" to 6\"","All",0.82499999999999996,0.63500000000000001,"Rural","4-inch edgelines","Two Lane Undivided Highway","Crash type also excludes intersection/interchange crashes and winter month crashes","https://www.cmfclearinghouse.org/detail.cfm?facid=4736","http://www.cmfclearinghouse.org/detail.cfm?facid=4737"]
[null,"Decrease Lane Width on Urban Street","All","Check CMF Clearinghouse for Relevant Lane Width Change: http://www.cmfclearinghouse.org/study_detail.cfm?stid=439","Check CMF Clearinghouse for Relevant Lane Width Change: http://www.cmfclearinghouse.org/study_detail.cfm?stid=439","Urban","Lane width of 10, 11, or 12 feet","Urban Street","Average for 1' and 2' lane width reductions, average AADT from study","http://www.cmfclearinghouse.org/study_detail.cfm?stid=439"]
[null,"Flatten Crest Vertical Curve","All",0.82,0.76,"Rural","Crest Vertical Curve without Sufficient Sight Distance","Crest Vertical Curve on Two Lane Undivided Highway","Speed Limit 25-65 mph","http://www.cmfclearinghouse.org/detail.cfm?facid=6869","http://www.cmfclearinghouse.org/detail.cfm?facid=6868"]
[null,"Flatten Horizontal Curve","All",0.315,0.25900000000000001,"Rural","Horizontal Curve with Sharp Horizontal Curve","Two Lane Rural Road","Minimum of 400 to Maximum of 12000 Annual Average Daily Traffic (AADT)","http://www.cmfclearinghouse.org/detail.cfm?facid=9651","http://www.cmfclearinghouse.org/detail.cfm?facid=9525"]
[null,"High Friction Surface Treatment on Horizontal Curve","All",0.52900000000000003,0.49,null,"Perceived Friction-Related Crash problem","Horizontal Curve",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=10319","http://www.cmfclearinghouse.org/detail.cfm?facid=10318"]
[null,"Horizontal Curve Warning Signs and Flashers","All",0.42,0.42,"Rural","Horizontal Curve with Speed-Related Crash Issues","Rural Highway",null,"https://www.fhwa.dot.gov/hfl/partnerships/tapco/final_report.pdf"]
[null,"Implement Traffic Calming Measure(s)","All",0.68,0.67,"Urban","No Traffic Calming Measure Present","Minor Collector","Generic traffic calming CMF","http://www.cmfclearinghouse.org/detail.cfm?facid=128","http://www.cmfclearinghouse.org/detail.cfm?facid=129"]
[null,"Improve Roadside by Reducing Roadside Hazard Rating from X to Y","All","exp(0.0668*(Y-X))","exp(0.0668*(Y-X))","Rural","Roadside Hazard Rating of X","Two Lane Undivided Highway",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=5187","https://www.fhwa.dot.gov/publications/research/safety/99207/appd.cfm"]
[null,"Improve STOP Sign Retroreflectivity at Stop-Controlled Intersection","All",0.94599999999999995,0.90600000000000003,"All","STOP Sign with Low Retroreflectivity","Stop-Controlled Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=6052","http://www.cmfclearinghouse.org/detail.cfm?facid=6053"]
[null,"Increase Pavement Marking Retroreflectivity","All",0.95,0.95059931598429293,"Rural","Longtiudinal Pavement Markings with Low Retroreflectivity","Two-lane rural highway","Proportionally adjusted from the target crash type (nighttime) to all crashes. Proportionally adjusted from FI and PDO to All","http://www.cmfclearinghouse.org/detail.cfm?facid=6842"]
[null,"Install Dynamic Speed Feedback Sign","All",0.95,0.95,"Rural","Horziontal Curve with Speeding Problem","Horizontal Curve on Two Lane Highway with a Posted Speed Limit Greater than 45 MPH","Speed Limit 50-65 mph","http://www.cmfclearinghouse.org/detail.cfm?facid=6885"]
[null,"Install Light-Reflecting Devices to Scare Away Animals","All",1,0.99997839580019987,null,"No Light-Reflecting Devices","Roadway Segment with a History of Animal Crashes","Proportionally adjusted from the target crash type (vehicle-animal) to all crashes","http://www.cmfclearinghouse.org/detail.cfm?facid=9149"]
[null,"Install Roadside Barrier","All",0.97,0.91051498219588756,null,"Unprotected Roadside Embankment","Fill Segment","Proportionally adjusted from the target crash type (run off road) to all crashes. Proportionally adjusted from FI and PDO to All. Proportionally adjusted from K and ABC to FI.","http://www.cmfclearinghouse.org/detail.cfm?facid=37","http://www.cmfclearinghouse.org/detail.cfm?facid=38","http://www.cmfclearinghouse.org/detail.cfm?facid=39"]
[null,"Install Speed Cameras","All",0.46,0.52,"Urban","No Speed Cameras Present","Principal Arterial - Other",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=2915","http://www.cmfclearinghouse.org/detail.cfm?facid=2921"]
[null,"Prohibit On-Street Parking","All",0.75,0.8,"Urban","Parking Permitted on Street","Minor Arterial","Proportionally adjusted from FI and PDO to All","http://www.cmfclearinghouse.org/detail.cfm?facid=153","http://www.cmfclearinghouse.org/detail.cfm?facid=154"]
[null,"Reduce Access Point Density from X Driveways per Mile to Y Driveways per Mile","All","exp(0.0232*[Y-X])","exp(0.0152*[Y-X])","Rural","Driveway Density of X Driveways per Mile","Two Lane Undivided Highway",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=1973","http://www.cmfclearinghouse.org/detail.cfm?facid=2248"]
[null,"Reduce Superelevation Deficiency on Horizontal Curve from X to Y, Superelevation Deficiency Between 0.01 and 0.02 Feet per Foot","All","(1+6*(Y-0.01))/(1+6*(X-0.01))","(1+6*(Y-0.01))/(1+6*(X-0.01))","Rural","Superelevation Deficiency of X Feet per Foot, X is Between 0.01 and 0.02","Horizontal Curve on Two Lane Undivided Highway",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=5183"]
[null,"Reduce Superelevation Deficiency on Horizontal Curve from X to Y, Superelevation Deficiency Greater than 0.02 Feet per Foot","All","(1+3*(Y-0.02))/(1+3*(X-0.02))","(1+3*(Y-0.02))/(1+3*(X-0.02))","Rural","Superelevation Deficiency of X Feet per Foot, X is Greater than 0.02","Horizontal Curve on Two Lane Undivided Highway",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=5184"]
[null,"Resurface Rural Roadway","All",1.03,0.74,"Rural","Poor Pavement Condition","Two Lane Undivided Highway","Minimum of 410 to Maximum of 26943 Annual Average Daily Traffic (AADT)","http://www.cmfclearinghouse.org/detail.cfm?facid=5629","http://www.cmfclearinghouse.org/detail.cfm?facid=5626"]
[null,"Resurface Urban Street","All",0.92900000000000005,0.78700000000000003,"Urban","Old Pavement","Urban Street, Signalized Intersection",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=10280","http://www.cmfclearinghouse.org/detail.cfm?facid=9289"]
[null,"Road Diet - 4U to 3T","All",0.71,0.71,"Urban","Four Lane Undivided Roadway","Four Lane Undivided Minor Arterial",null,"http://www.cmfclearinghouse.org/detail.cfm?facid=199"]
[null,"Widen Average Lane Width for Rural Roadway by 1 Foot","All",0.93,0.93,"Rural","Rural Roadway with Narrow Lanes","Rural Highway","Averaged 1' Lane Width Widening and Used HSM Adjustment Factor","Highway Safety Manual Table 10-8 and Equation 10-11"]
[null,"Widen Average Lane Width for Urban Street by 1 Foot","All",0.84,0.9,"Urban","Urban Street with Narrow Lanes","Urban Street","Average of 1' increases from 10 to 11 and 11 to 12","http://www.cmfclearinghouse.org/study_detail.cfm?stid=439"]
[null,"Widen Paved Shoulder on Rural Roadway","All",0.93,0.93,"Rural","Narrow Shoulder","Rural Highway",null,"Highway Safety Manual Table 10-9"]

{"sheet":"Input","index":2,"n_rows":119,"n_cols":13,"rows_kept":119,"cut":false,"hidden":false,"merged":[[75,2,75,3],[74,2,74,3],[74,4,74,5],[75,4,75,5],[14,0,14,6],[13,0,13,6],[59,2,59,3],[15,0,15,5],[28,0,28,5],[27,0,27,5],[19,0,19,5],[35,3,35,12],[16,0,16,5],[20,0,20,5],[18,0,18,6],[48,0,48,3],[53,0,53,2],[24,0,24,5],[26,0,26,5],[25,0,25,5],[23,0,23,5],[22,0,22,5],[21,0,21,5],[72,2,72,3],[72,4,72,5],[73,2,73,3],[73,4,73,5],[52,0,52,2],[30,0,30,5],[29,0,29,5],[32,0,32,5],[31,0,31,5],[49,0,49,2],[51,0,51,2],[50,0,50,2],[60,4,60,6],[54,0,54,2],[72,1,74,1],[82,4,82,5],[81,4,81,5],[78,2,78,3],[76,2,76,3],[78,4,78,5],[81,2,81,3],[82,2,82,3],[79,2,79,3],[80,2,80,3],[77,2,77,3],[77,4,77,5],[80,4,80,5],[76,4,76,5],[79,4,79,5],[0,4,0,6],[2,0,2,6],[3,0,3,3],[3,4,3,6],[9,0,9,6],[11,0,11,1],[10,0,10,1],[10,4,10,5],[7,0,7,1],[4,2,4,3],[4,5,4,6],[5,2,5,3],[5,5,5,6],[6,2,6,3],[6,5,6,6],[0,0,0,1],[0,2,0,3],[5,0,5,1],[4,0,4,1],[6,0,6,1],[7,5,7,6],[7,2,7,3],[11,2,11,3],[10,2,10,3],[92,2,92,3],[92,4,92,5],[84,2,84,3],[84,4,84,5],[84,1,86,1],[85,2,85,3],[85,4,85,5],[86,2,86,3],[86,4,86,5],[118,2,118,3],[118,4,118,5],[114,2,114,3],[114,4,114,5],[115,2,115,3],[115,4,115,5],[116,2,116,3],[116,4,116,5],[96,1,98,1],[97,2,97,3],[97,4,97,5],[98,2,98,3],[98,4,98,5],[96,4,96,5],[99,2,99,3],[99,4,99,5],[100,2,100,3],[100,4,100,5],[113,2,113,3],[113,4,113,5],[108,1,110,1],[109,2,109,3],[109,4,109,5],[110,2,110,3],[117,2,117,3],[117,4,117,5],[110,4,110,5],[105,2,105,3],[105,4,105,5],[106,2,106,3],[106,4,106,5],[108,2,108,3],[108,4,108,5],[111,2,111,3],[111,4,111,5],[112,2,112,3],[112,4,112,5],[1,2,1,3],[102,4,102,5],[103,2,103,3],[103,4,103,5],[104,2,104,3],[104,4,104,5],[102,2,102,3],[101,2,101,3],[101,4,101,5],[93,2,93,3],[93,4,93,5],[94,2,94,3],[94,4,94,5],[96,2,96,3],[87,2,87,3],[87,4,87,5],[88,2,88,3],[88,4,88,5],[89,2,89,3],[89,4,89,5],[90,2,90,3],[90,4,90,5],[91,2,91,3],[91,4,91,5]]}
["Required Manual Input",null,"Optional Manual Input",null,"Select from Drop-Down List"]
[null,null,"Method 3","Method 3"]
["General Information"]
["General Information",null,null,null,"Location Information"]
["Analyst",null,null,null,"City"]
["Agency or Company",null,null,null,"Intersection"]
["Date Performed",null,null,null,"Jurisdiction"]
["Study Period (Years, 5 minimum - 10 maximum):",null,1,null,"Analysis Year"]
[]
["Intersection Data"]
["Intersection Type:",null,"3ST HSM"]
["Intersection Lighting (Present/Not Present):",null,"Not Present"]
[]
[]
["Stop Controlled - This information not needed for Method 3"]
["Number of major-road approaches with left-turn lanes (0,1,2)"]
["Number of major-road approaches with right-turn lanes (0,1,2)"]
[]
["Signal Controlled - This information not needed for Method 3"]
["Number of approaches with left-turn lanes (0,1,2,3,4) \n[for 3SG, use maximum value of 3]"]
["Number of approaches with right-turn lanes (0,1,2,3,4) \n[for 3SG, use maximum value of 3]"]
["Number of approaches with left-turn signal phasing \n[for 3SG, use maximum value of 3]"]
["Type of left-turn signal phasing for Leg #1"]
["Type of left-turn signal phasing for Leg #2"]
["Type of left-turn signal phasing for Leg #3"]
["Type of left-turn signal phasing for Leg #4"]
["Number of approaches with right-turn-on-red prohibited \n[for 3SG, use maximum value of 3]"]
["Intersection red light cameras (present/not present)"]
["Sum of all pedestrian crossing volumes  (PedVol) -- Signalized intersections only"]
["Maximum number of lanes crossed by a pedestrian (nlanesx)"]
["Number of bus stops within 300 m (1,000 ft) of the intersection"]
["Schools within 300 m (1,000 ft) of the intersection (present/not present)"]
["Number of alcohol sales establishments within 300 m (1,000 ft) of the intersection"]
[]
["Step 1 – Expected Change in Safety Performance"]
[null,null,null,"Years"]
["Step 1.3A - Observed Crash Data for Intersection",null,null,"20XX","20XX","20XX","20XX","20XX","20XX","20XX","20XX","20XX","20XX"]
["Crash Type, Severity","Total","Average per Year","Year 1","Year 2","Year 3","Year 4","Year 5","Year 6","Year 7","Year 8","Year 9","Year 10"]
["MV, FI",{"$f":"IF(COUNTA(D39:INDIRECT(ADDRESS(39,3+$C$8)))<>$C$8,\"INVALID\",SUM(D39:INDIRECT(ADDRESS(39,3+$C$8))))","v":"INVALID"},{"$f":"IF(COUNTA(D39:INDIRECT(ADDRESS(39,3+$C$8)))<>$C$8,\"ENSURE TABLE ROW IS COMPLETELY FILLED OUT\",AVERAGE(D39:INDIRECT(ADDRESS(39,3+$C$8))))","v":"ENSURE TABLE ROW IS COMPLETELY FILLED OUT"}]
["MV, PDO",{"$f":"IF(COUNTA(D40:INDIRECT(ADDRESS(40,3+$C$8)))<>$C$8,\"INVALID\",SUM(D40:INDIRECT(ADDRESS(40,3+$C$8))))","v":"INVALID"},{"$f":"IF(COUNTA(D40:INDIRECT(ADDRESS(40,3+$C$8)))<>$C$8,\"ENSURE TABLE ROW IS COMPLETELY FILLED OUT\",AVERAGE(D40:INDIRECT(ADDRESS(40,3+$C$8))))","v":"ENSURE TABLE ROW IS COMPLETELY FILLED OUT"}]
["SV, FI",{"$f":"IF(COUNTA(D41:INDIRECT(ADDRESS(41,3+$C$8)))<>$C$8,\"INVALID\",SUM(D41:INDIRECT(ADDRESS(41,3+$C$8))))","v":"INVALID"},{"$f":"IF(COUNTA(D41:INDIRECT(ADDRESS(41,3+$C$8)))<>$C$8,\"ENSURE TABLE ROW IS COMPLETELY FILLED OUT\",AVERAGE(D41:INDIRECT(ADDRESS(41,3+$C$8))))","v":"ENSURE TABLE ROW IS COMPLETELY FILLED OUT"}]
["SV, PDO",{"$f":"IF(COUNTA(D42:INDIRECT(ADDRESS(42,3+$C$8)))<>$C$8,\"INVALID\",SUM(D42:INDIRECT(ADDRESS(42,3+$C$8))))","v":"INVALID"},{"$f":"IF(COUNTA(D42:INDIRECT(ADDRESS(42,3+$C$8)))<>$C$8,\"ENSURE TABLE ROW IS COMPLETELY FILLED OUT\",AVERAGE(D42:INDIRECT(ADDRESS(42,3+$C$8))))","v":"ENSURE TABLE ROW IS COMPLETELY FILLED OUT"}]
["Ped, FI",{"$f":"IF(COUNTA(D43:INDIRECT(ADDRESS(43,3+$C$8)))<>$C$8,\"INVALID\",SUM(D43:INDIRECT(ADDRESS(43,3+$C$8))))","v":"INVALID"},{"$f":"IF(COUNTA(D43:INDIRECT(ADDRESS(43,3+$C$8)))<>$C$8,\"ENSURE TABLE ROW IS COMPLETELY FILLED OUT\",AVERAGE(D43:INDIRECT(ADDRESS(43,3+$C$8))))","v":"ENSURE TABLE ROW IS COMPLETELY FILLED OUT"}]
["Ped, PDO",{"$f":"IF(COUNTA(D44:INDIRECT(ADDRESS(44,3+$C$8)))<>$C$8,\"INVALID\",SUM(D44:INDIRECT(ADDRESS(44,3+$C$8))))","v":"INVALID"},{"$f":"IF(COUNTA(D44:INDIRECT(ADDRESS(44,3+$C$8)))<>$C$8,\"ENSURE TABLE ROW IS COMPLETELY FILLED OUT\",AVERAGE(D44:INDIRECT(ADDRESS(44,3+$C$8))))","v":"ENSURE TABLE ROW IS COMPLETELY FILLED OUT"}]
["Bike, FI",{"$f":"IF(COUNTA(D45:INDIRECT(ADDRESS(45,3+$C$8)))<>$C$8,\"INVALID\",SUM(D45:INDIRECT(ADDRESS(45,3+$C$8))))","v":"INVALID"},{"$f":"IF(COUNTA(D45:INDIRECT(ADDRESS(45,3+$C$8)))<>$C$8,\"ENSURE TABLE ROW IS COMPLETELY FILLED OUT\",AVERAGE(D45:INDIRECT(ADDRESS(45,3+$C$8))))","v":"ENSURE TABLE ROW IS COMPLETELY FILLED OUT"}]
["Bike, PDO",{"$f":"IF(COUNTA(D46:INDIRECT(ADDRESS(46,3+$C$8)))<>$C$8,\"INVALID\",SUM(D46:INDIRECT(ADDRESS(46,3+$C$8))))","v":"INVALID"},{"$f":"IF(COUNTA(D46:INDIRECT(ADDRESS(46,3+$C$8)))<>$C$8,\"ENSURE TABLE ROW IS COMPLETELY FILLED OUT\",AVERAGE(D46:INDIRECT(ADDRESS(46,3+$C$8))))","v":"ENSURE TABLE ROW IS COMPLETELY FILLED OUT"}]
[null,null,null,{"$f":"IF(COUNTA(Table17[Year 1])=0,\"\",IF(COUNTA(Table17[Year 1])=8,\"\",\"ENSURE TABLE COLUMN IS COMPLETELY FILLED OUT\"))","v":""},{"$f":"IF(COUNTA(Table17[Year 2])=0,\"\",IF(COUNTA(Table17[Year 2])=8,\"\",\"ENSURE TABLE COLUMN IS COMPLETELY FILLED OUT\"))","v":""},{"$f":"IF(COUNTA(Table17[Year 3])=0,\"\",IF(COUNTA(Table17[Year 3])=8,\"\",\"ENSURE TABLE COLUMN IS COMPLETELY FILLED OUT\"))","v":""},{"$f":"IF(COUNTA(Table17[Year 4])=0,\"\",IF(COUNTA(Table17[Year 4])=8,\"\",\"ENSURE TABLE COLUMN IS COMPLETELY FILLED OUT\"))","v":""},{"$f":"IF(COUNTA(Table17[Year 5])=0,\"\",IF(COUNTA(Table17[Year 5])=8,\"\",\"ENSURE TABLE COLUMN IS COMPLETELY FILLED OUT\"))","v":""},{"$f":"IF(COUNTA(Table17[Year 6])=0,\"\",IF(COUNTA(Table17[Year 6])=8,\"\",\"ENSURE TABLE COLUMN IS COMPLETELY FILLED OUT\"))","v":""},{"$f":"IF(COUNTA(Table17[Year 7])=0,\"\",IF(COUNTA(Table17[Year 7])=8,\"\",\"ENSURE TABLE COLUMN IS COMPLETELY FILLED OUT\"))","v":""},{"$f":"IF(COUNTA(Table17[Year 8])=0,\"\",IF(COUNTA(Table17[Year 8])=8,\"\",\"ENSURE TABLE COLUMN IS COMPLETELY FILLED OUT\"))","v":""},{"$f":"IF(COUNTA(Table17[Year 9])=0,\"\",IF(COUNTA(Table17[Year 9])=8,\"\",\"ENSURE TABLE COLUMN IS COMPLETELY FILLED OUT\"))","v":""},{"$f":"IF(COUNTA(Table17[Year 10])=0,\"\",IF(COUNTA(Table17[Year 10])=8,\"\",\"ENSURE TABLE COLUMN IS COMPLETELY FILLED OUT\"))","v":""}]
[]
["Step 1.3B - Traffic Data"]
["Average AADT (entering the intersection or on the segment) for the Study Period(Major):"]
[]
["Average AADT (entering the intersection or on the segment) for the Study Period(Minor):"]
[]
["Average AADT for the Study Period(Total):",null,null,{"$f":"IF(AND(D50<>\"\",D52<>\"\"),D50+D52,\"Please Input Both AADT's\")","v":"Please Input Both AADT's"}]
["Design Year AADT (Total):"]
[null,null,null,{"$f":"IF(OR(D52=\"\",D55=\"\",D50=\"\"),\"Please Enter All AADT's\",\"\")","v":"Please Enter All AADT's"}]
[]
[]
["Step 2 – Expected Change in Safety Performance"]
["Facility Type:",{"$f":"INDEX(Table58[],MATCH(C60,Table58[Facility Type],0),2)","v":0},"Please Select Facility Type"]
["Discount Rate (i)",7.0000000000000007E-2,"Number of Proposed Alternatives:",0,{"$f":"IF(OR(D61=\"\",D61=0),\"To Unlock Tables Below Please Select The Number of Proposed Alternatives\",\"\")","v":"To Unlock Tables Below Please Select The Number of Proposed Alternatives"}]
[]
[]
[]
[null,"Alternative 1","Alternative 2","Alternative 3","Alternative 4"]
["Name of Countermeasure 1"]
["Name of Countermeasure 2 (If Desired)"]
["Estimated Service Life (Years)"]
["Estimated Improvement Cost"]
[]
[]
["CMF Input - Use CMFs Tab to Calculate - If no CMF Adjustment being made leave the default value of 1.000; PDO CMF Not required - PDO crash reductions calculated by subtracting FI crashes from ALL crashes"]
["Alternative 1","CMF Combination Method\n (If Applicable):","Countermeasure 1:",null,"Countermeasure 2\n(Select CMF Combination Method to Unlock):"]
["Name",null,{"$f":"IF(B66=\"\",\"\",B66)","v":""},null,{"$f":"IF(B67=\"\",\"\",B67)","v":""}]
["Crash Type, Severity",null,"CMF",null,"CMF"]
["MV, ALL","Not Applicable",1,null,1,null,{"$f":"IF(AND(B76=\"Multiplicative\",C76<=1,E76<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B76<>\"Not Applicable\",B76<>\"Multiplicative\"),IF(OR(C76>1,E76>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B76=\"Not Applicable\",E76<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["MV, FI","Not Applicable",1,null,1,null,{"$f":"IF(AND(B77=\"Multiplicative\",C77<=1,E77<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B77<>\"Not Applicable\",B77<>\"Multiplicative\"),IF(OR(C77>1,E77>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B77=\"Not Applicable\",E77<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["SV, ALL","Not Applicable",1,null,1,null,""]
["SV, FI","Not Applicable",1,null,1,null,{"$f":"IF(AND(B79=\"Multiplicative\",C79<=1,E79<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B79<>\"Not Applicable\",B79<>\"Multiplicative\"),IF(OR(C79>1,E79>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B79=\"Not Applicable\",E79<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["Ped, ALL","Not Applicable",1,null,1,null,""]
["Ped, FI","Not Applicable",1,null,1,null,{"$f":"IF(AND(B81=\"Multiplicative\",C81<=1,E81<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B81<>\"Not Applicable\",B81<>\"Multiplicative\"),IF(OR(C81>1,E81>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B81=\"Not Applicable\",E81<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["Bike, ALL","Not Applicable",1,null,1,null,""]
["Bike, FI","Not Applicable",1,null,1,null,{"$f":"IF(AND(B83=\"Multiplicative\",C83<=1,E83<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B83<>\"Not Applicable\",B83<>\"Multiplicative\"),IF(OR(C83>1,E83>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B83=\"Not Applicable\",E83<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
[]
["Alternative 2","CMF Combination Method\n (If Applicable):","Countermeasure 1:",null,"Countermeasure 2\n(Select CMF Combination Method to Unlock):"]
["Name",null,{"$f":"IF(C66=\"\",\"\",C66)","v":""},null,{"$f":"IF(C67=\"\",\"\",C67)","v":""}]
["Crash Type, Severity",null,"CMF",null,"CMF"]
["MV, ALL","Not Applicable",1,null,1,null,{"$f":"IF(AND(B88=\"Multiplicative\",C88<=1,E88<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B88<>\"Not Applicable\",B88<>\"Multiplicative\"),IF(OR(C88>1,E88>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B88=\"Not Applicable\",E88<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["MV, FI","Not Applicable",1,null,1,null,{"$f":"IF(AND(B89=\"Multiplicative\",C89<=1,E89<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B89<>\"Not Applicable\",B89<>\"Multiplicative\"),IF(OR(C89>1,E89>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B89=\"Not Applicable\",E89<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["SV, ALL","Not Applicable",1,null,1,null,""]
["SV, FI","Not Applicable",1,null,1,null,""]
["Ped, ALL","Not Applicable",1,null,1,null,""]
["Ped, FI","Not Applicable",1,null,1,null,""]
["Bike, ALL","Not Applicable",1,null,1,null,""]
["Bike, FI","Not Applicable",1,null,1,null,""]
[]
["Alternative 3","CMF Combination Method\n (If Applicable):","Countermeasure 1:",null,"Countermeasure 2\n(Select CMF Combination Method to Unlock):"]
["Name",null,{"$f":"IF(D66=\"\",\"\",D66)","v":""},null,{"$f":"IF(D67=\"\",\"\",D67)","v":""}]
["Crash Type, Severity",null,"CMF",null,"CMF"]
["MV, ALL","Not Applicable",1,null,1,null,{"$f":"IF(AND(B100=\"Multiplicative\",C100<=1,E100<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B100<>\"Not Applicable\",B100<>\"Multiplicative\"),IF(OR(C100>1,E100>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B100=\"Not Applicable\",E100<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["MV, FI","Not Applicable",1,null,1,null,{"$f":"IF(AND(B101=\"Multiplicative\",C101<=1,E101<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B101<>\"Not Applicable\",B101<>\"Multiplicative\"),IF(OR(C101>1,E101>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B101=\"Not Applicable\",E101<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["SV, ALL","Not Applicable",1,null,1,null,""]
["SV, FI","Not Applicable",1,null,1,null,""]
["Ped, ALL","Not Applicable",1,null,1,null,""]
["Ped, FI","Not Applicable",1,null,1,null,""]
["Bike, ALL","Not Applicable",1,null,1,null,""]
["Bike, FI","Not Applicable",1,null,1,null,""]
[null,null,null,null,null,null,{"$f":"IF(AND(B108=\"Multiplicative\",C108<=1,E108<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B108<>\"Not Applicable\",B108<>\"Multiplicative\"),IF(OR(C108>1,E108>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B108=\"Not Applicable\",E108<>\"\"),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["Alternative 4","CMF Combination Method\n (If Applicable):","Countermeasure 1:",null,"Countermeasure 2\n(Select CMF Combination Method to Unlock):"]
["Name",null,{"$f":"IF(E66=\"\",\"\",E66)","v":""},null,{"$f":"IF(E67=\"\",\"\",E67)","v":""}]
["Crash Type, Severity",null,"CMF",null,"CMF"]
["MV, ALL","Not Applicable",1,null,1,null,{"$f":"IF(AND(B112=\"Multiplicative\",C112<=1,E112<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B112<>\"Not Applicable\",B112<>\"Multiplicative\"),IF(OR(C112>1,E112>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B112=\"Not Applicable\",E112<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["MV, FI","Not Applicable",1,null,1,null,{"$f":"IF(AND(B113=\"Multiplicative\",C113<=1,E113<=1),\"ERROR - At Least 1 Value Must Be >1.0\",IF(AND(B113<>\"Not Applicable\",B113<>\"Multiplicative\"),IF(OR(C113>1,E113>1),\"If a CMF is > 1, must select Multiplicative\",\"\"),IF(AND(B113=\"Not Applicable\",E113<>1),\"Please clear value from countermeasure 2 CMF\",\"\")))","v":""}]
["SV, ALL","Not Applicable",1,null,1,null,""]
["SV, FI","Not Applicable",1,null,1,null,""]
["Ped, ALL","Not Applicable",1,null,1,null,""]
["Ped, FI","Not Applicable",1,null,1,null,""]
["Bike, ALL","Not Applicable",1,null,1,null,""]
["Bike, PDO","Not Applicable",1,null,1,null,""]

{"sheet":"Input Summary","index":3,"n_rows":37,"n_cols":5,"rows_kept":37,"cut":false,"hidden":true,"merged":[[14,0,14,3],[13,0,13,3],[12,0,12,3],[36,0,36,3],[35,0,35,3],[25,0,25,3],[24,0,24,3],[23,0,23,3],[31,0,31,3],[30,0,30,3],[29,0,29,3],[28,0,28,3],[27,0,27,3],[10,2,10,3],[9,2,9,3],[8,2,8,3],[26,0,26,3],[34,0,34,3],[33,0,33,3],[32,0,32,3],[22,0,22,4],[21,0,21,4],[11,0,11,4],[20,0,20,4],[19,0,19,3],[18,0,18,3],[17,0,17,4],[16,0,16,4],[15,0,15,4],[0,0,0,1],[0,2,0,4],[2,0,2,4],[7,3,7,4],[4,3,4,4],[3,0,3,1],[3,2,3,4],[1,0,1,4],[6,3,6,4],[5,3,5,4]]}
["Required Automated Input For Each Year",null,"Single Automated Data Pull"]
["NOTE: This sheet can't be used to calculate when converting to a different intersection type"]
["General Information and Input Data for Urban and Suburban Arterial Intersections"]
["General Information",null,"Location Information"]
["Analyst",{"$f":"Input!C5","v":0},"City",{"$f":"Input!F5","v":0}]
["Agency or Company",{"$f":"Input!C6","v":0},"Intersection",{"$f":"Input!F6","v":0}]
["Date Performed",{"$f":"Input!C7","v":"00:00:00"},"Jurisdiction",{"$f":"Input!F7","v":0}]
[null,null,"Analysis Year",{"$f":"Input!F8","v":0}]
["Facility Type:",{"$f":"Input!C60","v":"Please Select Facility Type"},"Discount Rate (i)",null,{"$f":"Input!B61","v":7.0000000000000007E-2}]
["Sheet to Pull Data From:",{"$f":"Input!C11","v":"3ST HSM"},"Intersection Type:",null,{"$f":"LEFT(B10,3)","v":"3ST"}]
["Number of Proposed Alternatives:",{"$f":"Input!D61","v":0},"Study Period:",null,{"$f":"Input!C8","v":1}]
["Present Data:"]
["Present AADT(Major):"]
["Present AADT(Minor):"]
["Intersection Lighting (Present/Not Present):",null,null,null,{"$f":"Input!C12","v":"Not Present"}]
[]
["Stop Controlled"]
["Present Data:"]
["Number of major-road approaches with left-turn lanes (0,1,2)",null,null,null,{"$f":"Input!G16","v":0}]
["Number of major-road approaches with right-turn lanes (0,1,2)",null,null,null,{"$f":"Input!G17","v":0}]
[]
["Signal Controlled"]
["Present Data:"]
["Number of approaches with left-turn lanes (0,1,2,3,4) \n[for 3SG, use maximum value of 3]",null,null,null,{"$f":"Input!G20","v":0}]
["Number of approaches with right-turn lanes (0,1,2,3,4) \n[for 3SG, use maximum value of 3]",null,null,null,{"$f":"Input!G21","v":0}]
["Number of approaches with left-turn signal phasing \n[for 3SG, use maximum value of 3]",null,null,null,{"$f":"Input!G22","v":0}]
["Type of left-turn signal phasing for Leg #1",null,null,null,{"$f":"Input!G23","v":0}]
["Type of left-turn signal phasing for Leg #2",null,null,null,{"$f":"Input!G24","v":0}]
["Type of left-turn signal phasing for Leg #3",null,null,null,{"$f":"Input!G25","v":0}]
["Type of left-turn signal phasing for Leg #4 (if applicable)",null,null,null,{"$f":"Input!G26","v":0}]
["Number of approaches with right-turn-on-red prohibited \n[for 3SG, use maximum value of 3]",null,null,null,{"$f":"Input!G27","v":0}]
["Intersection red light cameras (present/not present)",null,null,null,{"$f":"Input!G28","v":0}]
["Sum of all pedestrian crossing volumes  (PedVol) -- Signalized intersections only",null,null,null,{"$f":"Input!G29","v":0}]
["Maximum number of lanes crossed by a pedestrian (nlanesx)",null,null,null,{"$f":"Input!G30","v":0}]
["Number of bus stops within 300 m (1,000 ft) of the intersection",null,null,null,{"$f":"Input!G31","v":0}]
["Schools within 300 m (1,000 ft) of the intersection (present/not present)",null,null,null,{"$f":"Input!G32","v":0}]
["Number of alcohol sales establishments within 300 m (1,000 ft) of the intersection",null,null,null,{"$f":"Input!G33","v":0}]

{"sheet":"Output","index":4,"n_rows":105,"n_cols":9,"rows_kept":105,"cut":false,"hidden":false,"merged":[[92,1,92,2],[92,3,92,4],[92,5,92,6],[92,7,92,8],[91,0,91,8],[54,1,54,2],[54,4,54,6],[72,1,72,2],[72,4,72,6],[1,0,1,5],[16,0,16,6],[18,1,18,2],[18,4,18,6],[36,1,36,2],[36,4,36,6]]}
["Results","Ensure that program at end of Input was run. If any Input values are modified, the program must be run again. If cells display #REF, press the F9 key."]
["Step 1.3C - Calculate Estimated Number of Crashes for the Design Year"]
["Crash Type, Severity","Total Observed Crashes During Study Period","AADTstudy","YYears,study","AADTDesign","Estimated Crashes During the Design Year using Method 3, No-Build"]
["MV, FI",{"$f":"Input!B39","v":"INVALID"},{"$f":"Input!$D$54","v":"Please Input Both AADT's"},{"$f":"Input!$C$8","v":1},{"$f":"Input!$D$55","v":0},{"$f":"B4/(C4*D4)*E4","v":{"$error":"#VALUE!"}}]
["MV, PDO",{"$f":"Input!B40","v":"INVALID"},{"$f":"Input!$D$54","v":"Please Input Both AADT's"},{"$f":"Input!$C$8","v":1},{"$f":"Input!$D$55","v":0},{"$f":"B5/(C5*D5)*E5","v":{"$error":"#VALUE!"}}]
["SV, FI",{"$f":"Input!B41","v":"INVALID"},{"$f":"Input!$D$54","v":"Please Input Both AADT's"},{"$f":"Input!$C$8","v":1},{"$f":"Input!$D$55","v":0},{"$error":"#VALUE!"}]
["SV, PDO",{"$f":"Input!B42","v":"INVALID"},{"$f":"Input!$D$54","v":"Please Input Both AADT's"},{"$f":"Input!$C$8","v":1},{"$f":"Input!$D$55","v":0},{"$f":"B7/(C7*D7)*E7","v":{"$error":"#VALUE!"}}]
["Ped, FI",{"$f":"Input!B43","v":"INVALID"},{"$f":"Input!$D$54","v":"Please Input Both AADT's"},{"$f":"Input!$C$8","v":1},{"$f":"Input!$D$55","v":0},{"$error":"#VALUE!"}]
["Ped, PDO",{"$f":"Input!B44","v":"INVALID"},{"$f":"Input!$D$54","v":"Please Input Both AADT's"},{"$f":"Input!$C$8","v":1},{"$f":"Input!$D$55","v":0},{"$error":"#VALUE!"}]
["Bike, FI",{"$f":"Input!B45","v":"INVALID"},{"$f":"Input!$D$54","v":"Please Input Both AADT's"},{"$f":"Input!$C$8","v":1},{"$f":"Input!$D$55","v":0},{"$error":"#VALUE!"}]
["Bike, PDO",{"$f":"Input!B46","v":"INVALID"},{"$f":"Input!$D$54","v":"Please Input Both AADT's"},{"$f":"Input!$C$8","v":1},{"$f":"Input!$D$55","v":0},{"$error":"#VALUE!"}]
["Total (FI)",{"$f":"SUM(B4,B6,B8,B10)","v":0},"-","-","-",{"$f":"SUM(F4,F6,F8,F10)","v":{"$error":"#VALUE!"}}]
["Total (PDO)",{"$f":"SUM(B5,B7,B9,B10)","v":0},"-","-","-",{"$f":"SUM(F5,F7,F9,F11)","v":{"$error":"#VALUE!"}}]
[]
[]
[]
["Step 2 – Expected Change in Safety Performance"]
["Alternative 1",null,null,null,null,"Estimated Lifetime of Alternative 1:",{"$f":"IF(Input!B68=\"\",\"\",Input!B68)","v":""}]
["Countermeasure 1:",{"$f":"IF(Input!B66=\"\",\"\",Input!B66)","v":""},null,"Countermeasure 2:",{"$f":"IF(Input!B67=\"\",\"\",Input!B67)","v":""}]
["Crash Type, Severity","Estimated Crashes during the Design Year ","CMF1","CMF2\n(If Applicable)","Resultant CMF","Estimated Crashes during the Design Year for Alternative 1 ","Reduced Crashes for Alternative 1"]
["MV, ALL",{"$f":"IF(Input!$D$61>=1,F4+F5,\"\")","v":""},{"$f":"Input!C76","v":1},{"$f":"IF(Input!B76=\"Not Applicable\",\"\",Input!E76)","v":""},{"$f":"IF(Input!C76=\"\",\"\",IF(Input!B76=\"Not Applicable\",Input!C76,IF(Input!B76=\"Multiplicative\",'Construction - do not delete'!B145,IF(Input!B76=\"Additive\",'Construction - do not delete'!D145,IF(Input!B76=\"Dominant Effect\",'Construction - do not delete'!E145,IF(Input!B76=\"Dominant Common Residuals\",'Construction - do not delete'!G145,\"Error\"))))))","v":1},{"$f":"IF(B21=\"\",\"\",B21*E21)","v":""},{"$f":"IF(B21=\"\",\"\",B21-F21)","v":""}]
["MV, FI",{"$f":"IF(Input!$D$61>=1,F4,\"\")","v":""},{"$f":"Input!C77","v":1},{"$f":"IF(Input!B77=\"Not Applicable\",\"\",Input!E77)","v":""},{"$f":"IF(Input!C77=\"\",\"\",IF(Input!B77=\"Not Applicable\",Input!C77,IF(Input!B77=\"Multiplicative\",'Construction - do not delete'!B146,IF(Input!B77=\"Additive\",'Construction - do not delete'!D146,IF(Input!B77=\"Dominant Effect\",'Construction - do not delete'!E146,IF(Input!B77=\"Dominant Common Residuals\",'Construction - do not delete'!G146,\"Error\"))))))","v":1},{"$f":"IF(B22=\"\",\"\",B22*E22)","v":""},"",{"$f":"IF(E22<0,\"Error Confirm CMF Values\",\"\")","v":""}]
["MV, PDO",{"$f":"IF(Input!$D$61>=1,F5,\"\")","v":""},null,null,null,{"$f":"IF(B23=\"\",\"\",(F21-F22))","v":""},"",{"$f":"IF(F23<0,\"Check CMF Input Values\",\"\")","v":""}]
["SV, ALL",{"$f":"IF(Input!$D$61>=1,F6+F7,\"\")","v":""},{"$f":"Input!C78","v":1},{"$f":"IF(Input!B78=\"Not Applicable\",\"\",Input!E78)","v":""},{"$f":"IF(Input!C78=\"\",\"\",IF(Input!B78=\"Not Applicable\",Input!C78,IF(Input!B78=\"Multiplicative\",'Construction - do not delete'!B147,IF(Input!B78=\"Additive\",'Construction - do not delete'!D147,IF(Input!B78=\"Dominant Effect\",'Construction - do not delete'!E147,IF(Input!B78=\"Dominant Common Residuals\",'Construction - do not delete'!G147,\"Error\"))))))","v":1},{"$f":"IF(B24=\"\",\"\",B24*E24)","v":""},""]
["SV, FI",{"$f":"IF(Input!$D$61>=1,F6,\"\")","v":""},{"$f":"Input!C79","v":1},{"$f":"IF(Input!B79=\"Not Applicable\",\"\",Input!E79)","v":""},{"$f":"IF(Input!C79=\"\",\"\",IF(Input!B79=\"Not Applicable\",Input!C79,IF(Input!B79=\"Multiplicative\",'Construction - do not delete'!B148,IF(Input!B79=\"Additive\",'Construction - do not delete'!D148,IF(Input!B79=\"Dominant Effect\",'Construction - do not delete'!E148,IF(Input!B79=\"Dominant Common Residuals\",'Construction - do not delete'!G148,\"Error\"))))))","v":1},{"$f":"IF(B25=\"\",\"\",B25*E25)","v":""},""]
["SV, PDO",{"$f":"IF(Input!$D$61>=1,F7,\"\")","v":""},null,null,null,{"$f":"IF(B26=\"\",\"\",F24-F25)","v":""},"",{"$f":"IF(F26<0,\"Check CMF Input Values\",\"\")","v":""}]
["Ped, ALL",{"$f":"IF(Input!$D$61>=1,F8+F9,\"\")","v":""},{"$f":"Input!C80","v":1},{"$f":"IF(Input!B80=\"Not Applicable\",\"\",Input!E80)","v":""},{"$f":"IF(Input!C80=\"\",\"\",IF(Input!B80=\"Not Applicable\",Input!C80,IF(Input!B80=\"Multiplicative\",'Construction - do not delete'!B149,IF(Input!B80=\"Additive\",'Construction - do not delete'!D149,IF(Input!B80=\"Dominant Effect\",'Construction - do not delete'!E149,IF(Input!B80=\"Dominant Common Residuals\",'Construction - do not delete'!G149,\"Error\"))))))","v":1},{"$f":"IF(B27=\"\",\"\",B27*E27)","v":""},{"$f":"IF(B27=\"\",\"\",B27-F27)","v":""}]
["Ped, FI",{"$f":"IF(Input!$D$61>=1,F8,\"\")","v":""},{"$f":"Input!C81","v":1},{"$f":"IF(Input!B81=\"Not Applicable\",\"\",Input!E81)","v":""},{"$f":"IF(Input!C81=\"\",\"\",IF(Input!B81=\"Not Applicable\",Input!C81,IF(Input!B81=\"Multiplicative\",'Construction - do not delete'!B150,IF(Input!B81=\"Additive\",'Construction - do not delete'!D150,IF(Input!B81=\"Dominant Effect\",'Construction - do not delete'!E150,IF(Input!B81=\"Dominant Common Residuals\",'Construction - do not delete'!G150,\"Error\"))))))","v":1},{"$f":"IF(B28=\"\",\"\",B28*E28)","v":""},{"$f":"IF(B28=\"\",\"\",B28-F28)","v":""}]
["Ped, PDO",{"$f":"IF(Input!$D$61>=1,F9,\"\")","v":""},null,null,null,{"$f":"IF(B29=\"\",\"\",F27-F28)","v":""},"",{"$f":"IF(F29<0,\"Check CMF Input Values\",\"\")","v":""}]
["Bike, ALL",{"$f":"IF(Input!$D$61>=1,F10+F11,\"\")","v":""},{"$f":"Input!C82","v":1},{"$f":"IF(Input!B82=\"Not Applicable\",\"\",Input!E82)","v":""},{"$f":"IF(Input!C82=\"\",\"\",IF(Input!B82=\"Not Applicable\",Input!C82,IF(Input!B82=\"Multiplicative\",'Construction - do not delete'!B151,IF(Input!B82=\"Additive\",'Construction - do not delete'!D151,IF(Input!B82=\"Dominant Effect\",'Construction - do not delete'!E151,IF(Input!B82=\"Dominant Common Residuals\",'Construction - do not delete'!G151,\"Error\"))))))","v":1},{"$f":"IF(B30=\"\",\"\",B30*E30)","v":""},{"$f":"IF(B30=\"\",\"\",B30-F30)","v":""}]
["Bike, FI",{"$f":"IF(Input!$D$61>=1,F10,\"\")","v":""},{"$f":"Input!C83","v":1},{"$f":"IF(Input!B83=\"Not Applicable\",\"\",Input!E83)","v":""},{"$f":"IF(Input!C83=\"\",\"\",IF(Input!B83=\"Not Applicable\",Input!C83,IF(Input!B83=\"Multiplicative\",'Construction - do not delete'!B152,IF(Input!B83=\"Additive\",'Construction - do not delete'!D152,IF(Input!B83=\"Dominant Effect\",'Construction - do not delete'!E152,IF(Input!B83=\"Dominant Common Residuals\",'Construction - do not delete'!G152,\"Error\"))))))","v":1},"",""]
["Bike, PDO",{"$f":"IF(Input!$D$61>=1,F11,\"\")","v":""},null,null,null,{"$f":"IF(B32=\"\",\"\",F30-F31)","v":""},{"$f":"IF(B32=\"\",\"\",B32-F32)","v":""},{"$f":"IF(F32<0,\"Check CMF Input Values\",\"\")","v":""}]
["Total, FI",{"$f":"IFERROR(B22+B25+B28+B31,\"\")","v":""},null,null,null,{"$f":"IFERROR(F22+F25+F28+F31,\"\")","v":""},{"$f":"IFERROR(G22+G25+G28+G31,\"\")","v":""}]
["Total, PDO",{"$f":"IFERROR(B23+B26+B29+B32,\"\")","v":""},null,null,null,{"$f":"IFERROR(F23+F26+F29+F32,\"\")","v":""},{"$f":"IFERROR(G23+G26+G29+G32,\"\")","v":""}]
[]
["Alternative 2",null,null,null,null,"Estimated Lifetime of Alternative 2:",{"$f":"IF(Input!C68=\"\",\"\",Input!C68)","v":""}]
["Countermeasure 1:",{"$f":"IF(Input!C66=\"\",\"\",Input!C66)","v":""},null,"Countermeasure 2:",{"$f":"IF(Input!C67=\"\",\"\",Input!C67)","v":""}]
["Crash Type, Severity","Estimated Crashes during the Design Year ","CMF1","CMF2\n(If Applicable)","Resultant CMF","Estimated Crashes during the Design Year for Alternative 2","Reduced Crashes for Alternative 2"]
["MV, ALL",{"$f":"IF(Input!$D$61>=2,F4+F5,\"\")","v":""},{"$f":"Input!C88","v":1},{"$f":"IF(Input!B88=\"Not Applicable\",\"\",Input!E88)","v":""},{"$f":"IF(Input!C88=\"\",\"\",IF(Input!B88=\"Not Applicable\",Input!C88,IF(Input!B88=\"Multiplicative\",'Construction - do not delete'!B157,IF(Input!B88=\"Additive\",'Construction - do not delete'!D157,IF(Input!B88=\"Dominant Effect\",'Construction - do not delete'!E157,IF(Input!B88=\"Dominant Common Residuals\",'Construction - do not delete'!G157,\"Error\"))))))","v":1},{"$f":"IF(B39=\"\",\"\",B39*E39)","v":""},{"$f":"IF(B39=\"\",\"\",B39-F39)","v":""}]
["MV, FI",{"$f":"IF(Input!$D$61>=2,F4,\"\")","v":""},{"$f":"Input!C89","v":1},{"$f":"IF(Input!B89=\"Not Applicable\",\"\",Input!E89)","v":""},{"$f":"IF(Input!C89=\"\",\"\",IF(Input!B89=\"Not Applicable\",Input!C89,IF(Input!B89=\"Multiplicative\",'Construction - do not delete'!B158,IF(Input!B89=\"Additive\",'Construction - do not delete'!D158,IF(Input!B89=\"Dominant Effect\",'Construction - do not delete'!E158,IF(Input!B89=\"Dominant Common Residuals\",'Construction - do not delete'!G158,\"Error\"))))))","v":1},{"$f":"IF(B40=\"\",\"\",B40*E40)","v":""},{"$f":"IF(B40=\"\",\"\",B40-F40)","v":""}]
["MV, PDO",{"$f":"IF(Input!$D$61>=2,F5,\"\")","v":""},null,null,null,{"$f":"IF(B41=\"\",\"\",F39-F40)","v":""},{"$f":"IF(B41=\"\",\"\",B41-F41)","v":""},{"$f":"IF(F41<0,\"Check CMF Input Values\",\"\")","v":""}]
["SV, ALL",{"$f":"IF(Input!$D$61>=2,F6+F7,\"\")","v":""},{"$f":"Input!C90","v":1},{"$f":"IF(Input!B90=\"Not Applicable\",\"\",Input!E90)","v":""},{"$f":"IF(Input!C90=\"\",\"\",IF(Input!B90=\"Not Applicable\",Input!C90,IF(Input!B90=\"Multiplicative\",'Construction - do not delete'!B159,IF(Input!B90=\"Additive\",'Construction - do not delete'!D159,IF(Input!B90=\"Dominant Effect\",'Construction - do not delete'!E159,IF(Input!B90=\"Dominant Common Residuals\",'Construction - do not delete'!G159,\"Error\"))))))","v":1},{"$f":"IF(B42=\"\",\"\",B42*E42)","v":""},{"$f":"IF(B42=\"\",\"\",B42-F42)","v":""}]
["SV, FI",{"$f":"IF(Input!$D$61>=2,F6,\"\")","v":""},{"$f":"Input!C91","v":1},{"$f":"IF(Input!B91=\"Not Applicable\",\"\",Input!E91)","v":""},{"$f":"IF(Input!C91=\"\",\"\",IF(Input!B91=\"Not Applicable\",Input!C91,IF(Input!B91=\"Multiplicative\",'Construction - do not delete'!B160,IF(Input!B91=\"Additive\",'Construction - do not delete'!D160,IF(Input!B91=\"Dominant Effect\",'Construction - do not delete'!E160,IF(Input!B91=\"Dominant Common Residuals\",'Construction - do not delete'!G160,\"Error\"))))))","v":1},{"$f":"IF(B43=\"\",\"\",B43*E43)","v":""},{"$f":"IF(B43=\"\",\"\",B43-F43)","v":""}]
["SV, PDO",{"$f":"IF(Input!$D$61>=2,F7,\"\")","v":""},null,null,null,{"$f":"IF(B44=\"\",\"\",F42-F43)","v":""},"",{"$f":"IF(F44<0,\"Check CMF Input Values\",\"\")","v":""}]
["Ped, ALL",{"$f":"IF(Input!$D$61>=2,F8+F9,\"\")","v":""},{"$f":"Input!C92","v":1},{"$f":"IF(Input!B92=\"Not Applicable\",\"\",Input!E92)","v":""},{"$f":"IF(Input!C92=\"\",\"\",IF(Input!B92=\"Not Applicable\",Input!C92,IF(Input!B92=\"Multiplicative\",'Construction - do not delete'!B161,IF(Input!B92=\"Additive\",'Construction - do not delete'!D161,IF(Input!B92=\"Dominant Effect\",'Construction - do not delete'!E161,IF(Input!B92=\"Dominant Common Residuals\",'Construction - do not delete'!G161,\"Error\"))))))","v":1},{"$f":"IF(B45=\"\",\"\",B45*E45)","v":""},{"$f":"IF(B45=\"\",\"\",B45-F45)","v":""}]
["Ped, FI",{"$f":"IF(Input!$D$61>=2,F8,\"\")","v":""},{"$f":"Input!C93","v":1},{"$f":"IF(Input!B93=\"Not Applicable\",\"\",Input!E93)","v":""},{"$f":"IF(Input!C93=\"\",\"\",IF(Input!B93=\"Not Applicable\",Input!C93,IF(Input!B93=\"Multiplicative\",'Construction - do not delete'!B162,IF(Input!B93=\"Additive\",'Construction - do not delete'!D162,IF(Input!B93=\"Dominant Effect\",'Construction - do not delete'!E162,IF(Input!B93=\"Dominant Common Residuals\",'Construction - do not delete'!G162,\"Error\"))))))","v":1},{"$f":"IF(B46=\"\",\"\",B46*E46)","v":""},""]
["Ped, PDO",{"$f":"IF(Input!$D$61>=2,F9,\"\")","v":""},null,null,null,{"$f":"IF(B47=\"\",\"\",F45-F46)","v":""},"",{"$f":"IF(F47<0,\"Check CMF Input Values\",\"\")","v":""}]
["Bike, ALL",{"$f":"IF(Input!$D$61>=2,F10+F11,\"\")","v":""},{"$f":"Input!C94","v":1},{"$f":"IF(Input!B94=\"Not Applicable\",\"\",Input!E94)","v":""},{"$f":"IF(Input!C94=\"\",\"\",IF(Input!B94=\"Not Applicable\",Input!C94,IF(Input!B94=\"Multiplicative\",'Construction - do not delete'!B163,IF(Input!B94=\"Additive\",'Construction - do not delete'!D163,IF(Input!B94=\"Dominant Effect\",'Construction - do not delete'!E163,IF(Input!B94=\"Dominant Common Residuals\",'Construction - do not delete'!G163,\"Error\"))))))","v":1},{"$f":"IF(B48=\"\",\"\",B48*E48)","v":""},{"$f":"IF(B48=\"\",\"\",B48-F48)","v":""}]
["Bike, FI",{"$f":"IF(Input!$D$61>=2,F10,\"\")","v":""},{"$f":"Input!C95","v":1},{"$f":"IF(Input!B95=\"Not Applicable\",\"\",Input!E95)","v":""},{"$f":"IF(Input!C95=\"\",\"\",IF(Input!B95=\"Not Applicable\",Input!C95,IF(Input!B95=\"Multiplicative\",'Construction - do not delete'!B164,IF(Input!B95=\"Additive\",'Construction - do not delete'!D164,IF(Input!B95=\"Dominant Effect\",'Construction - do not delete'!E164,IF(Input!B95=\"Dominant Common Residuals\",'Construction - do not delete'!G164,\"Error\"))))))","v":1},"",""]
["Bike, PDO",{"$f":"IF(Input!$D$61>=2,F11,\"\")","v":""},null,null,null,{"$f":"IF(B50=\"\",\"\",F48-F49)","v":""},"",{"$f":"IF(F50<0,\"Check CMF Input Values\",\"\")","v":""}]
["Total, FI",{"$f":"IFERROR(B40+B43+B46+B49,\"\")","v":""},null,null,null,{"$f":"IFERROR(F40+F43+F46+F49,\"\")","v":""},{"$f":"IFERROR(G40+G43+G46+G49,\"\")","v":""}]
["Total, PDO",{"$f":"IFERROR(B41+B44+B47+B50,\"\")","v":""},null,null,null,{"$f":"IFERROR(F41+F44+F47+F50,\"\")","v":""},{"$f":"IFERROR(G41+G44+G47+G50,\"\")","v":""}]
[]
["Alternative 3",null,null,null,null,"Estimated Lifetime of Alternative 3:",{"$f":"IF(Input!D68=\"\",\"\",Input!D68)","v":""}]
["Countermeasure 1:",{"$f":"IF(Input!D66=\"\",\"\",Input!D66)","v":""},null,"Countermeasure 2:",{"$f":"IF(Input!D67=\"\",\"\",Input!D67)","v":""}]
["Crash Type, Severity","Estimated Crashes during the Design Year ","CMF1","CMF2\n(If Applicable)","Resultant CMF","Estimated Crashes during the Design Year for Alternative 3","Reduced Crashes for Alternative 3"]
["MV, ALL",{"$f":"IF(Input!$D$61>=3,F4+F5,\"\")","v":""},{"$f":"Input!C100","v":1},{"$f":"IF(Input!B100=\"Not Applicable\",\"\",Input!E100)","v":""},{"$f":"IF(Input!C100=\"\",\"\",IF(Input!B100=\"Not Applicable\",Input!C100,IF(Input!B100=\"Multiplicative\",'Construction - do not delete'!B169,IF(Input!B99=\"Additive\",'Construction - do not delete'!D169,IF(Input!B100=\"Dominant Effect\",'Construction - do not delete'!E169,IF(Input!B100=\"Dominant Common Residuals\",'Construction - do not delete'!G169,\"Error\"))))))","v":1},{"$f":"IF(B57=\"\",\"\",B57*E57)","v":""},{"$f":"IF(B57=\"\",\"\",B57-F57)","v":""}]
["MV, FI",{"$f":"IF(Input!$D$61>=3,F4,\"\")","v":""},{"$f":"Input!C101","v":1},{"$f":"IF(Input!B101=\"Not Applicable\",\"\",Input!E101)","v":""},{"$f":"IF(Input!C101=\"\",\"\",IF(Input!B101=\"Not Applicable\",Input!C101,IF(Input!B101=\"Multiplicative\",'Construction - do not delete'!B170,IF(Input!B100=\"Additive\",'Construction - do not delete'!D170,IF(Input!B101=\"Dominant Effect\",'Construction - do not delete'!E170,IF(Input!B101=\"Dominant Common Residuals\",'Construction - do not delete'!G170,\"Error\"))))))","v":1},{"$f":"IF(B58=\"\",\"\",B58*E58)","v":""},{"$f":"IF(B58=\"\",\"\",B58-F58)","v":""}]
["MV, PDO",{"$f":"IF(Input!$D$61>=3,F5,\"\")","v":""},null,null,null,{"$f":"IF(B59=\"\",\"\",F57-F58)","v":""},{"$f":"IF(B59=\"\",\"\",B59-F59)","v":""},{"$f":"IF(F59<0,\"Check CMF Input Values\",\"\")","v":""}]
["SV, ALL",{"$f":"IF(Input!$D$61>=3,F6+F7,\"\")","v":""},{"$f":"Input!C102","v":1},{"$f":"IF(Input!B102=\"Not Applicable\",\"\",Input!E102)","v":""},{"$f":"IF(Input!C102=\"\",\"\",IF(Input!B102=\"Not Applicable\",Input!C102,IF(Input!B102=\"Multiplicative\",'Construction - do not delete'!B171,IF(Input!B102=\"Additive\",'Construction - do not delete'!D171,IF(Input!B102=\"Dominant Effect\",'Construction - do not delete'!E171,IF(Input!B102=\"Dominant Common Residuals\",'Construction - do not delete'!G171,\"Error\"))))))","v":1},{"$f":"IF(B60=\"\",\"\",B60*E60)","v":""},{"$f":"IF(B60=\"\",\"\",B60-F60)","v":""}]
["SV, FI",{"$f":"IF(Input!$D$61>=3,F6,\"\")","v":""},{"$f":"Input!C103","v":1},{"$f":"IF(Input!B103=\"Not Applicable\",\"\",Input!E103)","v":""},{"$f":"IF(Input!C103=\"\",\"\",IF(Input!B103=\"Not Applicable\",Input!C103,IF(Input!B103=\"Multiplicative\",'Construction - do not delete'!B172,IF(Input!B103=\"Additive\",'Construction - do not delete'!D172,IF(Input!B103=\"Dominant Effect\",'Construction - do not delete'!E172,IF(Input!B103=\"Dominant Common Residuals\",'Construction - do not delete'!G172,\"Error\"))))))","v":1},{"$f":"IF(B61=\"\",\"\",B61*E61)","v":""},""]
["SV, PDO",{"$f":"IF(Input!$D$61>=3,F7,\"\")","v":""},null,null,null,{"$f":"IF(B62=\"\",\"\",F60-F61)","v":""},"",{"$f":"IF(F62<0,\"Check CMF Input Values\",\"\")","v":""}]
["Ped, ALL",{"$f":"IF(Input!$D$61>=3,F8+F9,\"\")","v":""},{"$f":"Input!C104","v":1},{"$f":"IF(Input!B104=\"Not Applicable\",\"\",Input!E104)","v":""},{"$f":"IF(Input!C104=\"\",\"\",IF(Input!B104=\"Not Applicable\",Input!C104,IF(Input!B104=\"Multiplicative\",'Construction - do not delete'!B173,IF(Input!B104=\"Additive\",'Construction - do not delete'!D173,IF(Input!B104=\"Dominant Effect\",'Construction - do not delete'!E173,IF(Input!B104=\"Dominant Common Residuals\",'Construction - do not delete'!G173,\"Error\"))))))","v":1},{"$f":"IF(B63=\"\",\"\",B63*E63)","v":""},{"$f":"IF(B63=\"\",\"\",B63-F63)","v":""}]
["Ped, FI",{"$f":"IF(Input!$D$61>=3,F8,\"\")","v":""},{"$f":"Input!C105","v":1},{"$f":"IF(Input!B105=\"Not Applicable\",\"\",Input!E105)","v":""},{"$f":"IF(Input!C105=\"\",\"\",IF(Input!B105=\"Not Applicable\",Input!C105,IF(Input!B105=\"Multiplicative\",'Construction - do not delete'!B174,IF(Input!B105=\"Additive\",'Construction - do not delete'!D174,IF(Input!B105=\"Dominant Effect\",'Construction - do not delete'!E174,IF(Input!B105=\"Dominant Common Residuals\",'Construction - do not delete'!G174,\"Error\"))))))","v":1},"",""]
["Ped, PDO",{"$f":"IF(Input!$D$61>=3,F9,\"\")","v":""},null,null,null,{"$f":"IF(B65=\"\",\"\",F63-F64)","v":""},"",{"$f":"IF(F65<0,\"Check CMF Input Values\",\"\")","v":""}]
["Bike, ALL",{"$f":"IF(Input!$D$61>=3,F10+F11,\"\")","v":""},{"$f":"Input!C106","v":1},{"$f":"IF(Input!B106=\"Not Applicable\",\"\",Input!E106)","v":""},{"$f":"IF(Input!C106=\"\",\"\",IF(Input!B106=\"Not Applicable\",Input!C106,IF(Input!B106=\"Multiplicative\",'Construction - do not delete'!B175,IF(Input!B106=\"Additive\",'Construction - do not delete'!D175,IF(Input!B106=\"Dominant Effect\",'Construction - do not delete'!E175,IF(Input!B106=\"Dominant Common Residuals\",'Construction - do not delete'!G175,\"Error\"))))))","v":1},{"$f":"IF(B66=\"\",\"\",B66*E66)","v":""},{"$f":"IF(B66=\"\",\"\",B66-F66)","v":""}]
["Bike, FI",{"$f":"IF(Input!$D$61>=3,F10,\"\")","v":""},{"$f":"Input!C107","v":1},{"$f":"IF(Input!B107=\"Not Applicable\",\"\",Input!E107)","v":""},{"$f":"IF(Input!C107=\"\",\"\",IF(Input!B107=\"Not Applicable\",Input!C107,IF(Input!B107=\"Multiplicative\",'Construction - do not delete'!B176,IF(Input!B107=\"Additive\",'Construction - do not delete'!D176,IF(Input!B107=\"Dominant Effect\",'Construction - do not delete'!E176,IF(Input!B107=\"Dominant Common Residuals\",'Construction - do not delete'!G176,\"Error\"))))))","v":1},"",""]
["Bike, PDO",{"$f":"IF(Input!$D$61>=3,F11,\"\")","v":""},null,null,null,{"$f":"IF(B68=\"\",\"\",F66-F67)","v":""},"",{"$f":"IF(F68<0,\"Check CMF Input Values\",\"\")","v":""}]
["Total, FI",{"$f":"IFERROR(B58+B61+B64+B67,\"\")","v":""},null,null,null,{"$f":"IFERROR(F58+F61+F64+F67,\"\")","v":""},{"$f":"IFERROR(G58+G61+G64+G67,\"\")","v":""}]
["Total, PDO",{"$f":"IFERROR(B59+B62+B65+B68,\"\")","v":""},null,null,null,{"$f":"IFERROR(F59+F62+F65+F68,\"\")","v":""},{"$f":"IFERROR(G59+G62+G65+G68,\"\")","v":""}]
[]
["Alternative 4",null,null,null,null,"Estimated Lifetime of Alternative 4:",{"$f":"IF(Input!E68=\"\",\"\",Input!E68)","v":""}]
["Countermeasure 1:",{"$f":"IF(Input!E66=\"\",\"\",Input!E66)","v":""},null,"Countermeasure 2:",{"$f":"IF(Input!E67=\"\",\"\",Input!E67)","v":""}]
["Crash Type, Severity","Estimated Crashes during the Design Year ","CMF1","CMF2\n(If Applicable)","Resultant CMF","Estimated Crashes during the Design Year for Alternative 4","Reduced Crashes for Alternative 4"]
["MV, ALL",{"$f":"IF(Input!$D$61=4,F4+F5,\"\")","v":""},{"$f":"Input!C112","v":1},{"$f":"IF(Input!B112=\"Not Applicable\",\"\",Input!E112)","v":""},{"$f":"IF(Input!C112=\"\",\"\",IF(Input!B112=\"Not Applicable\",Input!C112,IF(Input!B112=\"Multiplicative\",'Construction - do not delete'!B181,IF(Input!B112=\"Additive\",'Construction - do not delete'!D181,IF(Input!B112=\"Dominant Effect\",'Construction - do not delete'!E181,IF(Input!B112=\"Dominant Common Residuals\",'Construction - do not delete'!G181,\"Error\"))))))","v":1},{"$f":"IF(B75=\"\",\"\",B75*E75)","v":""},{"$f":"IF(B75=\"\",\"\",B75-F75)","v":""}]
["MV, FI",{"$f":"IF(Input!$D$61=4,F4,\"\")","v":""},{"$f":"Input!C113","v":1},{"$f":"IF(Input!B113=\"Not Applicable\",\"\",Input!E113)","v":""},{"$f":"IF(Input!C113=\"\",\"\",IF(Input!B113=\"Not Applicable\",Input!C113,IF(Input!B113=\"Multiplicative\",'Construction - do not delete'!B182,IF(Input!B113=\"Additive\",'Construction - do not delete'!D182,IF(Input!B113=\"Dominant Effect\",'Construction - do not delete'!E182,IF(Input!B113=\"Dominant Common Residuals\",'Construction - do not delete'!G182,\"Error\"))))))","v":1},{"$f":"IF(B76=\"\",\"\",B76*E76)","v":""},{"$f":"IF(B76=\"\",\"\",B76-F76)","v":""}]
["MV, PDO",{"$f":"IF(Input!$D$61=4,F5,\"\")","v":""},null,null,null,{"$f":"IF(B77=\"\",\"\",F75-F76)","v":""},{"$f":"IF(B77=\"\",\"\",B77-F77)","v":""},{"$f":"IF(F77<0,\"Check CMF Input Values\",\"\")","v":""}]
["SV, ALL",{"$f":"IF(Input!$D$61=4,F6+F7,\"\")","v":""},{"$f":"Input!C114","v":1},{"$f":"IF(Input!B114=\"Not Applicable\",\"\",Input!E114)","v":""},{"$f":"IF(Input!C114=\"\",\"\",IF(Input!B114=\"Not Applicable\",Input!C114,IF(Input!B114=\"Multiplicative\",'Construction - do not delete'!B183,IF(Input!B114=\"Additive\",'Construction - do not delete'!D183,IF(Input!B114=\"Dominant Effect\",'Construction - do not delete'!E183,IF(Input!B114=\"Dominant Common Residuals\",'Construction - do not delete'!G183,\"Error\"))))))","v":1},{"$f":"IF(B78=\"\",\"\",B78*E78)","v":""},{"$f":"IF(B78=\"\",\"\",B78-F78)","v":""}]
["SV, FI",{"$f":"IF(Input!$D$61=4,F6,\"\")","v":""},{"$f":"Input!C115","v":1},{"$f":"IF(Input!B115=\"Not Applicable\",\"\",Input!E115)","v":""},{"$f":"IF(Input!C115=\"\",\"\",IF(Input!B115=\"Not Applicable\",Input!C115,IF(Input!B115=\"Multiplicative\",'Construction - do not delete'!B184,IF(Input!B115=\"Additive\",'Construction - do not delete'!D184,IF(Input!B115=\"Dominant Effect\",'Construction - do not delete'!E184,IF(Input!B115=\"Dominant Common Residuals\",'Construction - do not delete'!G184,\"Error\"))))))","v":1},{"$f":"IF(B79=\"\",\"\",B79*E79)","v":""},""]
["SV, PDO",{"$f":"IF(Input!$D$61=4,F7,\"\")","v":""},null,null,null,{"$f":"IF(B80=\"\",\"\",F78-F79)","v":""},"",{"$f":"IF(F80<0,\"Check CMF Input Values\",\"\")","v":""}]
["Ped, ALL",{"$f":"IF(Input!$D$61=4,F8+F9,\"\")","v":""},{"$f":"Input!C116","v":1},{"$f":"IF(Input!B116=\"Not Applicable\",\"\",Input!E116)","v":""},{"$f":"IF(Input!C116=\"\",\"\",IF(Input!B116=\"Not Applicable\",Input!C116,IF(Input!B116=\"Multiplicative\",'Construction - do not delete'!B185,IF(Input!B116=\"Additive\",'Construction - do not delete'!D185,IF(Input!B116=\"Dominant Effect\",'Construction - do not delete'!E185,IF(Input!B116=\"Dominant Common Residuals\",'Construction - do not delete'!G185,\"Error\"))))))","v":1},{"$f":"IF(B81=\"\",\"\",B81*E81)","v":""},{"$f":"IF(B81=\"\",\"\",B81-F81)","v":""}]
["Ped, FI",{"$f":"IF(Input!$D$61=4,F8,\"\")","v":""},{"$f":"Input!C117","v":1},{"$f":"IF(Input!B117=\"Not Applicable\",\"\",Input!E117)","v":""},{"$f":"IF(Input!C117=\"\",\"\",IF(Input!B117=\"Not Applicable\",Input!C117,IF(Input!B117=\"Multiplicative\",'Construction - do not delete'!B186,IF(Input!B117=\"Additive\",'Construction - do not delete'!D186,IF(Input!B117=\"Dominant Effect\",'Construction - do not delete'!E186,IF(Input!B117=\"Dominant Common Residuals\",'Construction - do not delete'!G186,\"Error\"))))))","v":1},"",""]
["Ped, PDO",{"$f":"IF(Input!$D$61=4,F9,\"\")","v":""},null,null,null,{"$f":"IF(B83=\"\",\"\",F81-F82)","v":""},"",{"$f":"IF(F83<0,\"Check CMF Input Values\",\"\")","v":""}]
["Bike, ALL",{"$f":"IF(Input!$D$61=4,F10+F11,\"\")","v":""},{"$f":"Input!C118","v":1},{"$f":"IF(Input!B118=\"Not Applicable\",\"\",Input!E118)","v":""},{"$f":"IF(Input!C118=\"\",\"\",IF(Input!B118=\"Not Applicable\",Input!C118,IF(Input!B118=\"Multiplicative\",'Construction - do not delete'!B187,IF(Input!B118=\"Additive\",'Construction - do not delete'!D187,IF(Input!B118=\"Dominant Effect\",'Construction - do not delete'!E187,IF(Input!B118=\"Dominant Common Residuals\",'Construction - do not delete'!G187,\"Error\"))))))","v":1},{"$f":"IF(B84=\"\",\"\",B84*E84)","v":""},{"$f":"IF(B84=\"\",\"\",B84-F84)","v":""}]
["Bike, FI",{"$f":"IF(Input!$D$61=4,F10,\"\")","v":""},{"$f":"Input!C119","v":1},{"$f":"IF(Input!B119=\"Not Applicable\",\"\",Input!E119)","v":""},{"$f":"IF(Input!C119=\"\",\"\",IF(Input!B119=\"Not Applicable\",Input!C119,IF(Input!B119=\"Multiplicative\",'Construction - do not delete'!B188,IF(Input!B119=\"Additive\",'Construction - do not delete'!D188,IF(Input!B119=\"Dominant Effect\",'Construction - do not delete'!E188,IF(Input!B119=\"Dominant Common Residuals\",'Construction - do not delete'!G188,\"Error\"))))))","v":1},"",""]
["Bike, PDO",{"$f":"IF(Input!$D$61=4,F11,\"\")","v":""},null,null,null,{"$f":"IF(B86=\"\",\"\",F84-F85)","v":""},"",{"$f":"IF(F86<0,\"Check CMF Input Values\",\"\")","v":""}]
["Total, FI",{"$f":"IFERROR(B76+B79+B82+B85,\"\")","v":""},null,null,null,{"$f":"IFERROR(F76+F79+F82+F85,\"\")","v":""},{"$f":"IFERROR(G76+G79+G82+G85,\"\")","v":""}]
["Total, PDO",{"$f":"IFERROR(B77+B80+B83+B86,\"\")","v":""},null,null,null,{"$f":"IFERROR(F77+F80+F83+F86,\"\")","v":""},{"$f":"IFERROR(G77+G80+G83+G86,\"\")","v":""}]
[]
[]
[]
["Step 3 – Economic Analysis"]
[null,{"$f":"IF(Input!B66=\"\",\"\",Input!B66)","v":""},null,{"$f":"IF(Input!C66=\"\",\"\",Input!C66)","v":""},null,{"$f":"IF(Input!D66=\"\",\"\",Input!D66)","v":""},null,{"$f":"IF(Input!E66=\"\",\"\",Input!E66)","v":""}]
[]
[null,{"$f":"IF(B93=\"\",\"\",\"Reduction\")","v":""},{"$f":"IF(B93=\"\",\"\",\"Benefits\")","v":""},{"$f":"IF(D93=\"\",\"\",\"Reduction\")","v":""},{"$f":"IF(D93=\"\",\"\",\"Benefits\")","v":""},{"$f":"IF(F93=\"\",\"\",\"Reduction\")","v":""},{"$f":"IF(F93=\"\",\"\",\"Benefits\")","v":""},{"$f":"IF(H93=\"\",\"\",\"Reduction\")","v":""},{"$f":"IF(H93=\"\",\"\",\"Benefits\")","v":""}]
["Total, FI",{"$f":"IF(G33=\"\",\"\",G33)","v":""},{"$f":"IF(B96=\"\",\"\",INDEX(Table58[Average FI Crash Cost],MATCH(Input!C60,'Construction - do not delete'!$H$83:$H$96,0))*B96)","v":""},{"$f":"IF(G51=\"\",\"\",G51)","v":""},{"$f":"IF(D96=\"\",\"\",INDEX(Table58[Average FI Crash Cost],MATCH(Input!C60,'Construction - do not delete'!$H$84:$H$96,0))*D96)","v":""},{"$f":"IF(G69=\"\",\"\",G69)","v":""},{"$f":"IF(F96=\"\",\"\",INDEX(Table58[Average FI Crash Cost],MATCH(Input!C60,'Construction - do not delete'!$H$84:$H$96,0))*F96)","v":""},{"$f":"IF(G87=\"\",\"\",G87)","v":""},{"$f":"IF(H96=\"\",\"\",INDEX(Table58[Average FI Crash Cost],MATCH(Input!E60,'Construction - do not delete'!$H$84:$H$96,0))*H96)","v":""}]
["Total, PDO",{"$f":"IF(G34=\"\",\"\",G34)","v":""},{"$f":"IF(B97=\"\",\"\",INDEX(Table58[Average PDO Crash Cost],MATCH(Input!C60,'Construction - do not delete'!$H$84:$H$96,0))*B97)","v":""},{"$f":"IF(G52=\"\",\"\",G52)","v":""},{"$f":"IF(D97=\"\",\"\",INDEX(Table58[Average PDO Crash Cost],MATCH(Input!C60,'Construction - do not delete'!$H$84:$H$96,0))*D97)","v":""},{"$f":"IF(G70=\"\",\"\",G70)","v":""},{"$f":"IF(F97=\"\",\"\",INDEX(Table58[Average PDO Crash Cost],MATCH(Input!C60,'Construction - do not delete'!$H$84:$H$96,0))*F97)","v":""},{"$f":"IF(G88=\"\",\"\",G88)","v":""},{"$f":"IF(H97=\"\",\"\",INDEX(Table58[Average PDO Crash Cost],MATCH(Input!E60,'Construction - do not delete'!$H$84:$H$96,0))*H97)","v":""}]
["Total, All",{"$f":"IF(SUM(B96:B97)=0,\"\",SUM(B96:B97))","v":""},{"$f":"IFERROR(C96+C97,\"\")","v":""},{"$f":"IF(SUM(D96:D97)=0,\"\",SUM(D96:D97))","v":""},{"$f":"IFERROR(E96+E97,\"\")","v":""},{"$f":"IF(SUM(F96:F97)=0,\"\",SUM(F96:F97))","v":""},{"$f":"IFERROR(G96+G97,\"\")","v":""},{"$f":"IF(SUM(H96:H97)=0,\"\",SUM(H96:H97))","v":""},{"$f":"IFERROR(I96+I97,\"\")","v":""}]
[]
[null,{"$f":"IF(Input!B66=\"\",\"\",Input!B66)","v":""},{"$f":"IF(Input!C66=\"\",\"\",Input!C66)","v":""},{"$f":"IF(Input!D66=\"\",\"\",Input!D66)","v":""},{"$f":"IF(Input!E66=\"\",\"\",Input!E66)","v":""}]
["Design Year Benefit",{"$f":"C98","v":""},{"$f":"E98","v":""},{"$f":"G98","v":""},{"$f":"I98","v":""}]
["Present Value Conversion Factor (from Equation 13)",{"$f":"IF(Input!$D$61>=1,(((1+Input!$B$61)^Input!B68)-1)/(Input!$B$61*((1+Input!$B$61)^Input!B68)),\"\")","v":""},{"$f":"IF(Input!$D$61>=2,(((1+Input!$B$61)^Input!C68)-1)/(Input!$B$61*((1+Input!$B$61)^Input!C68)),\"\")","v":""},{"$f":"IF(Input!$D$61>=3,(((1+Input!$B$61)^Input!D68)-1)/(Input!$B$61*((1+Input!$B$61)^Input!D68)),\"\")","v":""},{"$f":"IF(Input!$D$61>=4,(((1+Input!$B$61)^Input!E68)-1)/(Input!$B$61*((1+Input!$B$61)^Input!E68)),\"\")","v":""}]
["Lifetime Present Value",{"$f":"IF(B102=\"\",\"\",B101*B102)","v":""},{"$f":"IF(C102=\"\",\"\",C101*C102)","v":""},{"$f":"IF(D102=\"\",\"\",D101*D102)","v":""},{"$f":"IF(E102=\"\",\"\",E101*E102)","v":""}]
["Cost",{"$f":"Input!B69","v":0},{"$f":"IF(Input!D61<2,\"\",Input!C69)","v":""},{"$f":"IF(Input!D61<3,\"\",Input!D69)","v":""},{"$f":"IF(Input!D61<4,\"\",Input!E69)","v":""}]
["Benefit-Cost Ratio",{"$f":"IF(B102=\"\",\"\",B103/B104)","v":""},{"$f":"IF(C102=\"\",\"\",C103/C104)","v":""},{"$f":"IF(D102=\"\",\"\",D103/D104)","v":""},{"$f":"IF(E102=\"\",\"\",E103/E104)","v":""}]

{"sheet":"Intersection Tables","index":5,"n_rows":137,"n_cols":31,"rows_kept":137,"cut":false,"hidden":true,"merged":[[92,1,92,2],[90,5,90,6],[91,5,91,6],[130,19,132,19],[130,20,132,20],[130,21,132,21],[130,22,132,22],[130,23,132,23],[130,24,132,24],[128,15,129,25],[130,15,132,15],[130,16,132,16],[130,17,132,17],[118,21,120,23],[130,1,130,5],[93,1,93,2],[93,3,93,4],[93,5,93,6],[115,1,116,5],[130,18,132,18],[118,18,120,20],[120,11,120,12],[115,15,116,29],[109,0,109,14],[68,24,69,28],[70,24,71,27],[70,28,71,28],[72,24,72,27],[54,24,54,27],[55,24,55,27],[59,24,60,28],[73,24,73,27],[74,24,74,27],[61,24,62,27],[61,28,62,28],[63,24,63,27],[64,24,64,27],[117,11,119,12],[117,28,117,29],[125,1,125,5],[120,1,120,5],[130,25,132,25],[117,26,117,27],[118,26,120,26],[118,27,120,27],[117,9,119,9],[117,10,119,10],[117,1,119,1],[117,5,119,5],[40,3,40,10],[49,3,49,10],[48,1,48,10],[50,7,50,8],[50,9,50,10],[41,9,41,10],[45,1,45,2],[46,1,46,2],[43,1,43,2],[49,1,51,2],[50,5,50,6],[63,3,63,10],[31,8,31,12],[39,1,40,2],[62,1,63,2],[24,1,24,5],[123,11,123,12],[121,11,121,12],[55,1,55,2],[88,3,89,4],[64,7,64,8],[64,9,64,10],[66,1,66,2],[67,1,67,2],[68,1,68,2],[91,1,91,2],[92,3,92,4],[80,1,80,2],[87,1,88,2],[92,5,92,6],[90,3,90,4],[91,3,91,4],[89,1,89,2],[90,1,90,2],[39,3,39,10],[115,8,116,12],[117,8,119,8],[14,8,14,12],[9,8,10,12],[11,8,13,8],[56,1,56,2],[52,1,52,2],[62,3,62,10],[54,1,54,2],[41,1,42,2],[47,1,47,2],[11,12,13,12],[37,1,38,10],[30,8,30,12],[51,11,51,12],[41,3,41,4],[41,5,41,6],[41,7,41,8],[44,1,44,2],[19,8,19,12],[24,8,24,12],[41,11,41,12],[53,1,53,2],[64,1,65,2],[87,3,87,6],[19,1,19,5],[33,25,33,26],[35,24,35,30],[28,30,29,30],[43,30,44,30],[41,24,42,27],[122,11,122,12],[118,24,120,25],[118,15,120,15],[118,16,120,16],[118,17,120,17],[118,28,120,28],[118,29,120,29],[43,24,43,27],[44,24,44,27],[45,24,45,27],[39,24,40,28],[41,28,42,28],[34,24,34,30],[58,24,58,27],[49,24,50,28],[51,24,52,27],[53,24,53,27],[51,28,52,28],[32,25,32,26],[0,0,0,13],[88,5,89,6],[71,1,71,2],[72,1,72,10],[70,1,70,2],[73,3,73,10],[69,1,69,2],[74,3,74,4],[74,5,74,6],[81,1,81,2],[85,1,86,6],[74,9,74,10],[76,1,76,2],[77,1,77,2],[78,1,78,2],[79,1,79,2],[64,3,64,4],[64,5,64,6],[50,3,50,4],[60,1,61,10],[74,7,74,8],[73,1,75,2],[3,0,4,13],[11,21,13,21],[14,15,14,21],[13,27,14,27],[13,28,14,28],[13,29,14,29],[9,1,10,5],[11,1,13,1],[11,5,13,5],[14,1,14,5],[11,15,13,15],[11,24,14,24],[11,25,14,26],[9,24,10,30],[13,30,14,30],[9,15,10,21],[11,27,12,30],[0,30,0,43],[1,25,1,27],[1,31,1,33],[1,37,1,38],[31,25,31,26],[15,25,15,26],[16,25,16,26],[17,25,17,26],[18,25,18,26],[26,27,27,30],[28,27,29,27],[26,25,29,26],[19,24,19,30],[20,24,20,30],[26,24,29,24],[30,25,30,26],[28,28,29,28],[28,29,29,29],[24,24,25,30],[0,15,0,28],[1,16,1,18],[1,22,1,23]]}
["Legend"]
[]
[]
["This sheet contains all the relevant tables required for prediction of crashes at urban and suburban intersections. Please do not delete this worksheet. "]
[]
[]
[]
[null,"Tables Affiliated with SPF Computation:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Tables Affiliated with Crash Modification Factors:"]
[]
[null,"Table 12-10: SPF Coefficients for Multiple-Vehicle Collisions at Intersections",null,null,null,null,null,null,"Table 12-12: SPF Coefficients for Single-Vehicle Crashes at Intersections",null,null,null,null,null,null,"Table 12-14: SPF for Vehicle-Pedestrian Collisions at Signalized Intersections",null,null,null,null,null,null,null,null,"Table 12-24: Crash Modification Factor (CMF1i) for Installation of Left-Turn Lanes on Intersection Approaches"]
[]
[null,"Intersection type","Coefficients use in Eqn. 12-21",null,null,"Overdispersion    parameter     (k)",null,null,"Intersection type","Coefficients use in Eqn. 12-24",null,null,"Overdispersion    parameter     (k)",null,null,"Intersection type","Coefficients use in Eqn. 12-29",null,null,null,null,"Overdispersion    parameter     (k)",null,null,"Intersection Type","Intersection traffic control",null,"Number of approaches with left-turn lanes a"]
[null,null,"Intercept","AADTmaj","AADTmin",null,null,null,null,"Intercept","AADTmaj","AADTmin",null,null,null,null,"Intercept","AADTtot","AADTmin/AADTmaj","PedVol","nlanesx"]
[null,null,"(a)","(b)","(c)",null,null,null,null,"(a)","(b)","(c)",null,null,null,null,"(a)","(b)","(c)","(d)","(e)",null,null,null,null,null,null," One  approach","Two approaches","Three approaches","Four approaches"]
[null,"Total crashes",null,null,null,null,null,null,"Total crashes",null,null,null,null,null,null,"Total crashes"]
[null,"3ST",-13.36,1.1100000000000001,0.41,0.8,null,null,"3ST",-6.81,0.16,0.51,1.1399999999999999,null,null,"3SG",-6.6,0.05,0.24,0.41,0.09,0.52,null,null,"3ST","Minor-road STOP controlb",null,0.67,0.45,"--","--"]
[null,"3SG",-12.13,1.1100000000000001,0.26,0.33,null,null,"3SG",-9.02,0.42,0.4,0.36,null,null,"4SG",-9.5299999999999994,0.4,0.26,0.45,0.04,0.24,null,null,"3SG","Traffic signal",null,0.93,0.86,0.8]
[null,"4ST",-8.9,0.82,0.25,0.4,null,null,"4ST",-5.33,0.33,0.12,0.65,null,null,null,null,null,null,null,null,null,null,null,"4ST","Minor-road STOP controla",null,0.73,0.53,"--","--"]
[null,"4SG",-10.99,1.07,0.23,0.39,null,null,"4SG",-10.210000000000001,0.68,0.27,0.36,null,null,null,null,null,null,null,null,null,null,null,"4SG","Traffic signal",null,0.9,0.81,0.73,0.66]
[null,"Fatal-and-injury crashes",null,null,null,null,null,null,"Fatal-and-injury crashes",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"a STOP-controlled approaches are not considered in determining the number of approaches with left-turn lanes."]
[null,"3ST",-14.01,1.1599999999999999,0.3,0.69,null,null,"3ST","--","--","--",0,null,null,null,null,null,null,null,null,null,null,null,"b Stop signs present on minor-road approaches only."]
[null,"3SG",-11.58,1.02,0.17,0.3,null,null,"3SG",-9.75,0.27,0.51,0.24]
[null,"4ST",-11.13,0.93,0.28000000000000003,0.48,null,null,"4ST","--","--","--",0]
[null,"4SG",-13.14,1.18,0.22,0.33,null,null,"4SG",-9.25,0.43,0.28999999999999998,0.09]
[null,"Property-damage-only crashes",null,null,null,null,null,null,"Property-damage-only crashes",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Table 12-26: Crash Modification Factor (CMF3i) for Installation of Right-Turn Lanes on Intersection Approaches"]
[null,"3ST",-15.38,1.2,0.51,0.77,null,null,"3ST",-8.36,0.25,0.55000000000000004,1.29]
[null,"3SG",-13.24,1.1399999999999999,0.3,0.36,null,null,"3SG",-9.08,0.45,0.33,0.53,null,null,null,null,null,null,null,null,null,null,null,"Intersection Type","Intersection traffic control",null,"Number of approaches with right-turn lanes a"]
[null,"4ST",-8.74,0.77,0.23,0.4,null,null,"4ST",-7.04,0.36,0.25,0.54]
[null,"4SG",-11.02,1.02,0.24,0.44,null,null,"4SG",-11.34,0.78,0.25,0.44,null,null,null,null,null,null,null,null,null,null,null,null,null,null," One  approach","Two approaches","Three approaches","Four approaches"]
[null,null,null,null,null,null,null,null,"Note:  Where no models are available, Equations 12-27 is used."]
[null,null,null,null,null,null,null,null,"Equation 12-27:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"3ST","Minor-road STOP controlb",null,0.86,0.74,"--","--"]
[null,null,null,null,null,null,null,null,"Nbisv(FI) = Nbisv(TOTAL) x fbisv",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"3SG","Traffic signal",null,0.96,0.92,"--","--"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"4ST","Minor-road STOP controla",null,0.86,0.74,"--","--"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"4SG","Traffic signal",null,0.96,0.92,0.88,0.85]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"a STOP-controlled approaches are not considered in determining the number of approaches with right-turn lanes."]
[null,"Tables Affiliated with Crash Statistics:",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"b Stop signs present on minor-road approaches only."]
[]
[null,"Table 12-11: Distribution of Multiple-Vehicle Collisions for Intersections by Collision Type"]
[]
[null,null,null,"Proportion of crashes by severity level for specific intersection types",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Table 12-25: Crash Modification Factor (CMF2i) for Type of Left-Turn Signal Phasing"]
[null,null,null,"HSM-Provided Values"]
[null,"Collision type",null,"3ST",null,"3SG",null,"4ST",null,"4SG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Type of Left-Turn Signal Phasing",null,null,null,"CMF2i"]
[null,null,null,"FI","PDO","FI","PDO","FI","PDO","FI","PDO"]
[null,"Rear-end collision",null,0.42099999999999999,0.44,0.54900000000000004,0.54600000000000004,0.33800000000000002,0.374,0.45,0.48299999999999998,null,null,null,null,null,null,null,null,null,null,null,null,null,"Permissive",null,null,null,1]
[null,"Head-on collision",null,4.4999999999999998E-2,2.3E-2,3.7999999999999999E-2,0.02,4.1000000000000002E-2,0.03,4.9000000000000002E-2,0.03,null,null,null,null,null,null,null,null,null,null,null,null,null,"Protected/permissive or permissive/protected",null,null,null,0.99]
[null,"Angle collision",null,0.34300000000000003,0.26200000000000001,0.28000000000000003,0.20399999999999999,0.44,0.33500000000000002,0.34699999999999998,0.24399999999999999,null,null,null,null,null,null,null,null,null,null,null,null,null,"Protected",null,null,null,0.94]
[null,"Sideswipe",null,0.126,0.04,7.5999999999999998E-2,3.2000000000000001E-2,0.121,4.3999999999999997E-2,9.9000000000000005E-2,3.2000000000000001E-2]
[null,"Other multiple-vehicle collision",null,6.5000000000000002E-2,0.23499999999999999,5.7000000000000002E-2,0.19800000000000001,0.06,0.217,5.5E-2,0.21099999999999999]
[null,"Source: HSIS data for Washington (2002-2006)"]
[null,"Collision type",null,"Locally-Derived Values (Massachusetts)",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Table 12-28. Crash Modification Factor (CMF1p) for the Presence of Bus Stops near the Intersection"]
[null,null,null,"3ST",null,"3SG",null,"4ST",null,"4SG"]
[null,null,null,"FI","PDO","FI","PDO","FI","PDO","FI","PDO",null,null,null,null,null,null,null,null,null,null,null,null,null,"Number of Bus Stops within 1,000 ft of the Intersection",null,null,null,"CMF1p"]
[null,"Rear-end collision",null,0.41095890410958902,0.33684210526315789,0.58048780487804874,0.6045548654244306,0.15702479338842976,0.185,0.45200000000000001,0.42218798151001541]
[null,"Head-on collision",null,1.3698630136986301E-2,1.0526315789473684E-2,3.4146341463414637E-2,1.4492753623188406E-2,8.2644628099173556E-3,1.4999999999999999E-2,3.5999999999999997E-2,3.8520801232665637E-2,null,null,null,null,null,null,null,null,null,null,null,null,null,0,null,null,null,1]
[null,"Angle collision",null,0.56164383561643838,0.57894736842105265,0.34146341463414637,0.26501035196687373,0.81818181818181823,0.72,0.49199999999999999,0.42526964560862868,null,null,null,null,null,null,null,null,null,null,null,null,null,"1 or 2",null,null,null,2.78]
[null,"Sideswipe",null,1.3698630136986301E-2,7.3684210526315783E-2,3.9024390243902439E-2,0.11594202898550725,1.6528925619834711E-2,0.08,0.02,0.11248073959938366,null,null,null,null,null,null,null,null,null,null,null,null,null,"3 or more",null,null,null,4.1500000000000004]
[null,"Other multiple-vehicle collision",null,0,0,4.8780487804878049E-3,0,0,0,0,1.5408320493066256E-3]
[null,"Note:  HSM-Provided values based on HSIS data for California (2002-2006)"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Table 12-29. Crash Modification Factor (CMF2p) for the Presence of Schools near the Intersection"]
[null,"Table 12-13: Distribution of Single-Vehicle Crashes for Intersections by Collision Type"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Number of Schools within 1,000 ft of the Intersection",null,null,null,"CMF2p"]
[null,null,null,"Proportion of crashes by severity level for specific intersection types"]
[null,null,null,"HSM-Provided Values",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"No school present",null,null,null,1]
[null,"Collision type",null,"3ST",null,"3SG",null,"4ST",null,"4SG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"School present",null,null,null,1.35]
[null,null,null,"FI","PDO","FI","PDO","FI","PDO","FI","PDO"]
[null,"Collision with parked vehicle",null,1E-3,3.0000000000000001E-3,1E-3,1E-3,1E-3,1E-3,1E-3,1E-3]
[null,"Collision with animal",null,3.0000000000000001E-3,1.7999999999999999E-2,1E-3,3.0000000000000001E-3,1E-3,2.5999999999999999E-2,2E-3,2E-3]
[null,"Collision with fixed object",null,0.76200000000000001,0.83409999999999995,0.65300000000000002,0.89500000000000002,0.67900000000000005,0.84699999999999998,0.74399999999999999,0.87,null,null,null,null,null,null,null,null,null,null,null,null,null,"Table 12-30. Crash Modification Factor (CMF3p) for the Presence of Alcohol Sales Establishments near the Intersection"]
[null,"Collision with other object",null,0.09,9.1999999999999998E-2,9.0999999999999998E-2,6.9000000000000006E-2,8.8999999999999996E-2,7.0000000000000007E-2,7.1999999999999995E-2,7.0000000000000007E-2]
[null,"Other single-vehicle collision",null,3.9E-2,2.3E-2,4.4999999999999998E-2,1.7999999999999999E-2,5.0999999999999997E-2,7.0000000000000001E-3,0.04,2.3E-2,null,null,null,null,null,null,null,null,null,null,null,null,null,"Number of Alcohol Sales Establishment within 1,000 ft of the Intersection",null,null,null,"CMF3p"]
[null,"Noncollision",null,0.105,0.03,0.20899999999999999,1.4E-2,0.17899999999999999,4.9000000000000002E-2,0.14099999999999999,3.4000000000000002E-2]
[null,"Source: HSM-Provided values base on HSIS data for California (2002-2006)",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,0,null,null,null,1]
[null,"Collision type",null,"Locally-Derived Values",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"1--8",null,null,null,1.1200000000000001]
[null,null,null,"3ST",null,"3SG",null,"4ST",null,"4SG",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"9 or more",null,null,null,1.56]
[null,null,null,"FI","PDO","FI","PDO","FI","PDO","FI","PDO"]
[null,"Collision with parked vehicle",null,0,4.3478260869565216E-2,0,5.2631578947368418E-2,0,0.14285714285714285,0,2.7777777777777776E-2]
[null,"Collision with animal",null,0,4.3478260869565216E-2,0,0,0,0.2857142857142857,0,2.7777777777777776E-2]
[null,"Collision with fixed object",null,0.625,0.86956521739130432,0.9,0.89473684210526316,0.66666666666666663,0.5714285714285714,0.625,0.86111111111111116]
[null,"Collision with other object",null,0.125,4.3478260869565216E-2,0,2.6315789473684209E-2,0,0,0,5.5555555555555552E-2]
[null,"Other single-vehicle collision",null,0,0,0,2.6315789473684209E-2,0,0,0.125,2.7777777777777776E-2]
[null,"Noncollision",null,0.25,0,0.1,0,0.33333333333333331,0,0.25,0]
[]
[]
[]
[null,"Table 12-27: Nighttime Crash Proportions for Unlighted Intersections"]
[]
[null,null,null,"Proportion of crashes that occur at night, pni"]
[null,null,null,"HSM-Provided Values",null,"Locally-Derived Values"]
[null,"Intersection Type"]
[null,"3ST",null,0.23799999999999999,null,"--"]
[null,"4ST",null,0.22900000000000001,null,0.27300000000000002]
[null,"3SG",null,0.23499999999999999,null,"--"]
[null,"4SG",null,0.23499999999999999,null,0.214]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
["MassDOT METHOD"]
[]
[]
[null,"Tables Affiliated with SPF Computation:"]
[]
[]
[null,"Table 12-10 Modified: SPF Coefficients for Multiple-Vehicle Collisions at Intersections",null,null,null,null,null,null,"Table 1A: Coefficients Derived From Historical Data  for Single-Vehicle Collisions at Intersections",null,null,null,null,null,null,"Table 1B: Number of Vehicle-Pedestrian and Vehicle-Bike Crashes by Manner and Injury Severity"]
[]
[null,"Intersection type","Coefficients use in Eqn. 12-21",null,null,"Overdispersion    parameter     (k)",null,null,"Intersection type","Total Single Vehicle Crashes","Total Multiple Vehicle Crashes","Coefficient Derived",null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Locally-Derived Values",null,"HSM-Provided Values"]
[null,null,"Intercept","AADTmaj","AADTmin",null,null,null,null,null,null,null,null,null,null,"Intersection type","Total Single Vehicle Crashes","Total Multiple Vehicle Crashes","Veh-Pedestrian",null,null,"Veh-Bike",null,null,"Total (FI+PDO)",null,"Veh-Ped FI ω Coefficient ","Veh-Bike ω Coefficient","Veh-Ped FI ω Coefficient ","Veh-Bike ω Coefficient"]
[null,null,"(a)","(b)","(c)"]
[null,"Total crashes",null,null,null,null,null,null,"3ST",31,263,{"$f":"J121/K121","v":0.11787072243346007}]
[null,"3ST",-20.02,1.66,0.54,0.24,null,null,"3SG",48,688,{"$f":"J122/K122","v":6.9767441860465115E-2},null,null,null,null,null,null,"FI","PDO","Total","FI","PDO","Total","FI","PDO"]
[null,"3SG",-8.2987000000000002,0.81220000000000003,0.2122,0.40716612377850164,null,null,"4ST",10,321,{"$f":"J123/K123","v":3.1152647975077882E-2},null,null,null,"3ST",31,263,6,0,{"$f":"S123+T123","v":6},8,2,{"$f":"V123+W123","v":10},{"$f":"S123+V123","v":14},2,{"$f":"U123/(Q123+R123)","v":2.0408163265306121E-2},{"$f":"X123/(Q123+R123)","v":3.4013605442176874E-2},2.1000000000000001E-2,1.6E-2]
[null,"4ST",-8.6972000000000005,0.30859999999999999,0.85619999999999996,0.36433854337450361,null,null,"4SG",44,899,{"$f":"J124/K124","v":4.8943270300333706E-2},null,null,null,"3SG",48,688,11,4,{"$f":"S124+T124","v":15},10,6,{"$f":"V124+W124","v":16},21,10,{"$f":"U124/(Q124+R124)","v":2.0380434782608696E-2},{"$f":"X124/(Q124+R124)","v":2.1739130434782608E-2},null,1.0999999999999999E-2]
[null,"4SG",-11.789899999999999,0.91769999999999996,0.52170000000000005,9.5023613367921936E-2,null,null,null,null,null,null,null,null,null,"4ST",10,321,5,0,{"$f":"S125+T125","v":5},2,1,{"$f":"V125+W125","v":3},7,1,{"$f":"U125/(Q125+R125)","v":1.5105740181268883E-2},{"$f":"X125/(Q125+R125)","v":9.0634441087613302E-3},2.1999999999999999E-2,1.7999999999999999E-2]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"4SG",44,899,26,1,{"$f":"S126+T126","v":27},30,10,{"$f":"V126+W126","v":40},56,11,{"$f":"U126/(Q126+R126)","v":2.863202545068929E-2},{"$f":"X126/(Q126+R126)","v":4.2417815482502653E-2},null,1.4999999999999999E-2]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Table 1C: Coefficients of FI and PDO Derived From Historical Data for multiple-vehicle Collisions at Intersections"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Intersection type","Total Single Vehicle Crashes","Total Multiple Vehicle Crashes","Single Vehicle FI","Single Vehicle PDO","Single Vehicle FI Ratio","Single Vehicle PDO Ratio","Multiple Vehicle FI","Multiple Vehicle PDO","Multiple Vehicle FI Ratio","Multiple Vehicle PDO Ratio"]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"3ST",31,263,8,23,{"$f":"S134/Q134","v":0.25806451612903225},{"$f":"1-U134","v":0.74193548387096775},73,190,{"$f":"W134/R134","v":0.27756653992395436},{"$f":"1-Y134","v":0.72243346007604559}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"3SG",48,688,10,38,{"$f":"S135/Q135","v":0.20833333333333334},{"$f":"1-U135","v":0.79166666666666663},205,483,{"$f":"W135/R135","v":0.29796511627906974},{"$f":"1-Y135","v":0.70203488372093026}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"4ST",10,321,3,7,{"$f":"S136/Q136","v":0.3},{"$f":"1-U136","v":0.7},121,200,{"$f":"W136/R136","v":0.37694704049844235},{"$f":"1-Y136","v":0.6230529595015577}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"4SG",44,899,8,36,{"$f":"S137/Q137","v":0.18181818181818182},{"$f":"1-U137","v":0.81818181818181812},250,649,{"$f":"W137/R137","v":0.27808676307007785},{"$f":"1-Y137","v":0.72191323692992215}]

{"sheet":"Calibration Factors","index":6,"n_rows":8,"n_cols":7,"rows_kept":8,"cut":false,"hidden":true,"merged":[[3,2,4,6]]}
[]
[]
[]
[null,null,"Calibration Factors"]
[]
[null,null,null,"3SG","3ST","4SG","4ST"]
[null,null,"HSM Method",1.5,0.77,1.49,1.03]
[null,null,"MassDOT Method",0.95,1.1299999999999999,1,1.04]

{"sheet":"Construction - do not delete","index":7,"n_rows":188,"n_cols":32,"rows_kept":188,"cut":false,"hidden":true,"merged":[[107,0,108,0],[107,4,107,14],[107,1,108,3],[99,27,99,31],[101,27,101,31],[103,21,103,25],[103,27,103,31],[81,21,81,25],[83,21,83,25],[87,21,87,25],[82,27,82,31],[83,27,83,31],[85,27,85,31],[82,21,82,25],[93,21,93,25],[95,21,95,25],[106,0,106,14],[81,27,81,31],[97,21,97,25],[99,21,99,25],[101,21,101,25],[89,27,89,31],[91,27,91,31],[93,27,93,31],[95,27,95,31],[97,27,97,31],[85,21,85,25],[89,21,89,25],[91,21,91,25],[87,27,87,31],[178,0,178,6],[166,0,166,6],[142,0,142,6],[154,0,154,6],[119,0,119,3],[120,1,120,3],[121,1,121,3],[122,1,122,3],[0,0,0,17],[1,0,1,17],[123,1,123,3],[128,1,128,3],[127,1,127,3],[124,1,124,3],[125,1,125,3],[126,1,126,3],[113,1,113,3],[114,1,114,3],[115,1,115,3],[112,1,112,3],[116,1,116,3],[110,1,110,3],[111,1,111,3],[109,1,109,3]]}
["NOTICE!"]
["This sheet is present to ensure the proper functioning of the excel workbook. Please do not tamper with or delete this worksheet. Doing so, would result in improper functioning of the workbook."]
[]
[null,"Lane Width",null,"Shoulder Width",null,"RHR"]
[null,9,null,0,null,1]
[null,9.5,null,1,null,2]
[null,10,null,2,null,3]
[null,10.5,null,3,null,4]
[null,11,null,4,null,5]
[null,11.5,null,5,null,6]
[null,12,null,6,null,7]
[null,null,null,7]
[null,null,null,8]
[]
[]
[null,null,null,null,null,null,null,"Centerline",null,"Passing",null,"Local"]
[null,null,null,"Shoulder Type",null,"Spiral",null,"Rumble Strips",null,"Lane",null,"Yes"]
[null,null,null,"Paved",null,"Not Present",null,"Not Present",null,"Not Present",null,"No"]
[null,null,null,"Gravel",null,"Present",null,"Present",null,"Present (1 lane)"]
[null,null,null,"Composite",null,null,null,null,null,"Present (2 lanes)"]
[null,null,null,"Turf"]
[]
[null,null,null,null,null,"TWLTL",null,"Lighting",null,"SpEnforce"]
[null,null,null,null,null,"Not Present",null,"Not Present",null,"Not Present"]
[null,null,null,null,null,"Present",null,"Present",null,"Present"]
[]
[]
[null,null,null,"Intersection Type",null,"No. of Left Turn Approaches",null,"No. of Right Turn Approaches",null,"Intersection Lighting",null,"Use of Coefficients"]
[null,null,null,"Itype",null,"Lapproach",null,"Rapproach",null,"Ilight",null,"Differ"]
[null,null,null,"3ST",null,0,null,0,null,"Not Present",null,"Yes"]
[null,null,null,"4ST",null,1,null,1,null,"Present",null,"No"]
[null,null,null,"4SG",null,2,null,2]
[null,null,null,null,null,3,null,3]
[null,null,null,null,null,4,null,4]
[]
[null,null,null,"Median Width"]
[null,null,null,"Mwidth",null,"Division",null,"Sslope",null,"Shld2",null,"Iapproach"]
[null,null,null,10,null,"Divided",null,"1:2 or Steeper",null,0,null,0]
[null,null,null,20,null,"Undivided",null,"1:4",null,1,null,1]
[null,null,null,30,null,null,null,"1:5",null,2,null,2]
[null,null,null,40,null,null,null,"1:6",null,3]
[null,null,null,50,null,null,null,"1:7 or Flatter",null,4]
[null,null,null,60,null,null,null,null,null,5]
[null,null,null,70,null,null,null,null,null,6]
[null,null,null,80,null,null,null,null,null,7]
[null,null,null,90,null,null,null,null,null,8]
[null,null,null,100,null,null,null,null,null,9]
[null,null,null,null,null,null,null,null,null,10]
[]
[]
[]
[null,null,null,"Urban / Suburban Fields:"]
[]
[]
[null,null,null,"Rtype",null,"UMedWidth",null,"PresOrNot",null,"OnStreetType",null,"OffsetFO",null,"Posted"]
[null,null,null,"2U",null,"Not Present",null,"Not Present",null,"None",null,2,null,"Posted Speed 30 mph or Lower"]
[null,null,null,"3T",null,10,null,"Present",null,"Parallel (Residential)",null,5,null,"Posted Speed Greater than 30 mph"]
[null,null,null,"4U",null,15,null,null,null,"Parallel (Comm/Ind)",null,10]
[null,null,null,"4D",null,20,null,null,null,"Angle (Residential)",null,15]
[null,null,null,"5T",null,30,null,null,null,"Angle (Comm/Ind)",null,20]
[null,null,null,null,null,40,null,null,null,null,null,25]
[null,null,null,null,null,50,null,null,null,null,null,"≥ 30"]
[null,null,null,null,null,60]
[null,null,null,null,null,70]
[null,null,null,null,null,80]
[null,null,null,null,null,90]
[null,null,null,null,null,100]
[]
[]
[null,null,null,"Turning Lanes",null,"Intersection Type2",null,"Phasing",null,"Unsignalized Approaches",null,"Phasing 2"]
[null,null,null,"Tlanes",null,"Itype2",null,"Phasing",null,"UnsigApproach",null,"Phasing2"]
[null,null,null,0,null,"3ST",null,"Permissive",null,0,null,"Not Applicable"]
[null,null,null,1,null,"3SG",null,"Protected",null,1,null,"Permissive"]
[null,null,null,2,null,"4ST",null,"Protected / Permissive",null,2,null,"Protected"]
[null,null,null,3,null,"4SG",null,"Permissive / Protected",null,null,null,"Protected / Permissive"]
[null,null,null,4,null,null,null,null,null,null,null,"Permissive / Protected"]
[]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"IF(Input!#REF!=\"\",\"\",IF(Input!#REF!>#REF!,\"AADT Out of Range\", \"AADT OK\"))","v":{"$error":"#REF!"}}]
[]
[]
["Intersection Type",null,"Number of Alternatives",null,"Spreadsheet Selection",null,null,"Facility Type","Facility Type Code","Average FI Crash Cost","Average PDO Crash Cost",null,null,"Study Period (Years)",null,null,null,null,null,null,null,"DO NOT MODIFY",null,null,null,null,null,"DO NOT MODIFY"]
["3ST",null,0,null,"3ST HSM",null,null,"Please Select Facility Type",null,null,null,null,null,1,null,null,null,null,null,null,null,"Major AADT Verification",null,null,null,null,null,"Minor AADT Verification"]
["3SG",null,1,null,"4ST HSM",null,null,"Urban Three-Leg Signalized Intersection","U3SG",339500,16700,null,null,2,null,null,null,null,null,null,null,{"$f":"V85&W85&X85&Y85&Z85","v":"=if('Input'!D50>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB85&AC85&AD85&AE85&AF85","v":"=if('Input'!D52>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
["4ST",null,2,null,"3SG HSM",null,null,"Urban Three-Leg Stop-Controlled Intersection","U3ST",352800,16700,null,null,3,null,null,null,null,null,null,null,"=if('","Input","'!D50>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!D52>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
["4SG",null,3,null,"4SG HSM",null,null,"Urban Four-Leg Signalized Intersection","U4SG",327200,16700,null,null,4,null,null,null,null,null,null,null,{"$f":"V87&W87&X87&Y87&Z87","v":"=if('Input'!E50>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB87&AC87&AD87&AE87&AF87","v":"=if('Input'!E52>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
[null,null,4,null,null,null,null,"Urban Four-Leg Stop-Controlled Intersection","U4ST",319100,16700,null,null,5,null,null,null,null,null,null,null,"=if('","Input","'!E50>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!E52>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
[null,null,null,null,null,null,null,"Urban Two-Lane Undivided Arterial – District 1","U2UAD1",501300,16700,null,null,6,null,null,null,null,null,null,null,{"$f":"V89&W89&X89&Y89&Z89","v":"=if('Input'!F50>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB89&AC89&AD89&AE89&AF89","v":"=if('Input'!F52>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
[null,null,null,null,null,null,null,"Urban Two-Lane Undivided Arterial – District 2","U2UAD2",490700,16700,null,null,7,null,null,null,null,null,null,null,"=if('","Input","'!F50>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!F52>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
[null,null,null,null,null,null,null,"Urban Two-Lane Undivided Arterial – District 3","U2UAD3",532100,16700,null,null,8,null,null,null,null,null,null,null,{"$f":"V91&W91&X91&Y91&Z91","v":"=if('Input'!G50>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB91&AC91&AD91&AE91&AF91","v":"=if('Input'!G52>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
[null,null,null,null,null,null,null,"Urban Two-Lane Undivided Arterial – District 4","U2UAD4",402400,16700,null,null,9,null,null,null,null,null,null,null,"=if('","Input","'!G50>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!G52>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
[null,null,null,null,null,null,null,"Urban Two-Lane Undivided Arterial – District 5","U2UAD5",522500,16700,null,null,10,null,null,null,null,null,null,null,{"$f":"V93&W93&X93&Y93&Z93","v":"=if('Input'!H50>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB93&AC93&AD93&AE93&AF93","v":"=if('Input'!H52>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
[null,null,null,null,null,null,null,"Urban Two-Lane Undivided Arterial – District 6","U2UAD6",462000,16700,null,null,null,null,null,null,null,null,null,null,"=if('","Input","'!H50>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!H52>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
[null,null,null,null,null,null,null,"Urban Four-Lane Undivided Arterial","U4UA",481300,16700,null,null,null,null,null,null,null,null,null,null,{"$f":"V95&W95&X95&Y95&Z95","v":"=if('Input'!I50>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB95&AC95&AD95&AE95&AF95","v":"=if('Input'!I52>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
[null,null,null,null,null,null,null,"Urban Four-Lane Divided Arterial","U4DA",530800,16700,null,null,null,null,null,null,null,null,null,null,"=if('","Input","'!I50>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!I52>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
[null,null,null,null,null,null,null,"Rural Two-Lane Undivided Highway","R2UAC",878400,16700,null,null,null,null,null,null,null,null,null,null,{"$f":"V97&W97&X97&Y97&Z97","v":"=if('Input'!J50>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB97&AC97&AD97&AE97&AF97","v":"=if('Input'!J52>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"=if('","Input","'!J50>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!J52>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"V99&W99&X99&Y99&Z99","v":"=if('Input'!K50>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB99&AC99&AD99&AE99&AF99","v":"=if('Input'!K52>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"=if('","Input","'!K50>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!K52>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"V101&W101&X101&Y101&Z101","v":"=if('Input'!L50>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB101&AC101&AD101&AE101&AF101","v":"=if('Input'!L52>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"=if('","Input","'!L50>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!L52>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"V103&W103&X103&Y103&Z103","v":"=if('Input'!M50>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB103&AC103&AD103&AE103&AF103","v":"=if('Input'!M52>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"=if('","Input","'!M50>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!M52>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"V105&W105&X105&Y105&Z105","v":"=if('Input'!D55>'3ST HSM'!F12,\"AADT Out of Range\",\"AADT OK\") "},null,null,null,null,null,{"$f":"AB105&AC105&AD105&AE105&AF105","v":"=if('Input'!D57>'3ST HSM'!F13,\"AADT Out of Range\",\"AADT OK\") "}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"=if('","Input","'!D55>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F12,\"AADT Out of Range\",\"AADT OK\") ",null,"=if('","Input","'!D57>'",{"$f":"'Input Summary'!B10","v":"3ST HSM"},"'!F13,\"AADT Out of Range\",\"AADT OK\") "]
[]
["DO NOT MODIFY"]
["Crash Type, Severity","Predicted Crash Frequency per Year \n(From Prediction Spreadsheet [Predicted Nb])",null,null,"Year:"]
[null,null,null,null,1,2,3,4,5,6,7,8,9,10,"Design Year"]
["MV, FI",{"$f":"$A$118&$B$118&\"'!N71\"","v":"='Year '!N71"},null,null,{"$f":"$A$118&E109&\"'!N71\"","v":"='Year 1'!N71"},{"$f":"$A$118&F109&\"'!N71\"","v":"='Year 2'!N71"},"='Year 3'!N71","='Year 4'!N71","='Year 5'!N71","='Year 6'!N71","='Year 7'!N71","='Year 8'!N71","='Year 9'!N71","='Year 10'!N71",{"$f":"\"'\"&O109&\"'!N71\"","v":"'Design Year'!N71"}]
["MV, PDO",{"$f":"$A$118&$B$118&\"'!N73\"","v":"='Year '!N73"},null,null,{"$f":"$A$118&E109&\"'!N73\"","v":"='Year 1'!N73"},{"$f":"$A$118&F109&\"'!N73\"","v":"='Year 2'!N73"},"='Year 3'!N73","='Year 4'!N73","='Year 5'!N73","='Year 6'!N73","='Year 7'!N73","='Year 8'!N73","='Year 9'!N73","='Year 10'!N73",{"$f":"\"'\"&O109&\"'!N73\"","v":"'Design Year'!N73"}]
["SV, FI",{"$f":"$A$118&$B$118&\"'!N117\"","v":"='Year '!N117"},null,null,{"$f":"$A$118&E109&\"'!N117\"","v":"='Year 1'!N117"},{"$f":"$A$118&F109&\"'!N117\"","v":"='Year 2'!N117"},"='Year 3'!N117","='Year 4'!N117","='Year 5'!N117","='Year 6'!N117","='Year 7'!N117","='Year 8'!N117","='Year 9'!N117","='Year 10'!N117",{"$f":"\"'\"&O109&\"'!N117\"","v":"'Design Year'!N117"}]
["SV, PDO",{"$f":"$A$118&$B$118&\"'!N119\"","v":"='Year '!N119"},null,null,{"$f":"$A$118&E109&\"'!N119\"","v":"='Year 1'!N119"},{"$f":"$A$118&F109&\"'!N119\"","v":"='Year 2'!N119"},"='Year 3'!N119","='Year 4'!N119","='Year 5'!N119","='Year 6'!N119","='Year 7'!N119","='Year 8'!N119","='Year 9'!N119","='Year 10'!N119",{"$f":"\"'\"&O109&\"'!N119\"","v":"'Design Year'!N119"}]
["Ped, FI",{"$f":"$A$118&$B$118&\"'!N158\"","v":"='Year '!N158"},null,null,{"$f":"$A$118&E109&\"'!K158\"","v":"='Year 1'!K158"},"='Year 2'!K158","='Year 3'!K158","='Year 4'!K158","='Year 5'!K158","='Year 6'!K158","='Year 7'!K158","='Year 8'!K158","='Year 9'!K158","='Year 10'!K158",{"$f":"\"'\"&O109&\"'!K158\"","v":"'Design Year'!K158"}]
["Ped, PDO",0,null,null,0,0,0,0,0,0,0,0,0,0,0]
["Bike, FI",{"$f":"$A$118&$B$118&\"'!M169\"","v":"='Year '!M169"},null,null,{"$f":"$A$118&E109&\"'!K169\"","v":"='Year 1'!K169"},"='Year 2'!K169","='Year 3'!K169","='Year 4'!K169","='Year 5'!K169","='Year 6'!K169","='Year 7'!K169","='Year 8'!K169","='Year 9'!K169","='Year 10'!K169",{"$f":"\"'\"&O109&\"'!K169\"","v":"'Design Year'!K169"}]
["Bike, PDO",0,null,null,0,0,0,0,0,0,0,0,0,0,0]
["='Year "]
[]
["DO NOT MODIFY - For Design Year Calc"]
["Crash Type, Severity","Future Predicted Crash Frequency per Year \n(From Prediction Spreadsheet [Predicted Nb])"]
["MV, FI",{"$f":"$A$130&$B$130&\"'!N71\"","v":"='Design Year'!N71"}]
["MV, PDO",{"$f":"$A$130&$B$130&\"'!N73\"","v":"='Design Year'!N73"}]
["SV, FI",{"$f":"$A$130&$B$130&\"'!N117\"","v":"='Design Year'!N117"}]
["SV, PDO",{"$f":"$A$130&$B$130&\"'!N119\"","v":"='Design Year'!N119"}]
["Ped, FI",{"$f":"$A$130&$B$130&\"'!M158\"","v":"='Design Year'!M158"}]
["Ped, PDO",0]
["Bike, FI",{"$f":"$A$130&$B$130&\"'!K169\"","v":"='Design Year'!K169"}]
["Bike, PDO",0]
["='Design Year",null,"N71"]
[]
[]
[]
[]
["CMF Calculations:"]
["Not Applicable"]
["Multiplicative"]
["Additive"]
["Dominant Effect"]
["Dominant Common Residuals"]
[]
[]
["Alternative 1"]
["Crash Type, Severity","Multiplicative","Additive Calc","Additive < 0 Round","Dominant Effect","Dominant Common Residuals Step 1","Dominant Common Residuals Result"]
["MV, ALL",{"$f":"IF(AND(Input!B76=\"Multiplicative\",Input!C76<>\"\",Input!E76<>\"\"),IF(AND(Input!C76<1,Input!E76<1),\"ERROR Check Input\",Input!C76*Input!E76),\"\")","v":""},{"$f":"IF(AND(Input!B76=\"Additive\",Input!C76<>\"\",Input!E76<>\"\"),1-((1-Input!C76)+(1-Input!E76)),\"\")","v":""},{"$f":"IF(C145=\"\",\"\",IF(C145<=0,0,C145))","v":""},{"$f":"IF(AND(Input!B76=\"Dominant Effect\",Input!C76<>\"\",Input!E76<>\"\"),MIN(Input!C76,Input!E76),\"\")","v":""},{"$f":"IF(AND(Input!B76=\"Dominant Common Residuals\",Input!C76<>\"\",Input!E76<>\"\"),MIN(Input!C76,Input!E76),\"\")","v":""},{"$f":"IF(F145<>\"\",MIN(Input!C76,Input!E76,(Input!C76*Input!E76)^F145),\"\")","v":""}]
["MV, FI",{"$f":"IF(AND(Input!B77=\"Multiplicative\",Input!C77<>\"\",Input!E77<>\"\"),IF(AND(Input!C77<1,Input!E77<1),\"ERROR Check Input\",Input!C77*Input!E77),\"\")","v":""},{"$f":"IF(AND(Input!B77=\"Additive\",Input!C77<>\"\",Input!E77<>\"\"),1-((1-Input!C77)+(1-Input!E77)),\"\")","v":""},{"$f":"IF(AND(Input!B77=\"Additive\",Input!C77<>\"\",Input!E77<>\"\"),1-((1-Input!C77)+(1-Input!E77)),\"\")","v":""},{"$f":"IF(AND(Input!B77=\"Dominant Effect\",Input!C77<>\"\",Input!E77<>\"\"),MIN(Input!C77,Input!E77),\"\")","v":""},{"$f":"IF(AND(Input!B77=\"Dominant Common Residuals\",Input!C77<>\"\",Input!E77<>\"\"),MIN(Input!C77,Input!E77),\"\")","v":""},{"$f":"IF(F146<>\"\",MIN(Input!C77,Input!E77,(Input!C77*Input!E77)^F146),\"\")","v":""}]
["SV, ALL",{"$f":"IF(AND(Input!B78=\"Multiplicative\",Input!C78<>\"\",Input!E78<>\"\"),IF(AND(Input!C78<1,Input!E78<1),\"ERROR Check Input\",Input!C78*Input!E78),\"\")","v":""},{"$f":"IF(AND(Input!B78=\"Additive\",Input!C78<>\"\",Input!E78<>\"\"),1-((1-Input!C78)+(1-Input!E78)),\"\")","v":""},{"$f":"IF(AND(Input!B78=\"Additive\",Input!C78<>\"\",Input!E78<>\"\"),1-((1-Input!C78)+(1-Input!E78)),\"\")","v":""},{"$f":"IF(AND(Input!B78=\"Dominant Effect\",Input!C78<>\"\",Input!E78<>\"\"),MIN(Input!C78,Input!E78),\"\")","v":""},{"$f":"IF(AND(Input!B78=\"Dominant Common Residuals\",Input!C78<>\"\",Input!E78<>\"\"),MIN(Input!C78,Input!E78),\"\")","v":""},{"$f":"IF(F147<>\"\",MIN(Input!C78,Input!E78,(Input!C78*Input!E78)^F147),\"\")","v":""}]
["SV, FI",{"$f":"IF(AND(Input!B79=\"Multiplicative\",Input!C79<>\"\",Input!E79<>\"\"),IF(AND(Input!C79<1,Input!E79<1),\"ERROR Check Input\",Input!C79*Input!E79),\"\")","v":""},{"$f":"IF(AND(Input!B79=\"Additive\",Input!C79<>\"\",Input!E79<>\"\"),1-((1-Input!C79)+(1-Input!E79)),\"\")","v":""},{"$f":"IF(AND(Input!B79=\"Additive\",Input!C79<>\"\",Input!E79<>\"\"),1-((1-Input!C79)+(1-Input!E79)),\"\")","v":""},{"$f":"IF(AND(Input!B79=\"Dominant Effect\",Input!C79<>\"\",Input!E79<>\"\"),MIN(Input!C79,Input!E79),\"\")","v":""},{"$f":"IF(AND(Input!B79=\"Dominant Common Residuals\",Input!C79<>\"\",Input!E79<>\"\"),MIN(Input!C79,Input!E79),\"\")","v":""},{"$f":"IF(F148<>\"\",MIN(Input!C79,Input!E79,(Input!C79*Input!E79)^F148),\"\")","v":""}]
["Ped, ALL",{"$f":"IF(AND(Input!B80=\"Multiplicative\",Input!C80<>\"\",Input!E80<>\"\"),IF(AND(Input!C80<1,Input!E80<1),\"ERROR Check Input\",Input!C80*Input!E80),\"\")","v":""},{"$f":"IF(AND(Input!B80=\"Additive\",Input!C80<>\"\",Input!E80<>\"\"),1-((1-Input!C80)+(1-Input!E80)),\"\")","v":""},{"$f":"IF(AND(Input!B80=\"Additive\",Input!C80<>\"\",Input!E80<>\"\"),1-((1-Input!C80)+(1-Input!E80)),\"\")","v":""},{"$f":"IF(AND(Input!B80=\"Dominant Effect\",Input!C80<>\"\",Input!E80<>\"\"),MIN(Input!C80,Input!E80),\"\")","v":""},{"$f":"IF(AND(Input!B80=\"Dominant Common Residuals\",Input!C80<>\"\",Input!E80<>\"\"),MIN(Input!C80,Input!E80),\"\")","v":""},{"$f":"IF(F149<>\"\",MIN(Input!C80,Input!E80,(Input!C80*Input!E80)^F149),\"\")","v":""}]
["Ped, FI",{"$f":"IF(AND(Input!B81=\"Multiplicative\",Input!C81<>\"\",Input!E81<>\"\"),IF(AND(Input!C81<1,Input!E81<1),\"ERROR Check Input\",Input!C81*Input!E81),\"\")","v":""},{"$f":"IF(AND(Input!B81=\"Additive\",Input!C81<>\"\",Input!E81<>\"\"),1-((1-Input!C81)+(1-Input!E81)),\"\")","v":""},{"$f":"IF(AND(Input!B81=\"Additive\",Input!C81<>\"\",Input!E81<>\"\"),1-((1-Input!C81)+(1-Input!E81)),\"\")","v":""},{"$f":"IF(AND(Input!B81=\"Dominant Effect\",Input!C81<>\"\",Input!E81<>\"\"),MIN(Input!C81,Input!E81),\"\")","v":""},{"$f":"IF(AND(Input!B81=\"Dominant Common Residuals\",Input!C81<>\"\",Input!E81<>\"\"),MIN(Input!C81,Input!E81),\"\")","v":""},{"$f":"IF(F150<>\"\",MIN(Input!C81,Input!E81,(Input!C81*Input!E81)^F150),\"\")","v":""}]
["Bike, ALL",{"$f":"IF(AND(Input!B82=\"Multiplicative\",Input!C82<>\"\",Input!E82<>\"\"),IF(AND(Input!C82<1,Input!E82<1),\"ERROR Check Input\",Input!C82*Input!E82),\"\")","v":""},{"$f":"IF(AND(Input!B82=\"Additive\",Input!C82<>\"\",Input!E82<>\"\"),1-((1-Input!C82)+(1-Input!E82)),\"\")","v":""},{"$f":"IF(AND(Input!B82=\"Additive\",Input!C82<>\"\",Input!E82<>\"\"),1-((1-Input!C82)+(1-Input!E82)),\"\")","v":""},{"$f":"IF(AND(Input!B82=\"Dominant Effect\",Input!C82<>\"\",Input!E82<>\"\"),MIN(Input!C82,Input!E82),\"\")","v":""},{"$f":"IF(AND(Input!B82=\"Dominant Common Residuals\",Input!C82<>\"\",Input!E82<>\"\"),MIN(Input!C82,Input!E82),\"\")","v":""},{"$f":"IF(F151<>\"\",MIN(Input!C82,Input!E82,(Input!C82*Input!E82)^F151),\"\")","v":""}]
["Bike, FI",{"$f":"IF(AND(Input!B83=\"Multiplicative\",Input!C83<>\"\",Input!E83<>\"\"),IF(AND(Input!C83<1,Input!E83<1),\"ERROR Check Input\",Input!C83*Input!E83),\"\")","v":""},{"$f":"IF(AND(Input!B83=\"Additive\",Input!C83<>\"\",Input!E83<>\"\"),1-((1-Input!C83)+(1-Input!E83)),\"\")","v":""},{"$f":"IF(AND(Input!B83=\"Additive\",Input!C83<>\"\",Input!E83<>\"\"),1-((1-Input!C83)+(1-Input!E83)),\"\")","v":""},{"$f":"IF(AND(Input!B83=\"Dominant Effect\",Input!C83<>\"\",Input!E83<>\"\"),MIN(Input!C83,Input!E83),\"\")","v":""},{"$f":"IF(AND(Input!B83=\"Dominant Common Residuals\",Input!C83<>\"\",Input!E83<>\"\"),MIN(Input!C83,Input!E83),\"\")","v":""},{"$f":"IF(F152<>\"\",MIN(Input!C83,Input!E83,(Input!C83*Input!E83)^F152),\"\")","v":""}]
[]
[]
["Alternative 2"]
["Crash Type, Severity","Multiplicative","Additive Calc","Additive < 0 Round","Dominant Effect","Dominant Common Residuals Step 1","Dominant Common Residuals Result"]
["MV, ALL",{"$f":"IF(AND(Input!B88=\"Multiplicative\",Input!C88<>\"\",Input!E88<>\"\"),IF(AND(Input!C88<1,Input!E88<1),\"ERROR Check Input\",Input!C88*Input!E88),\"\")","v":""},{"$f":"IF(AND(Input!B88=\"Additive\",Input!C88<>\"\",Input!E88<>\"\"),1-((1-Input!C88)+(1-Input!E88)),\"\")","v":""},{"$f":"IF(C157=\"\",\"\",IF(C157<=0,0,C157))","v":""},{"$f":"IF(AND(Input!B88=\"Dominant Effect\",Input!C88<>\"\",Input!E88<>\"\"),MIN(Input!C88,Input!E88),\"\")","v":""},{"$f":"IF(AND(Input!B88=\"Dominant Common Residuals\",Input!C88<>\"\",Input!E88<>\"\"),MIN(Input!C88,Input!E88),\"\")","v":""},{"$f":"IF(F157<>\"\",MIN(Input!C88,Input!E88,(Input!C88*Input!E88)^F157),\"\")","v":""}]
["MV, FI",{"$f":"IF(AND(Input!B89=\"Multiplicative\",Input!C89<>\"\",Input!E89<>\"\"),IF(AND(Input!C89<1,Input!E89<1),\"ERROR Check Input\",Input!C89*Input!E89),\"\")","v":""},{"$f":"IF(AND(Input!B89=\"Additive\",Input!C89<>\"\",Input!E89<>\"\"),1-((1-Input!C89)+(1-Input!E89)),\"\")","v":""},{"$f":"IF(AND(Input!B89=\"Additive\",Input!C89<>\"\",Input!E89<>\"\"),1-((1-Input!C89)+(1-Input!E89)),\"\")","v":""},{"$f":"IF(AND(Input!B89=\"Dominant Effect\",Input!C89<>\"\",Input!E89<>\"\"),MIN(Input!C89,Input!E89),\"\")","v":""},{"$f":"IF(AND(Input!B89=\"Dominant Common Residuals\",Input!C89<>\"\",Input!E89<>\"\"),MIN(Input!C89,Input!E89),\"\")","v":""},{"$f":"IF(F158<>\"\",MIN(Input!C89,Input!E89,(Input!C89*Input!E89)^F158),\"\")","v":""}]
["SV, ALL",{"$f":"IF(AND(Input!B90=\"Multiplicative\",Input!C90<>\"\",Input!E90<>\"\"),IF(AND(Input!C90<1,Input!E90<1),\"ERROR Check Input\",Input!C90*Input!E90),\"\")","v":""},{"$f":"IF(AND(Input!B90=\"Additive\",Input!C90<>\"\",Input!E90<>\"\"),1-((1-Input!C90)+(1-Input!E90)),\"\")","v":""},{"$f":"IF(AND(Input!B90=\"Additive\",Input!C90<>\"\",Input!E90<>\"\"),1-((1-Input!C90)+(1-Input!E90)),\"\")","v":""},{"$f":"IF(AND(Input!B90=\"Dominant Effect\",Input!C90<>\"\",Input!E90<>\"\"),MIN(Input!C90,Input!E90),\"\")","v":""},{"$f":"IF(AND(Input!B90=\"Dominant Common Residuals\",Input!C90<>\"\",Input!E90<>\"\"),MIN(Input!C90,Input!E90),\"\")","v":""},{"$f":"IF(F159<>\"\",MIN(Input!C90,Input!E90,(Input!C90*Input!E90)^F159),\"\")","v":""}]
["SV, FI",{"$f":"IF(AND(Input!B91=\"Multiplicative\",Input!C91<>\"\",Input!E91<>\"\"),IF(AND(Input!C91<1,Input!E91<1),\"ERROR Check Input\",Input!C91*Input!E91),\"\")","v":""},{"$f":"IF(AND(Input!B91=\"Additive\",Input!C91<>\"\",Input!E91<>\"\"),1-((1-Input!C91)+(1-Input!E91)),\"\")","v":""},{"$f":"IF(AND(Input!B91=\"Additive\",Input!C91<>\"\",Input!E91<>\"\"),1-((1-Input!C91)+(1-Input!E91)),\"\")","v":""},{"$f":"IF(AND(Input!B91=\"Dominant Effect\",Input!C91<>\"\",Input!E91<>\"\"),MIN(Input!C91,Input!E91),\"\")","v":""},{"$f":"IF(AND(Input!B91=\"Dominant Common Residuals\",Input!C91<>\"\",Input!E91<>\"\"),MIN(Input!C91,Input!E91),\"\")","v":""},{"$f":"IF(F160<>\"\",MIN(Input!C91,Input!E91,(Input!C91*Input!E91)^F160),\"\")","v":""}]
["Ped, ALL",{"$f":"IF(AND(Input!B92=\"Multiplicative\",Input!C92<>\"\",Input!E92<>\"\"),IF(AND(Input!C92<1,Input!E92<1),\"ERROR Check Input\",Input!C92*Input!E92),\"\")","v":""},{"$f":"IF(AND(Input!B92=\"Additive\",Input!C92<>\"\",Input!E92<>\"\"),1-((1-Input!C92)+(1-Input!E92)),\"\")","v":""},{"$f":"IF(AND(Input!B92=\"Additive\",Input!C92<>\"\",Input!E92<>\"\"),1-((1-Input!C92)+(1-Input!E92)),\"\")","v":""},{"$f":"IF(AND(Input!B92=\"Dominant Effect\",Input!C92<>\"\",Input!E92<>\"\"),MIN(Input!C92,Input!E92),\"\")","v":""},{"$f":"IF(AND(Input!B92=\"Dominant Common Residuals\",Input!C92<>\"\",Input!E92<>\"\"),MIN(Input!C92,Input!E92),\"\")","v":""},{"$f":"IF(F161<>\"\",MIN(Input!C92,Input!E92,(Input!C92*Input!E92)^F161),\"\")","v":""}]
["Ped, FI",{"$f":"IF(AND(Input!B93=\"Multiplicative\",Input!C93<>\"\",Input!E93<>\"\"),IF(AND(Input!C93<1,Input!E93<1),\"ERROR Check Input\",Input!C93*Input!E93),\"\")","v":""},{"$f":"IF(AND(Input!B93=\"Additive\",Input!C93<>\"\",Input!E93<>\"\"),1-((1-Input!C93)+(1-Input!E93)),\"\")","v":""},{"$f":"IF(AND(Input!B93=\"Additive\",Input!C93<>\"\",Input!E93<>\"\"),1-((1-Input!C93)+(1-Input!E93)),\"\")","v":""},{"$f":"IF(AND(Input!B93=\"Dominant Effect\",Input!C93<>\"\",Input!E93<>\"\"),MIN(Input!C93,Input!E93),\"\")","v":""},{"$f":"IF(AND(Input!B93=\"Dominant Common Residuals\",Input!C93<>\"\",Input!E93<>\"\"),MIN(Input!C93,Input!E93),\"\")","v":""},{"$f":"IF(F162<>\"\",MIN(Input!C93,Input!E93,(Input!C93*Input!E93)^F162),\"\")","v":""}]
["Bike, ALL",{"$f":"IF(AND(Input!B94=\"Multiplicative\",Input!C94<>\"\",Input!E94<>\"\"),IF(AND(Input!C94<1,Input!E94<1),\"ERROR Check Input\",Input!C94*Input!E94),\"\")","v":""},{"$f":"IF(AND(Input!B94=\"Additive\",Input!C94<>\"\",Input!E94<>\"\"),1-((1-Input!C94)+(1-Input!E94)),\"\")","v":""},{"$f":"IF(AND(Input!B94=\"Additive\",Input!C94<>\"\",Input!E94<>\"\"),1-((1-Input!C94)+(1-Input!E94)),\"\")","v":""},{"$f":"IF(AND(Input!B94=\"Dominant Effect\",Input!C94<>\"\",Input!E94<>\"\"),MIN(Input!C94,Input!E94),\"\")","v":""},{"$f":"IF(AND(Input!B94=\"Dominant Common Residuals\",Input!C94<>\"\",Input!E94<>\"\"),MIN(Input!C94,Input!E94),\"\")","v":""},{"$f":"IF(F163<>\"\",MIN(Input!C94,Input!E94,(Input!C94*Input!E94)^F163),\"\")","v":""}]
["Bike, FI",{"$f":"IF(AND(Input!B95=\"Multiplicative\",Input!C95<>\"\",Input!E95<>\"\"),IF(AND(Input!C95<1,Input!E95<1),\"ERROR Check Input\",Input!C95*Input!E95),\"\")","v":""},{"$f":"IF(AND(Input!B95=\"Additive\",Input!C95<>\"\",Input!E95<>\"\"),1-((1-Input!C95)+(1-Input!E95)),\"\")","v":""},{"$f":"IF(AND(Input!B95=\"Additive\",Input!C95<>\"\",Input!E95<>\"\"),1-((1-Input!C95)+(1-Input!E95)),\"\")","v":""},{"$f":"IF(AND(Input!B95=\"Dominant Effect\",Input!C95<>\"\",Input!E95<>\"\"),MIN(Input!C95,Input!E95),\"\")","v":""},{"$f":"IF(AND(Input!B95=\"Dominant Common Residuals\",Input!C95<>\"\",Input!E95<>\"\"),MIN(Input!C95,Input!E95),\"\")","v":""},{"$f":"IF(F164<>\"\",MIN(Input!C95,Input!E95,(Input!C95*Input!E95)^F164),\"\")","v":""}]
[]
[]
["Alternative 3"]
["Crash Type, Severity","Multiplicative","Additive Calc","Additive < 0 Round","Dominant Effect","Dominant Common Residuals Step 1","Dominant Common Residuals Result"]
["MV, ALL",{"$f":"IF(AND(Input!B100=\"Multiplicative\",Input!C100<>\"\",Input!E100<>\"\"),IF(AND(Input!C100<1,Input!E100<1),\"ERROR Check Input\",Input!C100*Input!E100),\"\")","v":""},{"$f":"IF(AND(Input!B100=\"Additive\",Input!C100<>\"\",Input!E100<>\"\"),1-((1-Input!C100)+(1-Input!E100)),\"\")","v":""},{"$f":"IF(C169=\"\",\"\",IF(C169<=0,0,C169))","v":""},{"$f":"IF(AND(Input!B100=\"Dominant Effect\",Input!C100<>\"\",Input!E100<>\"\"),MIN(Input!C100,Input!E100),\"\")","v":""},{"$f":"IF(AND(Input!B100=\"Dominant Common Residuals\",Input!C100<>\"\",Input!E100<>\"\"),MIN(Input!C100,Input!E100),\"\")","v":""},{"$f":"IF(F169<>\"\",MIN(Input!C100,Input!E100,(Input!C100*Input!E100)^F169),\"\")","v":""}]
["MV, FI",{"$f":"IF(AND(Input!B101=\"Multiplicative\",Input!C101<>\"\",Input!E101<>\"\"),IF(AND(Input!C101<1,Input!E101<1),\"ERROR Check Input\",Input!C101*Input!E101),\"\")","v":""},{"$f":"IF(AND(Input!B101=\"Additive\",Input!C101<>\"\",Input!E101<>\"\"),1-((1-Input!C101)+(1-Input!E101)),\"\")","v":""},{"$f":"IF(AND(Input!B101=\"Additive\",Input!C101<>\"\",Input!E101<>\"\"),1-((1-Input!C101)+(1-Input!E101)),\"\")","v":""},{"$f":"IF(AND(Input!B101=\"Dominant Effect\",Input!C101<>\"\",Input!E101<>\"\"),MIN(Input!C101,Input!E101),\"\")","v":""},{"$f":"IF(AND(Input!B101=\"Dominant Common Residuals\",Input!C101<>\"\",Input!E101<>\"\"),MIN(Input!C101,Input!E101),\"\")","v":""},{"$f":"IF(F170<>\"\",MIN(Input!C101,Input!E101,(Input!C101*Input!E101)^F170),\"\")","v":""}]
["SV, ALL",{"$f":"IF(AND(Input!B102=\"Multiplicative\",Input!C102<>\"\",Input!E102<>\"\"),IF(AND(Input!C102<1,Input!E102<1),\"ERROR Check Input\",Input!C102*Input!E102),\"\")","v":""},{"$f":"IF(AND(Input!B102=\"Additive\",Input!C102<>\"\",Input!E102<>\"\"),1-((1-Input!C102)+(1-Input!E102)),\"\")","v":""},{"$f":"IF(AND(Input!B102=\"Additive\",Input!C102<>\"\",Input!E102<>\"\"),1-((1-Input!C102)+(1-Input!E102)),\"\")","v":""},{"$f":"IF(AND(Input!B102=\"Dominant Effect\",Input!C102<>\"\",Input!E102<>\"\"),MIN(Input!C102,Input!E102),\"\")","v":""},{"$f":"IF(AND(Input!B102=\"Dominant Common Residuals\",Input!C102<>\"\",Input!E102<>\"\"),MIN(Input!C102,Input!E102),\"\")","v":""},{"$f":"IF(F171<>\"\",MIN(Input!C102,Input!E102,(Input!C102*Input!E102)^F171),\"\")","v":""}]
["SV, FI",{"$f":"IF(AND(Input!B103=\"Multiplicative\",Input!C103<>\"\",Input!E103<>\"\"),IF(AND(Input!C103<1,Input!E103<1),\"ERROR Check Input\",Input!C103*Input!E103),\"\")","v":""},{"$f":"IF(AND(Input!B103=\"Additive\",Input!C103<>\"\",Input!E103<>\"\"),1-((1-Input!C103)+(1-Input!E103)),\"\")","v":""},{"$f":"IF(AND(Input!B103=\"Additive\",Input!C103<>\"\",Input!E103<>\"\"),1-((1-Input!C103)+(1-Input!E103)),\"\")","v":""},{"$f":"IF(AND(Input!B103=\"Dominant Effect\",Input!C103<>\"\",Input!E103<>\"\"),MIN(Input!C103,Input!E103),\"\")","v":""},{"$f":"IF(AND(Input!B103=\"Dominant Common Residuals\",Input!C103<>\"\",Input!E103<>\"\"),MIN(Input!C103,Input!E103),\"\")","v":""},{"$f":"IF(F172<>\"\",MIN(Input!C103,Input!E103,(Input!C103*Input!E103)^F172),\"\")","v":""}]
["Ped, ALL",{"$f":"IF(AND(Input!B104=\"Multiplicative\",Input!C104<>\"\",Input!E104<>\"\"),IF(AND(Input!C104<1,Input!E104<1),\"ERROR Check Input\",Input!C104*Input!E104),\"\")","v":""},{"$f":"IF(AND(Input!B104=\"Additive\",Input!C104<>\"\",Input!E104<>\"\"),1-((1-Input!C104)+(1-Input!E104)),\"\")","v":""},{"$f":"IF(AND(Input!B104=\"Additive\",Input!C104<>\"\",Input!E104<>\"\"),1-((1-Input!C104)+(1-Input!E104)),\"\")","v":""},{"$f":"IF(AND(Input!B104=\"Dominant Effect\",Input!C104<>\"\",Input!E104<>\"\"),MIN(Input!C104,Input!E104),\"\")","v":""},{"$f":"IF(AND(Input!B104=\"Dominant Common Residuals\",Input!C104<>\"\",Input!E104<>\"\"),MIN(Input!C104,Input!E104),\"\")","v":""},{"$f":"IF(F173<>\"\",MIN(Input!C104,Input!E104,(Input!C104*Input!E104)^F173),\"\")","v":""}]
["Ped, FI",{"$f":"IF(AND(Input!B105=\"Multiplicative\",Input!C105<>\"\",Input!E105<>\"\"),IF(AND(Input!C105<1,Input!E105<1),\"ERROR Check Input\",Input!C105*Input!E105),\"\")","v":""},{"$f":"IF(AND(Input!B105=\"Additive\",Input!C105<>\"\",Input!E105<>\"\"),1-((1-Input!C105)+(1-Input!E105)),\"\")","v":""},{"$f":"IF(AND(Input!B105=\"Additive\",Input!C105<>\"\",Input!E105<>\"\"),1-((1-Input!C105)+(1-Input!E105)),\"\")","v":""},{"$f":"IF(AND(Input!B105=\"Dominant Effect\",Input!C105<>\"\",Input!E105<>\"\"),MIN(Input!C105,Input!E105),\"\")","v":""},{"$f":"IF(AND(Input!B105=\"Dominant Common Residuals\",Input!C105<>\"\",Input!E105<>\"\"),MIN(Input!C105,Input!E105),\"\")","v":""},{"$f":"IF(F174<>\"\",MIN(Input!C105,Input!E105,(Input!C105*Input!E105)^F174),\"\")","v":""}]
["Bike, ALL",{"$f":"IF(AND(Input!B106=\"Multiplicative\",Input!C106<>\"\",Input!E106<>\"\"),IF(AND(Input!C106<1,Input!E106<1),\"ERROR Check Input\",Input!C106*Input!E106),\"\")","v":""},{"$f":"IF(AND(Input!B106=\"Additive\",Input!C106<>\"\",Input!E106<>\"\"),1-((1-Input!C106)+(1-Input!E106)),\"\")","v":""},{"$f":"IF(AND(Input!B106=\"Additive\",Input!C106<>\"\",Input!E106<>\"\"),1-((1-Input!C106)+(1-Input!E106)),\"\")","v":""},{"$f":"IF(AND(Input!B106=\"Dominant Effect\",Input!C106<>\"\",Input!E106<>\"\"),MIN(Input!C106,Input!E106),\"\")","v":""},{"$f":"IF(AND(Input!B106=\"Dominant Common Residuals\",Input!C106<>\"\",Input!E106<>\"\"),MIN(Input!C106,Input!E106),\"\")","v":""},{"$f":"IF(F175<>\"\",MIN(Input!C106,Input!E106,(Input!C106*Input!E106)^F175),\"\")","v":""}]
["Bike, FI",{"$f":"IF(AND(Input!B107=\"Multiplicative\",Input!C107<>\"\",Input!E107<>\"\"),IF(AND(Input!C107<1,Input!E107<1),\"ERROR Check Input\",Input!C107*Input!E107),\"\")","v":""},{"$f":"IF(AND(Input!B107=\"Additive\",Input!C107<>\"\",Input!E107<>\"\"),1-((1-Input!C107)+(1-Input!E107)),\"\")","v":""},{"$f":"IF(AND(Input!B107=\"Additive\",Input!C107<>\"\",Input!E107<>\"\"),1-((1-Input!C107)+(1-Input!E107)),\"\")","v":""},{"$f":"IF(AND(Input!B107=\"Dominant Effect\",Input!C107<>\"\",Input!E107<>\"\"),MIN(Input!C107,Input!E107),\"\")","v":""},{"$f":"IF(AND(Input!B107=\"Dominant Common Residuals\",Input!C107<>\"\",Input!E107<>\"\"),MIN(Input!C107,Input!E107),\"\")","v":""},{"$f":"IF(F176<>\"\",MIN(Input!C107,Input!E107,(Input!C107*Input!E107)^F176),\"\")","v":""}]
[]
[]
["Alternative 4"]
["Crash Type, Severity","Multiplicative","Additive Calc","Additive < 0 Round","Dominant Effect","Dominant Common Residuals Step 1","Dominant Common Residuals Result"]
["MV, ALL",{"$f":"IF(AND(Input!B112=\"Multiplicative\",Input!C112<>\"\",Input!E112<>\"\"),IF(AND(Input!C112<1,Input!E112<1),\"ERROR Check Input\",Input!C112*Input!E112),\"\")","v":""},{"$f":"IF(AND(Input!B112=\"Additive\",Input!C112<>\"\",Input!E112<>\"\"),1-((1-Input!C112)+(1-Input!E112)),\"\")","v":""},{"$f":"IF(C181=\"\",\"\",IF(C181<=0,0,C181))","v":""},{"$f":"IF(AND(Input!B112=\"Dominant Effect\",Input!C112<>\"\",Input!E112<>\"\"),MIN(Input!C112,Input!E112),\"\")","v":""},{"$f":"IF(AND(Input!B112=\"Dominant Common Residuals\",Input!C112<>\"\",Input!E112<>\"\"),MIN(Input!C112,Input!E112),\"\")","v":""},{"$f":"IF(F181<>\"\",MIN(Input!C112,Input!E112,(Input!C112*Input!E112)^F181),\"\")","v":""}]
["MV, FI",{"$f":"IF(AND(Input!B113=\"Multiplicative\",Input!C113<>\"\",Input!E113<>\"\"),IF(AND(Input!C113<1,Input!E113<1),\"ERROR Check Input\",Input!C113*Input!E113),\"\")","v":""},{"$f":"IF(AND(Input!B113=\"Additive\",Input!C113<>\"\",Input!E113<>\"\"),1-((1-Input!C113)+(1-Input!E113)),\"\")","v":""},{"$f":"IF(AND(Input!B113=\"Additive\",Input!C113<>\"\",Input!E113<>\"\"),1-((1-Input!C113)+(1-Input!E113)),\"\")","v":""},{"$f":"IF(AND(Input!B113=\"Dominant Effect\",Input!C113<>\"\",Input!E113<>\"\"),MIN(Input!C113,Input!E113),\"\")","v":""},{"$f":"IF(AND(Input!B113=\"Dominant Common Residuals\",Input!C113<>\"\",Input!E113<>\"\"),MIN(Input!C113,Input!E113),\"\")","v":""},{"$f":"IF(F182<>\"\",MIN(Input!C113,Input!E113,(Input!C113*Input!E113)^F182),\"\")","v":""}]
["SV, ALL",{"$f":"IF(AND(Input!B114=\"Multiplicative\",Input!C114<>\"\",Input!E114<>\"\"),IF(AND(Input!C114<1,Input!E114<1),\"ERROR Check Input\",Input!C114*Input!E114),\"\")","v":""},{"$f":"IF(AND(Input!B114=\"Additive\",Input!C114<>\"\",Input!E114<>\"\"),1-((1-Input!C114)+(1-Input!E114)),\"\")","v":""},{"$f":"IF(AND(Input!B114=\"Additive\",Input!C114<>\"\",Input!E114<>\"\"),1-((1-Input!C114)+(1-Input!E114)),\"\")","v":""},{"$f":"IF(AND(Input!B114=\"Dominant Effect\",Input!C114<>\"\",Input!E114<>\"\"),MIN(Input!C114,Input!E114),\"\")","v":""},{"$f":"IF(AND(Input!B114=\"Dominant Common Residuals\",Input!C114<>\"\",Input!E114<>\"\"),MIN(Input!C114,Input!E114),\"\")","v":""},{"$f":"IF(F183<>\"\",MIN(Input!C114,Input!E114,(Input!C114*Input!E114)^F183),\"\")","v":""}]
["SV, FI",{"$f":"IF(AND(Input!B115=\"Multiplicative\",Input!C115<>\"\",Input!E115<>\"\"),IF(AND(Input!C115<1,Input!E115<1),\"ERROR Check Input\",Input!C115*Input!E115),\"\")","v":""},{"$f":"IF(AND(Input!B115=\"Additive\",Input!C115<>\"\",Input!E115<>\"\"),1-((1-Input!C115)+(1-Input!E115)),\"\")","v":""},{"$f":"IF(AND(Input!B115=\"Additive\",Input!C115<>\"\",Input!E115<>\"\"),1-((1-Input!C115)+(1-Input!E115)),\"\")","v":""},{"$f":"IF(AND(Input!B115=\"Dominant Effect\",Input!C115<>\"\",Input!E115<>\"\"),MIN(Input!C115,Input!E115),\"\")","v":""},{"$f":"IF(AND(Input!B115=\"Dominant Common Residuals\",Input!C115<>\"\",Input!E115<>\"\"),MIN(Input!C115,Input!E115),\"\")","v":""},{"$f":"IF(F184<>\"\",MIN(Input!C115,Input!E115,(Input!C115*Input!E115)^F184),\"\")","v":""}]
["Ped, ALL",{"$f":"IF(AND(Input!B116=\"Multiplicative\",Input!C116<>\"\",Input!E116<>\"\"),IF(AND(Input!C116<1,Input!E116<1),\"ERROR Check Input\",Input!C116*Input!E116),\"\")","v":""},{"$f":"IF(AND(Input!B116=\"Additive\",Input!C116<>\"\",Input!E116<>\"\"),1-((1-Input!C116)+(1-Input!E116)),\"\")","v":""},{"$f":"IF(AND(Input!B116=\"Additive\",Input!C116<>\"\",Input!E116<>\"\"),1-((1-Input!C116)+(1-Input!E116)),\"\")","v":""},{"$f":"IF(AND(Input!B116=\"Dominant Effect\",Input!C116<>\"\",Input!E116<>\"\"),MIN(Input!C116,Input!E116),\"\")","v":""},{"$f":"IF(AND(Input!B116=\"Dominant Common Residuals\",Input!C116<>\"\",Input!E116<>\"\"),MIN(Input!C116,Input!E116),\"\")","v":""},{"$f":"IF(F185<>\"\",MIN(Input!C116,Input!E116,(Input!C116*Input!E116)^F185),\"\")","v":""}]
["Ped, FI",{"$f":"IF(AND(Input!B117=\"Multiplicative\",Input!C117<>\"\",Input!E117<>\"\"),IF(AND(Input!C117<1,Input!E117<1),\"ERROR Check Input\",Input!C117*Input!E117),\"\")","v":""},{"$f":"IF(AND(Input!B117=\"Additive\",Input!C117<>\"\",Input!E117<>\"\"),1-((1-Input!C117)+(1-Input!E117)),\"\")","v":""},{"$f":"IF(AND(Input!B117=\"Additive\",Input!C117<>\"\",Input!E117<>\"\"),1-((1-Input!C117)+(1-Input!E117)),\"\")","v":""},{"$f":"IF(AND(Input!B117=\"Dominant Effect\",Input!C117<>\"\",Input!E117<>\"\"),MIN(Input!C117,Input!E117),\"\")","v":""},{"$f":"IF(AND(Input!B117=\"Dominant Common Residuals\",Input!C117<>\"\",Input!E117<>\"\"),MIN(Input!C117,Input!E117),\"\")","v":""},{"$f":"IF(F186<>\"\",MIN(Input!C117,Input!E117,(Input!C117*Input!E117)^F186),\"\")","v":""}]
["Bike, ALL",{"$f":"IF(AND(Input!B118=\"Multiplicative\",Input!C118<>\"\",Input!E118<>\"\"),IF(AND(Input!C118<1,Input!E118<1),\"ERROR Check Input\",Input!C118*Input!E118),\"\")","v":""},{"$f":"IF(AND(Input!B118=\"Additive\",Input!C118<>\"\",Input!E118<>\"\"),1-((1-Input!C118)+(1-Input!E118)),\"\")","v":""},{"$f":"IF(AND(Input!B118=\"Additive\",Input!C118<>\"\",Input!E118<>\"\"),1-((1-Input!C118)+(1-Input!E118)),\"\")","v":""},{"$f":"IF(AND(Input!B118=\"Dominant Effect\",Input!C118<>\"\",Input!E118<>\"\"),MIN(Input!C118,Input!E118),\"\")","v":""},{"$f":"IF(AND(Input!B118=\"Dominant Common Residuals\",Input!C118<>\"\",Input!E118<>\"\"),MIN(Input!C118,Input!E118),\"\")","v":""},{"$f":"IF(F187<>\"\",MIN(Input!C118,Input!E118,(Input!C118*Input!E118)^F187),\"\")","v":""}]
["Bike, FI",{"$f":"IF(AND(Input!B119=\"Multiplicative\",Input!C119<>\"\",Input!E119<>\"\"),IF(AND(Input!C119<1,Input!E119<1),\"ERROR Check Input\",Input!C119*Input!E119),\"\")","v":""},{"$f":"IF(AND(Input!B119=\"Additive\",Input!C119<>\"\",Input!E119<>\"\"),1-((1-Input!C119)+(1-Input!E119)),\"\")","v":""},{"$f":"IF(AND(Input!B119=\"Additive\",Input!C119<>\"\",Input!E119<>\"\"),1-((1-Input!C119)+(1-Input!E119)),\"\")","v":""},{"$f":"IF(AND(Input!B119=\"Dominant Effect\",Input!C119<>\"\",Input!E119<>\"\"),MIN(Input!C119,Input!E119),\"\")","v":""},{"$f":"IF(AND(Input!B119=\"Dominant Common Residuals\",Input!C119<>\"\",Input!E119<>\"\"),MIN(Input!C119,Input!E119),\"\")","v":""},{"$f":"IF(F188<>\"\",MIN(Input!C119,Input!E119,(Input!C119*Input!E119)^F188),\"\")","v":""}]